{"id":11722,"date":"2023-03-12T21:18:46","date_gmt":"2023-03-12T17:48:46","guid":{"rendered":"https:\/\/nabfollower.com\/blog\/how-to-add-social-media-icons-in-html\/"},"modified":"2023-03-12T21:18:46","modified_gmt":"2023-03-12T17:48:46","slug":"how-to-add-social-media-icons-in-html","status":"publish","type":"post","link":"https:\/\/nabfollower.com\/blog\/how-to-add-social-media-icons-in-html\/","title":{"rendered":"\u0686\u06af\u0648\u0646\u0647 \u0622\u06cc\u06a9\u0648\u0646 \u0647\u0627\u06cc \u0631\u0633\u0627\u0646\u0647 \u0647\u0627\u06cc \u0627\u062c\u062a\u0645\u0627\u0639\u06cc \u0631\u0627 \u062f\u0631 HTML \u0627\u0636\u0627\u0641\u0647 \u06a9\u0646\u06cc\u0645"},"content":{"rendered":"<div id=\"hs_cos_wrapper_post_body\">\n<p>\u0627\u0636\u0627\u0641\u0647 \u0643\u0631\u062f\u0646 <span style=\"background-color: #ffffff;\">\u0622\u06cc\u06a9\u0648\u0646 \u0647\u0627\u06cc \u0631\u0633\u0627\u0646\u0647 \u0647\u0627\u06cc \u0627\u062c\u062a\u0645\u0627\u0639\u06cc \u0631\u0627\u06cc\u06af\u0627\u0646<\/span> \u0628\u0647 \u0635\u0641\u062d\u0627\u062a \u0648\u0628 \u0633\u0627\u06cc\u062a \u0634\u0645\u0627 \u0645\u06cc \u062a\u0648\u0627\u0646\u062f \u0631\u0627\u0647\u06cc \u0639\u0627\u0644\u06cc \u0628\u0631\u0627\u06cc \u0647\u062f\u0627\u06cc\u062a \u0628\u0627\u0632\u062f\u06cc\u062f\u06a9\u0646\u0646\u062f\u06af\u0627\u0646 \u0628\u0647 \u0641\u06cc\u062f\u0647\u0627\u06cc \u0634\u0645\u0627\u060c \u0631\u0634\u062f \u0645\u062e\u0627\u0637\u0628\u0627\u0646 \u0648 \u0627\u0631\u0627\u0626\u0647 \u0627\u062b\u0628\u0627\u062a \u0627\u062c\u062a\u0645\u0627\u0639\u06cc \u0628\u0627\u0634\u062f \u2013 \u0627\u0645\u0627 \u0636\u0631\u0648\u0631\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0646\u0645\u0627\u062f\u0647\u0627\u06cc \u0634\u0645\u0627 \u0628\u0647 \u062f\u0631\u0633\u062a\u06cc \u0642\u0627\u0644\u0628 \u0628\u0646\u062f\u06cc \u0634\u062f\u0647 \u0648 \u0628\u0647 \u0635\u0641\u062d\u0627\u062a \u0645\u0646\u0627\u0633\u0628 \u067e\u06cc\u0648\u0646\u062f \u062f\u0627\u062f\u0647 \u0634\u0648\u0646\u062f.<\/p>\n<p><!--more--><\/p>\n<p>\u0646\u06a9\u062a\u0647 \u06a9\u0644\u06cc\u062f\u06cc \u0627\u06cc\u0646 \u0627\u0633\u062a \u06a9\u0647 \u06cc\u06a9 \u0633\u0641\u0631 \u0633\u0627\u062f\u0647 \u0628\u0631\u0627\u06cc \u0645\u0634\u062a\u0631\u06cc \u0627\u0631\u0627\u0626\u0647 \u062f\u0647\u06cc\u062f\u060c \u0628\u0646\u0627\u0628\u0631\u0627\u06cc\u0646 \u0645\u0637\u0645\u0626\u0646 \u0646\u06cc\u0633\u062a\u06cc\u062f <span style=\"background-color: #b6d7a8;\">\u0686\u06af\u0648\u0646\u0647 \u0622\u06cc\u06a9\u0648\u0646 \u0647\u0627\u06cc \u0631\u0633\u0627\u0646\u0647 \u0647\u0627\u06cc \u0627\u062c\u062a\u0645\u0627\u0639\u06cc \u0631\u0627 \u0628\u0647 Adobe Portfolio \u0627\u0636\u0627\u0641\u0647 \u06a9\u0646\u06cc\u0645<\/span> \u06cc\u0627 \u067e\u06cc\u0648\u0646\u062f\u0647\u0627\u06cc \u0627\u062c\u062a\u0645\u0627\u0639\u06cc \u0631\u0627 \u062f\u0631 \u0635\u0641\u062d\u0627\u062a \u0641\u0631\u0648\u062f \u062e\u0648\u062f \u062c\u0627\u0633\u0627\u0632\u06cc \u06a9\u0646\u06cc\u062f\u060c \u06cc\u06a9 \u0627\u0641\u0632\u0648\u0646\u0647 \u0628\u0647\u062a\u0631\u06cc\u0646 \u06af\u0632\u06cc\u0646\u0647 \u0628\u0631\u0627\u06cc \u0634\u0645\u0627\u0633\u062a.  \u0627\u0641\u0632\u0648\u0646\u0647 \u0647\u0627\u06cc \u0631\u0633\u0627\u0646\u0647 \u0647\u0627\u06cc \u0627\u062c\u062a\u0645\u0627\u0639\u06cc \u0628\u0647 \u0634\u0645\u0627 \u0627\u06cc\u0646 \u0627\u0645\u06a9\u0627\u0646 \u0631\u0627 \u0645\u06cc \u062f\u0647\u0646\u062f \u06a9\u0647 \u0622\u06cc\u06a9\u0648\u0646 \u0647\u0627\u06cc \u062d\u0631\u0641\u0647 \u0627\u06cc \u0648 \u0642\u0627\u0628\u0644 \u062a\u0634\u062e\u06cc\u0635 \u0631\u0627 \u0628\u062f\u0648\u0646 \u0646\u06cc\u0627\u0632 \u0628\u0647 \u0628\u0631\u0646\u0627\u0645\u0647 \u0646\u0648\u06cc\u0633\u06cc \u06cc\u0627 \u0646\u06af\u0631\u0627\u0646\u06cc \u062f\u0631 \u0645\u0648\u0631\u062f \u0633\u0627\u0632\u06af\u0627\u0631\u06cc \u0646\u0645\u0627\u06cc\u0634 \u062f\u0647\u06cc\u062f.<\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter-rtl ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u0641\u0647\u0631\u0633\u062a \u0645\u0637\u0627\u0644\u0628<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"\u062a\u063a\u06cc\u06cc\u0631 \u0648\u0636\u0639\u06cc\u062a \u0641\u0647\u0631\u0633\u062a \u0645\u0637\u0627\u0644\u0628\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/nabfollower.com\/blog\/how-to-add-social-media-icons-in-html\/#%D8%A7%D9%81%D8%B2%D9%88%D8%AF%D9%86_%D9%84%DB%8C%D9%86%DA%A9_%D9%87%D8%A7%DB%8C_%D8%B1%D8%B3%D8%A7%D9%86%D9%87_%D9%87%D8%A7%DB%8C_%D8%A7%D8%AC%D8%AA%D9%85%D8%A7%D8%B9%DB%8C_%D8%A8%D9%87_%DA%A9%D8%AF%D9%86%D9%88%DB%8C%D8%B3%DB%8C_HTML\" >\u0627\u0641\u0632\u0648\u062f\u0646 \u0644\u06cc\u0646\u06a9 \u0647\u0627\u06cc \u0631\u0633\u0627\u0646\u0647 \u0647\u0627\u06cc \u0627\u062c\u062a\u0645\u0627\u0639\u06cc \u0628\u0647 \u06a9\u062f\u0646\u0648\u06cc\u0633\u06cc HTML<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/nabfollower.com\/blog\/how-to-add-social-media-icons-in-html\/#%D8%A7%DB%8C%D8%AC%D8%A7%D8%AF_%D8%A2%DB%8C%DA%A9%D9%88%D9%86_%D9%87%D8%A7%DB%8C_%D8%B1%D8%B3%D8%A7%D9%86%D9%87_%D9%87%D8%A7%DB%8C_%D8%A7%D8%AC%D8%AA%D9%85%D8%A7%D8%B9%DB%8C_HTML\" >\u0627\u06cc\u062c\u0627\u062f \u0622\u06cc\u06a9\u0648\u0646 \u0647\u0627\u06cc \u0631\u0633\u0627\u0646\u0647 \u0647\u0627\u06cc \u0627\u062c\u062a\u0645\u0627\u0639\u06cc HTML<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/nabfollower.com\/blog\/how-to-add-social-media-icons-in-html\/#HTML_%D8%AF%D8%B1_%D9%85%D9%82%D8%A7%D8%A8%D9%84_%D9%BE%D9%84%D8%A7%DA%AF%DB%8C%D9%86_%D9%87%D8%A7\" >HTML \u062f\u0631 \u0645\u0642\u0627\u0628\u0644 \u067e\u0644\u0627\u06af\u06cc\u0646 \u0647\u0627<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/nabfollower.com\/blog\/how-to-add-social-media-icons-in-html\/#%D9%85%D8%B2%D8%A7%DB%8C%D8%A7%DB%8C_%D8%A7%D9%81%D8%B2%D9%88%D8%AF%D9%86_%D8%A2%DB%8C%DA%A9%D9%88%D9%86_%D9%87%D8%A7%DB%8C_%D8%B1%D8%B3%D8%A7%D9%86%D9%87_%D9%87%D8%A7%DB%8C_%D8%A7%D8%AC%D8%AA%D9%85%D8%A7%D8%B9%DB%8C_%D8%A8%D9%87_%D8%B5%D9%81%D8%AD%D8%A7%D8%AA_%D9%81%D8%B1%D9%88%D8%AF\" >\u0645\u0632\u0627\u06cc\u0627\u06cc \u0627\u0641\u0632\u0648\u062f\u0646 \u0622\u06cc\u06a9\u0648\u0646 \u0647\u0627\u06cc \u0631\u0633\u0627\u0646\u0647 \u0647\u0627\u06cc \u0627\u062c\u062a\u0645\u0627\u0639\u06cc \u0628\u0647 \u0635\u0641\u062d\u0627\u062a \u0641\u0631\u0648\u062f<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/nabfollower.com\/blog\/how-to-add-social-media-icons-in-html\/#%D9%85%D8%AD%D8%AA%D9%88%D8%A7%DB%8C_%D8%A7%DB%8C%D8%AC%D8%A7%D8%AF_%D8%B4%D8%AF%D9%87_%D8%AA%D9%88%D8%B3%D8%B7_%DA%A9%D8%A7%D8%B1%D8%A8%D8%B1\" >\u0645\u062d\u062a\u0648\u0627\u06cc \u0627\u06cc\u062c\u0627\u062f \u0634\u062f\u0647 \u062a\u0648\u0633\u0637 \u06a9\u0627\u0631\u0628\u0631<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/nabfollower.com\/blog\/how-to-add-social-media-icons-in-html\/#%D8%A7%D8%AB%D8%A8%D8%A7%D8%AA_%D8%A7%D8%AC%D8%AA%D9%85%D8%A7%D8%B9%DB%8C\" >\u0627\u062b\u0628\u0627\u062a \u0627\u062c\u062a\u0645\u0627\u0639\u06cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/nabfollower.com\/blog\/how-to-add-social-media-icons-in-html\/#%D8%AA%D8%B9%D8%A7%D9%85%D9%84_%D8%A8%D9%87%D8%A8%D9%88%D8%AF_%DB%8C%D8%A7%D9%81%D8%AA%D9%87\" >\u062a\u0639\u0627\u0645\u0644 \u0628\u0647\u0628\u0648\u062f \u06cc\u0627\u0641\u062a\u0647<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h2 style=\"font-size: 24px;\"><span class=\"ez-toc-section\" id=\"%D8%A7%D9%81%D8%B2%D9%88%D8%AF%D9%86_%D9%84%DB%8C%D9%86%DA%A9_%D9%87%D8%A7%DB%8C_%D8%B1%D8%B3%D8%A7%D9%86%D9%87_%D9%87%D8%A7%DB%8C_%D8%A7%D8%AC%D8%AA%D9%85%D8%A7%D8%B9%DB%8C_%D8%A8%D9%87_%DA%A9%D8%AF%D9%86%D9%88%DB%8C%D8%B3%DB%8C_HTML\"><\/span><span style=\"color: #000000;\">\u0627\u0641\u0632\u0648\u062f\u0646 \u0644\u06cc\u0646\u06a9 \u0647\u0627\u06cc \u0631\u0633\u0627\u0646\u0647 \u0647\u0627\u06cc \u0627\u062c\u062a\u0645\u0627\u0639\u06cc \u0628\u0647 \u06a9\u062f\u0646\u0648\u06cc\u0633\u06cc HTML<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0631\u0627\u0647\u200c\u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641\u06cc \u0628\u0631\u0627\u06cc \u067e\u06cc\u0648\u0646\u062f \u062f\u0627\u062f\u0646 \u0641\u06cc\u062f \u0631\u0633\u0627\u0646\u0647\u200c\u0647\u0627\u06cc \u0627\u062c\u062a\u0645\u0627\u0639\u06cc \u0628\u0627 \u0648\u0628\u200c\u0633\u0627\u06cc\u062a\u200c\u062a\u0627\u0646 \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u062f\u060c \u0648 \u0631\u0627\u0647\u200c\u062d\u0644\u200c\u0647\u0627\u06cc \u0645\u0646\u0627\u0633\u0628 \u0628\u0647 \u0645\u0647\u0627\u0631\u062a\u200c\u0647\u0627\u06cc \u06a9\u062f\u0646\u0648\u06cc\u0633\u06cc \u0634\u0645\u0627 \u0648 \u0622\u0646\u0686\u0647 \u0645\u06cc\u200c\u062e\u0648\u0627\u0647\u06cc\u062f \u0628\u0647 \u0622\u0646 \u0628\u0631\u0633\u06cc\u062f \u0628\u0633\u062a\u06af\u06cc \u062f\u0627\u0631\u062f.<\/p>\n<h3 style=\"font-size: 20px;\"><span class=\"ez-toc-section\" id=\"%D8%A7%DB%8C%D8%AC%D8%A7%D8%AF_%D8%A2%DB%8C%DA%A9%D9%88%D9%86_%D9%87%D8%A7%DB%8C_%D8%B1%D8%B3%D8%A7%D9%86%D9%87_%D9%87%D8%A7%DB%8C_%D8%A7%D8%AC%D8%AA%D9%85%D8%A7%D8%B9%DB%8C_HTML\"><\/span><span style=\"color: #000000;\">\u0627\u06cc\u062c\u0627\u062f \u0622\u06cc\u06a9\u0648\u0646 \u0647\u0627\u06cc \u0631\u0633\u0627\u0646\u0647 \u0647\u0627\u06cc \u0627\u062c\u062a\u0645\u0627\u0639\u06cc HTML<\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0627\u0648\u0644\u06cc\u0646 \u06af\u0632\u06cc\u0646\u0647 \u062f\u0627\u0646\u0644\u0648\u062f \u0646\u0645\u0627\u062f \u0645\u0631\u0628\u0648\u0637 \u0628\u0647 \u0641\u06cc\u062f \u0631\u0633\u0627\u0646\u0647 \u0647\u0627\u06cc \u0627\u062c\u062a\u0645\u0627\u0639\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0645\u06cc \u062e\u0648\u0627\u0647\u06cc\u062f \u0628\u0647 \u0622\u0646 \u067e\u06cc\u0648\u0646\u062f \u062f\u0647\u06cc\u062f\u060c \u0645\u0627\u0646\u0646\u062f \u0644\u06cc\u0646\u06a9\u062f\u06cc\u0646\u060c \u0627\u06cc\u0646\u0633\u062a\u0627\u06af\u0631\u0627\u0645\u060c \u0641\u06cc\u0633 \u0628\u0648\u06a9\u060c \u062a\u0648\u06cc\u06cc\u062a\u0631 \u06cc\u0627 \u067e\u06cc\u0646\u062a\u0631\u0633\u062a.<\/p>\n<p>\u062f\u0631 \u0627\u06cc\u0646\u062c\u0627 \u0646\u062d\u0648\u0647 \u06a9\u0627\u0631 \u0622\u0646 \u0622\u0645\u062f\u0647 \u0627\u0633\u062a:<\/p>\n<blockquote>\n<ul style=\"font-size: 14px;\">\n<li style=\"color: #000000;\" aria-level=\"1\"><span style=\"color: #000000;\">\u06cc\u06a9 \u0646\u0645\u0627\u062f \u0628\u0627 \u06a9\u06cc\u0641\u06cc\u062a \u062e\u0648\u0628 \u062f\u0627\u0646\u0644\u0648\u062f \u06a9\u0646\u06cc\u062f\u2014\u0628\u0627 \u0627\u0637\u0645\u06cc\u0646\u0627\u0646 \u0627\u0632 \u062f\u0627\u0634\u062a\u0646 \u0645\u062c\u0648\u0632 \u062a\u062c\u0627\u0631\u06cc \u0628\u0631\u0627\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u062c\u062f\u062f \u0627\u0632 \u0646\u0645\u0627\u062f \u062f\u0631 \u0633\u0627\u06cc\u062a \u062e\u0648\u062f.<\/span><\/li>\n<li style=\"color: #000000;\" aria-level=\"1\"><span style=\"color: #000000;\">\u0646\u0645\u0627\u062f \u0631\u0627 \u062f\u0631 \u0635\u0641\u062d\u0647 \u0645\u0631\u0628\u0648\u0637\u0647 \u062c\u0627\u0633\u0627\u0632\u06cc \u06a9\u0646\u06cc\u062f\u060c \u0628\u0627 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u06cc\u06a9 \u062a\u06af a \u062f\u0631 \u0627\u0628\u062a\u062f\u0627\u06cc \u0642\u0637\u0639\u0647 \u06a9\u062f \u062e\u0648\u062f\u060c \u0622\u0646 \u0631\u0627 \u0628\u0647 \u062c\u0627\u06cc \u06cc\u06a9 \u062a\u0635\u0648\u06cc\u0631 \u0627\u06cc\u0633\u062a\u0627\u060c \u0628\u0647 \u06cc\u06a9 \u067e\u06cc\u0648\u0646\u062f \u062a\u0628\u062f\u06cc\u0644 \u06a9\u0646\u06cc\u062f.<\/span><\/li>\n<li style=\"color: #000000;\" aria-level=\"1\"><span style=\"color: #000000;\">\u0645\u0637\u0645\u0626\u0646 \u0634\u0648\u06cc\u062f \u06a9\u0647 \u0647\u062f\u0641 \u0631\u0627 \u0628\u0647 \u0627\u06cc\u0646 \u0635\u0648\u0631\u062a \u062a\u0646\u0638\u06cc\u0645 \u06a9\u0631\u062f\u0647 \u0627\u06cc\u062f: &#8216;target=&#8221;_blank&#8221;;  \u062f\u0631 \u063a\u06cc\u0631 \u0627\u06cc\u0646 \u0635\u0648\u0631\u062a\u060c \u0646\u0645\u0627\u062f \u0634\u0645\u0627 \u0628\u0647 \u062c\u0627\u06cc \u0627\u06cc\u0646\u06a9\u0647 \u062f\u0631 \u06cc\u06a9 \u067e\u0646\u062c\u0631\u0647 \u062c\u062f\u06cc\u062f \u0631\u0648\u06cc \u0635\u0641\u062d\u0647 \u0641\u0631\u0648\u062f \u0634\u0645\u0627 \u0628\u0627\u0632 \u0634\u0648\u062f.<\/span><\/li>\n<\/ul>\n<\/blockquote>\n<p>\u0627\u06af\u0631 \u0628\u0627 \u06a9\u062f \u0646\u0648\u06cc\u0633\u06cc HTML \u0622\u0634\u0646\u0627 \u0646\u06cc\u0633\u062a\u06cc\u062f\u060c \u0627\u0631\u0632\u0634 \u0622\u0646 \u0631\u0627 \u062f\u0627\u0631\u062f \u06a9\u0647 \u06cc\u06a9 \u062a\u0648\u0633\u0639\u0647 \u062f\u0647\u0646\u062f\u0647 \u0627\u0633\u062a\u062e\u062f\u0627\u0645 \u06a9\u0646\u06cc\u062f \u06cc\u0627 \u0627\u0632 \u06cc\u06a9 \u0627\u0641\u0632\u0648\u0646\u0647 \u0628\u062f\u0648\u0646 \u06a9\u062f \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f\u060c \u0632\u06cc\u0631\u0627 \u06cc\u06a9 \u0627\u0634\u062a\u0628\u0627\u0647 \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0631\u062d\u0644\u0647 \u0645\u06cc \u062a\u0648\u0627\u0646\u062f \u0628\u0647 \u0627\u06cc\u0646 \u0645\u0639\u0646\u06cc \u0628\u0627\u0634\u062f \u06a9\u0647 \u0646\u0645\u0627\u062f \u0634\u0645\u0627 \u062f\u0631 \u0645\u06a9\u0627\u0646 \u0627\u0634\u062a\u0628\u0627\u0647\u06cc \u0642\u0631\u0627\u0631 \u06af\u0631\u0641\u062a\u0647 \u0627\u0633\u062a\u060c \u0628\u0647 \u062f\u0631\u0633\u062a\u06cc \u067e\u06cc\u0648\u0646\u062f \u0646\u0645\u06cc \u062f\u0647\u062f \u06cc\u0627 \u0628\u0647 \u0633\u0627\u062f\u06af\u06cc \u0627\u0646\u062c\u0627\u0645 \u0646\u0645\u06cc \u0634\u0648\u062f. \u06a9\u0627\u0631 \u06a9\u0631\u062f\u0646  \u0627\u06a9\u062b\u0631 \u0635\u0627\u062d\u0628\u0627\u0646 \u0648\u0628\u200c\u0633\u0627\u06cc\u062a\u200c\u0647\u0627 \u0628\u0627\u06cc\u062f \u0627\u0646\u062f\u0627\u0632\u0647 \u0622\u06cc\u06a9\u0648\u0646\u200c\u0647\u0627 \u0631\u0627 \u062a\u063a\u06cc\u06cc\u0631 \u062f\u0647\u0646\u062f \u062a\u0627 \u0645\u0637\u0645\u0626\u0646 \u0634\u0648\u0646\u062f \u06a9\u0647 \u062f\u0631 \u0641\u06cc\u0644\u062f \u0645\u0646\u0627\u0633\u0628 \u062f\u0631 \u0635\u0641\u062d\u0647\u200c\u0634\u0627\u0646 \u0642\u0631\u0627\u0631 \u0645\u06cc\u200c\u06af\u06cc\u0631\u0646\u062f\u060c \u0627\u0645\u0627 \u0628\u0627\u06cc\u062f \u0645\u0631\u0627\u0642\u0628 \u0628\u0627\u0634\u06cc\u062f \u06a9\u0647 \u0627\u0632 \u0648\u0636\u0648\u062d \u0641\u0627\u06cc\u0644 \u0622\u06cc\u06a9\u0648\u0646 \u062a\u062c\u0627\u0648\u0632 \u0646\u06a9\u0646\u06cc\u062f \u0632\u06cc\u0631\u0627 \u0628\u0627\u0639\u062b \u0627\u06cc\u062c\u0627\u062f \u06cc\u06a9 \u062a\u0635\u0648\u06cc\u0631 \u062a\u0627\u0631 \u0645\u06cc\u200c\u0634\u0648\u062f.<\/p>\n<h3 style=\"font-size: 20px;\"><span class=\"ez-toc-section\" id=\"HTML_%D8%AF%D8%B1_%D9%85%D9%82%D8%A7%D8%A8%D9%84_%D9%BE%D9%84%D8%A7%DA%AF%DB%8C%D9%86_%D9%87%D8%A7\"><\/span><span style=\"color: #000000;\">HTML \u062f\u0631 \u0645\u0642\u0627\u0628\u0644 \u067e\u0644\u0627\u06af\u06cc\u0646 \u0647\u0627<\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u06cc\u06a9\u06cc \u0627\u0632 \u0686\u0627\u0644\u0634\u200c\u0647\u0627\u060c \u062d\u062a\u06cc \u0627\u06af\u0631 \u062f\u0631 HTML \u0645\u0633\u0644\u0637 \u0628\u0627\u0634\u06cc\u062f\u060c \u0627\u06cc\u0646 \u0627\u0633\u062a \u06a9\u0647 \u0628\u0627\u06cc\u062f \u0627\u06cc\u0646 \u0641\u0631\u0622\u06cc\u0646\u062f \u0631\u0627 \u0628\u0647 \u0635\u0648\u0631\u062a \u062f\u0633\u062a\u06cc \u0628\u0631\u0627\u06cc \u0647\u0631 \u067e\u0644\u062a\u0641\u0631\u0645 \u0631\u0633\u0627\u0646\u0647 \u0627\u062c\u062a\u0645\u0627\u0639\u06cc \u06a9\u0647 \u0645\u06cc\u200c\u062e\u0648\u0627\u0647\u06cc\u062f \u062f\u06a9\u0645\u0647\u200c\u0627\u06cc \u0628\u0631\u0627\u06cc \u0622\u0646 \u0627\u0636\u0627\u0641\u0647 \u06a9\u0646\u06cc\u062f\u060c \u062a\u06a9\u0631\u0627\u0631 \u06a9\u0646\u06cc\u062f.  \u06cc\u06a9 \u0628\u0631\u0646\u0627\u0645\u0647 \u06cc\u0627 \u0627\u0641\u0632\u0648\u0646\u0647 \u0631\u0633\u0627\u0646\u0647\u200c\u0647\u0627\u06cc \u0627\u062c\u062a\u0645\u0627\u0639\u06cc \u0628\u0627\u0639\u062b \u0645\u06cc\u200c\u0634\u0648\u062f \u06a9\u0647 \u0628\u0647\u200c\u0637\u0648\u0631 \u0642\u0627\u0628\u0644\u200c\u062a\u0648\u062c\u0647\u06cc \u0633\u0631\u06cc\u0639\u200c\u062a\u0631 \u0648 \u0622\u0633\u0627\u0646\u200c\u062a\u0631 \u0628\u0647 \u062d\u062f\u0627\u06a9\u062b\u0631 \u0631\u0633\u0627\u0646\u062f\u0646 \u062f\u06cc\u062f \u0631\u0633\u0627\u0646\u0647\u200c\u0647\u0627\u06cc \u0627\u062c\u062a\u0645\u0627\u0639\u06cc\u060c \u0627\u0641\u0632\u0627\u06cc\u0634 \u0641\u0627\u0644\u0648\u0648\u0631\u0647\u0627 \u0648 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u062f\u06a9\u0645\u0647\u200c\u0647\u0627\u06cc \u0645\u062a\u062d\u0631\u06a9 \u06a9\u0647 \u062d\u0631\u0641\u0647\u200c\u0627\u06cc \u0628\u0647 \u0646\u0638\u0631 \u0645\u06cc\u200c\u0631\u0633\u0646\u062f.<\/p>\n<p>\u0645\u0632\u0627\u06cc\u0627\u06cc \u0627\u0641\u0632\u0648\u0646\u0647 \u0622\u06cc\u06a9\u0648\u0646 \u0631\u0633\u0627\u0646\u0647 \u0647\u0627\u06cc \u0627\u062c\u062a\u0645\u0627\u0639\u06cc \u0639\u0628\u0627\u0631\u062a\u0646\u062f \u0627\u0632:<\/p>\n<blockquote>\n<ul style=\"font-size: 14px;\">\n<li style=\"color: #000000;\" aria-level=\"1\"><span style=\"color: #000000;\">\u0637\u0631\u062d\u200c\u0628\u0646\u062f\u06cc\u200c\u0647\u0627\u06cc \u0633\u0641\u0627\u0631\u0634\u06cc\u060c \u0628\u0646\u0627\u0628\u0631\u0627\u06cc\u0646 \u0622\u06cc\u06a9\u0648\u0646\u200c\u0647\u0627\u06cc \u0634\u0645\u0627 \u0631\u0648\u06cc \u0647\u0645 \u0686\u06cc\u062f\u0647 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f \u06cc\u0627 \u06a9\u0627\u0645\u0644\u0627\u064b \u0686\u06cc\u062f\u0647 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f \u062a\u0627 \u0628\u0627 \u0635\u0641\u062d\u0627\u062a \u0648\u0628 \u0648 \u0633\u0627\u06cc\u0631 \u0645\u062d\u062a\u0648\u0627\u06cc \u0634\u0645\u0627 \u0645\u0637\u0627\u0628\u0642\u062a \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u0646\u062f.<\/span><\/li>\n<li style=\"color: #000000;\" aria-level=\"1\"><span style=\"color: #000000;\">\u0646\u0627\u0645 \u062a\u062c\u0627\u0631\u06cc \u0633\u0641\u0627\u0631\u0634\u06cc\u060c \u0628\u0627 \u06af\u0632\u06cc\u0646\u0647 \u0647\u0627\u06cc\u06cc \u0628\u0631\u0627\u06cc \u062a\u0646\u0638\u06cc\u0645 \u0631\u0646\u06af\u060c \u0627\u0646\u062f\u0627\u0632\u0647 \u0648 \u067e\u0633 \u0632\u0645\u06cc\u0646\u0647 \u0647\u0631 \u0646\u0645\u0627\u062f \u0628\u0631\u0627\u06cc \u0633\u0627\u0632\u06af\u0627\u0631\u06cc<\/span><\/li>\n<li style=\"color: #000000;\" aria-level=\"1\"><span style=\"color: #000000;\">\u0645\u0648\u0642\u0639\u06cc\u062a \u0686\u0633\u0628\u0646\u062f\u0647 \u0628\u0647 \u0627\u06cc\u0646 \u0645\u0639\u0646\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0647\u0646\u06af\u0627\u0645 \u062d\u0631\u06a9\u062a \u0647\u0631 \u0645\u0634\u062a\u0631\u06cc \u0628\u0647 \u0628\u0627\u0644\u0627 \u06cc\u0627 \u067e\u0627\u06cc\u06cc\u0646\u060c \u0646\u0645\u0627\u062f\u0647\u0627 \u062f\u0631 \u0635\u0641\u062d\u0647 \u0628\u0627\u0642\u06cc \u0645\u06cc \u0645\u0627\u0646\u0646\u062f<\/span><\/li>\n<\/ul>\n<\/blockquote>\n<p>\u0622\u06cc\u06a9\u0648\u0646 \u0647\u0627\u06cc \u0645\u062a\u062d\u0631\u06a9 \u0645\u06cc \u062a\u0648\u0627\u0646\u0646\u062f \u062a\u0639\u0627\u0645\u0644 \u0631\u0627 \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u06cc\u06a9 \u0648\u06cc\u0698\u06af\u06cc \u0686\u0634\u0645 \u0646\u0648\u0627\u0632 &#8211; \u0628\u0627 \u0628\u0647\u06cc\u0646\u0647 \u0633\u0627\u0632\u06cc \u0645\u0648\u0628\u0627\u06cc\u0644 \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f &#8211; \u0628\u0647\u0628\u0648\u062f \u0628\u062e\u0634\u0646\u062f \u062a\u0627 \u0628\u062a\u0648\u0627\u0646\u06cc\u062f \u0628\u0627\u0632\u062f\u06cc\u062f\u06a9\u0646\u0646\u062f\u06af\u0627\u0646 \u0631\u0627 \u062f\u0631 \u0647\u0631 \u0631\u0633\u0627\u0646\u0647 \u0648 \u0627\u0632 \u0637\u0631\u06cc\u0642 \u0647\u0631 \u0648\u0633\u06cc\u0644\u0647 \u0627\u06cc \u0628\u0647 \u0635\u0641\u062d\u0627\u062a \u0631\u0633\u0627\u0646\u0647 \u0647\u0627\u06cc \u0627\u062c\u062a\u0645\u0627\u0639\u06cc \u062e\u0648\u062f \u062f\u0639\u0648\u062a \u06a9\u0646\u06cc\u062f. <\/p>\n<h2 style=\"font-size: 24px;\"><span class=\"ez-toc-section\" id=\"%D9%85%D8%B2%D8%A7%DB%8C%D8%A7%DB%8C_%D8%A7%D9%81%D8%B2%D9%88%D8%AF%D9%86_%D8%A2%DB%8C%DA%A9%D9%88%D9%86_%D9%87%D8%A7%DB%8C_%D8%B1%D8%B3%D8%A7%D9%86%D9%87_%D9%87%D8%A7%DB%8C_%D8%A7%D8%AC%D8%AA%D9%85%D8%A7%D8%B9%DB%8C_%D8%A8%D9%87_%D8%B5%D9%81%D8%AD%D8%A7%D8%AA_%D9%81%D8%B1%D9%88%D8%AF\"><\/span><span style=\"color: #000000;\">\u0645\u0632\u0627\u06cc\u0627\u06cc \u0627\u0641\u0632\u0648\u062f\u0646 \u0622\u06cc\u06a9\u0648\u0646 \u0647\u0627\u06cc \u0631\u0633\u0627\u0646\u0647 \u0647\u0627\u06cc \u0627\u062c\u062a\u0645\u0627\u0639\u06cc \u0628\u0647 \u0635\u0641\u062d\u0627\u062a \u0641\u0631\u0648\u062f<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0686\u0631\u0627 \u0633\u0639\u06cc \u06a9\u0646\u06cc\u062f \u0622\u06cc\u06a9\u0648\u0646 \u0647\u0627\u06cc \u0631\u0633\u0627\u0646\u0647 \u0647\u0627\u06cc \u0627\u062c\u062a\u0645\u0627\u0639\u06cc \u0631\u0627 \u062f\u0631 \u0648\u0628 \u0633\u0627\u06cc\u062a \u062e\u0648\u062f \u062f\u0631\u062c \u06a9\u0646\u06cc\u062f\u061f  \u067e\u0627\u0633\u062e \u062f\u0631 \u0645\u0648\u0631\u062f \u0631\u0634\u062f \u0637\u0628\u06cc\u0639\u06cc\u060c \u0627\u062b\u0628\u0627\u062a \u0627\u062c\u062a\u0645\u0627\u0639\u06cc \u0648 \u062a\u0639\u0627\u0645\u0644 \u0628\u0627 \u0628\u0627\u0632\u062f\u06cc\u062f\u06a9\u0646\u0646\u062f\u0647 \u0627\u0633\u062a.  \u0631\u0633\u0627\u0646\u0647 \u0647\u0627\u06cc \u0627\u062c\u062a\u0645\u0627\u0639\u06cc \u0628\u0647 \u0646\u0627\u0686\u0627\u0631 \u0622\u0631\u0627\u0645\u0634 \u0628\u06cc\u0634\u062a\u0631\u06cc \u0646\u0633\u0628\u062a \u0628\u0647 \u06cc\u06a9 \u0648\u0628 \u0633\u0627\u06cc\u062a \u062a\u062c\u0627\u0631\u06cc \u062f\u0627\u0631\u0646\u062f.  \u0634\u0645\u0627 \u0641\u0631\u0635\u062a \u0647\u0627\u06cc \u0645\u062a\u0639\u062f\u062f\u06cc \u062f\u0627\u0631\u06cc\u062f \u062a\u0627 \u0627\u0632 \u0645\u0634\u062a\u0631\u06cc\u0627\u0646 \u0628\u0627\u0632\u062e\u0648\u0631\u062f \u0628\u067e\u0631\u0633\u06cc\u062f\u060c \u0627\u06cc\u062f\u0647 \u0647\u0627\u06cc \u062c\u062f\u06cc\u062f \u0631\u0627 \u067e\u06cc\u0634 \u0646\u0645\u0627\u06cc\u0634 \u062f\u0647\u06cc\u062f\u060c \u0628\u0647 \u0633\u0648\u0627\u0644\u0627\u062a \u067e\u0627\u0633\u062e \u062f\u0647\u06cc\u062f \u06cc\u0627 \u0627\u0631\u0632\u0634 \u0647\u0627\u06cc \u0628\u0631\u0646\u062f \u062e\u0648\u062f \u0631\u0627 \u0627\u0631\u062a\u0642\u0627 \u062f\u0647\u06cc\u062f.<\/p>\n<h3 style=\"font-size: 20px;\"><span class=\"ez-toc-section\" id=\"%D9%85%D8%AD%D8%AA%D9%88%D8%A7%DB%8C_%D8%A7%DB%8C%D8%AC%D8%A7%D8%AF_%D8%B4%D8%AF%D9%87_%D8%AA%D9%88%D8%B3%D8%B7_%DA%A9%D8%A7%D8%B1%D8%A8%D8%B1\"><\/span><span style=\"color: #000000;\">\u0645\u062d\u062a\u0648\u0627\u06cc \u0627\u06cc\u062c\u0627\u062f \u0634\u062f\u0647 \u062a\u0648\u0633\u0637 \u06a9\u0627\u0631\u0628\u0631<\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0647\u0646\u06af\u0627\u0645\u06cc \u06a9\u0647 \u0628\u0627\u0632\u062f\u06cc\u062f\u06a9\u0646\u0646\u062f\u06af\u0627\u0646 \u0627\u0628\u0632\u0627\u0631\u06cc \u0628\u0627 \u06cc\u06a9 \u06a9\u0644\u06cc\u06a9 \u062f\u0627\u0631\u0646\u062f\u060c \u0645\u0627\u0646\u0646\u062f \u0628\u0627\u0632\u062a\u0648\u06cc\u06cc\u062a \u06a9\u0631\u062f\u0646 \u06cc\u06a9 \u0648\u06cc\u062f\u06cc\u0648\u06cc \u062e\u0646\u062f\u0647 \u062f\u0627\u0631\u060c \u0644\u0627\u06cc\u06a9 \u06a9\u0631\u062f\u0646 \u06cc\u06a9 \u062a\u0628\u0644\u06cc\u063a \u0641\u06cc\u0633 \u0628\u0648\u06a9\u060c \u06cc\u0627 \u0630\u062e\u06cc\u0631\u0647 \u06cc\u06a9 \u067e\u0633\u062a \u0628\u0631\u0627\u06cc \u062a\u0645\u0627\u0634\u0627\u06cc \u0645\u062c\u062f\u062f \u06cc\u0627 \u0627\u0634\u062a\u0631\u0627\u06a9 \u06af\u0630\u0627\u0631\u06cc \u062f\u0631 \u0641\u0631\u0635\u062a\u06cc \u062f\u06cc\u06af\u0631\u060c \u0628\u0647 \u0627\u062d\u062a\u0645\u0627\u0644 \u0632\u06cc\u0627\u062f \u0627\u0632 \u0627\u0634\u062a\u0631\u0627\u06a9 \u06af\u0630\u0627\u0631\u06cc \u0627\u062c\u062a\u0645\u0627\u0639\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc \u06a9\u0646\u0646\u062f.  \u0645\u062d\u062a\u0648\u0627\u06cc \u062a\u0648\u0644\u06cc\u062f \u0634\u062f\u0647 \u062a\u0648\u0633\u0637 \u06a9\u0627\u0631\u0628\u0631 \u0628\u0631\u0627\u06cc \u0627\u062b\u0628\u0627\u062a \u0627\u062c\u062a\u0645\u0627\u0639\u06cc \u0639\u0627\u0644\u06cc \u0627\u0633\u062a\u060c \u0648 \u0647\u0631 \u0686\u0647 \u062a\u0639\u062f\u0627\u062f \u0644\u0627\u06cc\u06a9\u200c\u0647\u0627\u060c \u0646\u0638\u0631\u0627\u062a\u060c \u062a\u0639\u0627\u0645\u0644\u0627\u062a \u06cc\u0627 \u06a9\u0644\u06cc\u06a9\u200c\u0647\u0627\u06cc \u0628\u06cc\u0634\u062a\u0631\u06cc \u062f\u0631\u06cc\u0627\u0641\u062a \u06a9\u0646\u06cc\u062f\u060c \u0641\u06cc\u062f\u0647\u0627\u06cc \u0627\u062c\u062a\u0645\u0627\u0639\u06cc \u0648 \u0628\u0631\u0646\u062f \u0634\u0645\u0627 \u0642\u0627\u0628\u0644 \u0645\u0634\u0627\u0647\u062f\u0647\u200c\u062a\u0631 \u0648 \u0645\u0639\u062a\u0628\u0631\u062a\u0631 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f.<\/p>\n<h3 style=\"font-size: 20px;\"><span class=\"ez-toc-section\" id=\"%D8%A7%D8%AB%D8%A8%D8%A7%D8%AA_%D8%A7%D8%AC%D8%AA%D9%85%D8%A7%D8%B9%DB%8C\"><\/span><span style=\"color: #000000;\">\u0627\u062b\u0628\u0627\u062a \u0627\u062c\u062a\u0645\u0627\u0639\u06cc<\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0647\u062f\u0627\u06cc\u062a \u062e\u0648\u0627\u0646\u0646\u062f\u06af\u0627\u0646 \u0628\u0647 \u0635\u0641\u062d\u0627\u062a \u0631\u0633\u0627\u0646\u0647 \u0647\u0627\u06cc \u0627\u062c\u062a\u0645\u0627\u0639\u06cc \u0634\u0645\u0627 \u0628\u0647 \u0627\u06cc\u0646 \u0645\u0639\u0646\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0622\u0646\u0647\u0627 \u0645\u06cc \u062a\u0648\u0627\u0646\u0646\u062f \u0641\u06cc\u062f\u0647\u0627\u06cc \u0634\u0645\u0627 \u0631\u0627 \u062f\u0646\u0628\u0627\u0644 \u06a9\u0646\u0646\u062f \u062a\u0627 \u0628\u0647 \u0631\u0648\u0632 \u0628\u0645\u0627\u0646\u0646\u062f\u060c \u0628\u0627 \u062e\u0648\u0627\u0646\u062f\u0646 \u0646\u0638\u0631\u0627\u062a \u0634\u0645\u0627 \u0645\u062f\u0627\u0631\u06a9 \u0627\u062c\u062a\u0645\u0627\u0639\u06cc \u0631\u0627 \u06a9\u0634\u0641 \u06a9\u0646\u0646\u062f \u0648 \u062a\u0639\u062f\u0627\u062f \u0641\u0627\u0644\u0648\u0648\u0631\u0647\u0627\u06cc \u0634\u0645\u0627 \u0631\u0627 \u0628\u0647\u0628\u0648\u062f \u0628\u062e\u0634\u0646\u062f.  \u0647\u0631\u0686\u0647 \u0646\u0642\u0627\u0637 \u062a\u0645\u0627\u0633 \u0628\u06cc\u0634\u062a\u0631\u06cc \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f\u060c \u0634\u0627\u0646\u0633 \u0628\u06cc\u0634\u062a\u0631\u06cc \u0628\u0631\u0627\u06cc \u062a\u0639\u0627\u0645\u0644\u060c \u0646\u0634\u0627\u0646 \u062f\u0627\u062f\u0646 \u0627\u0631\u0632\u0634 \u067e\u06cc\u0634\u0646\u0647\u0627\u062f\u06cc \u062e\u0648\u062f \u06cc\u0627 \u0627\u0631\u062a\u0628\u0627\u0637 \u0628\u0627 \u0628\u0627\u0632\u062f\u06cc\u062f\u06a9\u0646\u0646\u062f\u06af\u0627\u0646 \u0628\u0631\u0627\u06cc \u0628\u0647\u0628\u0648\u062f \u062a\u0628\u062f\u06cc\u0644 \u062f\u0627\u0631\u06cc\u062f. <\/p>\n<h3 style=\"font-size: 20px;\"><span class=\"ez-toc-section\" id=\"%D8%AA%D8%B9%D8%A7%D9%85%D9%84_%D8%A8%D9%87%D8%A8%D9%88%D8%AF_%DB%8C%D8%A7%D9%81%D8%AA%D9%87\"><\/span><span style=\"color: #000000;\">\u062a\u0639\u0627\u0645\u0644 \u0628\u0647\u0628\u0648\u062f \u06cc\u0627\u0641\u062a\u0647<\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0627\u062d\u062a\u0645\u0627\u0644 \u0627\u06cc\u0646\u06a9\u0647 \u0646\u0633\u0644\u200c\u0647\u0627\u06cc \u062c\u0648\u0627\u0646 \u0631\u0648\u06cc \u0646\u0645\u0627\u062f \u0631\u0633\u0627\u0646\u0647\u200c\u0647\u0627\u06cc \u0627\u062c\u062a\u0645\u0627\u0639\u06cc \u06a9\u0644\u06cc\u06a9 \u06a9\u0646\u0646\u062f\u060c \u0628\u0631\u0646\u062f\u06cc \u0631\u0627 \u062f\u0646\u0628\u0627\u0644 \u06a9\u0646\u0646\u062f \u0648 \u067e\u0633\u062a\u200c\u0647\u0627\u06cc\u0634\u0627\u0646 \u0631\u0627 \u0628\u062e\u0648\u0627\u0646\u0646\u062f\u060c \u0686\u0646\u062f\u06cc\u0646 \u0628\u0631\u0627\u0628\u0631 \u0628\u06cc\u0634\u062a\u0631 \u0627\u0632 \u062a\u0627\u06cc\u067e \u062f\u0633\u062a\u06cc \u06cc\u06a9 \u0622\u062f\u0631\u0633 \u0627\u06cc\u0645\u06cc\u0644 \u062f\u0631 \u0641\u0631\u0645 \u062b\u0628\u062a\u200c\u0646\u0627\u0645 \u062e\u0628\u0631\u0646\u0627\u0645\u0647 \u0647\u0633\u062a\u0646\u062f.  \u062a\u0628\u0644\u06cc\u063a \u062d\u0636\u0648\u0631 \u062e\u0648\u062f \u062f\u0631 \u0631\u0633\u0627\u0646\u0647\u200c\u0647\u0627\u06cc \u0627\u062c\u062a\u0645\u0627\u0639\u06cc \u0648 \u06cc\u0627\u0641\u062a\u0646 \u0622\u0646 \u0622\u0633\u0627\u0646\u200c\u062a\u0631\u060c \u0631\u0627\u0647\u06cc \u0639\u0627\u0644\u06cc \u0628\u0631\u0627\u06cc \u062a\u0639\u0627\u0645\u0644 \u0628\u0627 \u0645\u0634\u062a\u0631\u06cc\u0627\u0646 \u062e\u0648\u062f \u0628\u0631 \u0627\u0633\u0627\u0633 \u0634\u0631\u0627\u06cc\u0637 \u0622\u0646\u0647\u0627 \u0648 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u062d\u062f\u0627\u06a9\u062b\u0631\u06cc \u0627\u0632 \u0647\u0631 \u0631\u0633\u0627\u0646\u0647\u200c\u0627\u06cc \u0627\u0633\u062a \u06a9\u0647 \u062f\u0627\u0631\u06cc\u062f.<\/p>\n<\/div>\n<p><script>(function(d, s, id) {\n  var js, fjs = d.getElementsByTagName(s)[0];\n  if (d.getElementById(id)) return;\n  js = d.createElement(s); js.id = id;\n  js.src = \"\/\/connect.facebook.net\/en_GB\/all.js#xfbml=1&status=0\";\n  fjs.parentNode.insertBefore(js, fjs);\n}(document, 'script', 'facebook-jssdk'));<\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0627\u0636\u0627\u0641\u0647 \u0643\u0631\u062f\u0646 \u0622\u06cc\u06a9\u0648\u0646 \u0647\u0627\u06cc \u0631\u0633\u0627\u0646\u0647 \u0647\u0627\u06cc \u0627\u062c\u062a\u0645\u0627\u0639\u06cc \u0631\u0627\u06cc\u06af\u0627\u0646 \u0628\u0647 \u0635\u0641\u062d\u0627\u062a \u0648\u0628 \u0633\u0627\u06cc\u062a \u0634\u0645\u0627 \u0645\u06cc \u062a\u0648\u0627\u0646\u062f \u0631\u0627\u0647\u06cc \u0639\u0627\u0644\u06cc \u0628\u0631\u0627\u06cc \u0647\u062f\u0627\u06cc\u062a \u0628\u0627\u0632\u062f\u06cc\u062f\u06a9\u0646\u0646\u062f\u06af\u0627\u0646 \u0628\u0647 \u0641\u06cc\u062f\u0647\u0627\u06cc \u0634\u0645\u0627\u060c \u0631\u0634\u062f \u0645\u062e\u0627\u0637\u0628\u0627\u0646 \u0648 \u0627\u0631\u0627\u0626\u0647 \u0627\u062b\u0628\u0627\u062a \u0627\u062c\u062a\u0645\u0627\u0639\u06cc \u0628\u0627\u0634\u062f \u2013 \u0627\u0645\u0627 \u0636\u0631\u0648\u0631\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0646\u0645\u0627\u062f\u0647\u0627\u06cc \u0634\u0645\u0627 \u0628\u0647 \u062f\u0631\u0633\u062a\u06cc \u0642\u0627\u0644\u0628 \u0628\u0646\u062f\u06cc \u0634\u062f\u0647 \u0648 \u0628\u0647 \u0635\u0641\u062d\u0627\u062a \u0645\u0646\u0627\u0633\u0628 \u067e\u06cc\u0648\u0646\u062f \u062f\u0627\u062f\u0647 \u0634\u0648\u0646\u062f. \u0646\u06a9\u062a\u0647 \u06a9\u0644\u06cc\u062f\u06cc \u0627\u06cc\u0646 \u0627\u0633\u062a \u06a9\u0647 \u06cc\u06a9 &hellip;<\/p>\n","protected":false},"author":2,"featured_media":11723,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[174],"tags":[],"class_list":["post-11722","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-howto"],"_links":{"self":[{"href":"https:\/\/nabfollower.com\/blog\/wp-json\/wp\/v2\/posts\/11722","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nabfollower.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nabfollower.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nabfollower.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/nabfollower.com\/blog\/wp-json\/wp\/v2\/comments?post=11722"}],"version-history":[{"count":0,"href":"https:\/\/nabfollower.com\/blog\/wp-json\/wp\/v2\/posts\/11722\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nabfollower.com\/blog\/wp-json\/wp\/v2\/media\/11723"}],"wp:attachment":[{"href":"https:\/\/nabfollower.com\/blog\/wp-json\/wp\/v2\/media?parent=11722"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nabfollower.com\/blog\/wp-json\/wp\/v2\/categories?post=11722"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nabfollower.com\/blog\/wp-json\/wp\/v2\/tags?post=11722"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}