{"id":11804,"date":"2023-03-13T13:15:08","date_gmt":"2023-03-13T09:45:08","guid":{"rendered":"https:\/\/nabfollower.com\/blog\/dungeons-dragons-dnd-ways-to-increase-armor-class-ac\/"},"modified":"2023-03-13T13:15:08","modified_gmt":"2023-03-13T09:45:08","slug":"dungeons-dragons-dnd-ways-to-increase-armor-class-ac","status":"publish","type":"post","link":"https:\/\/nabfollower.com\/blog\/dungeons-dragons-dnd-ways-to-increase-armor-class-ac\/","title":{"rendered":"6 \u0631\u0627\u0647 \u0628\u0631\u0627\u06cc \u0627\u0641\u0632\u0627\u06cc\u0634 \u06a9\u0644\u0627\u0633 \u0632\u0631\u0647\u06cc \u062e\u0648\u062f \u062f\u0631 D&#038;D"},"content":{"rendered":"<div>\n<p>\u0647\u0646\u06af\u0627\u0645 \u0634\u0631\u06a9\u062a \u062f\u0631 \u0645\u0628\u0627\u0631\u0632\u0627\u062a \u062f\u0631 Dungeons &#038; Dragons\u060c \u0645\u06a9\u0627\u0646\u06cc\u06a9 \u0647\u0627\u06cc \u0632\u06cc\u0627\u062f\u06cc \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u062f \u06a9\u0647 \u0628\u0627\u0632\u06cc\u06a9\u0646\u0627\u0646 \u0628\u0627\u06cc\u062f \u0639\u0644\u0627\u0648\u0647 \u0628\u0631 \u0627\u0645\u062a\u06cc\u0627\u0632\u0627\u062a \u062a\u0648\u0627\u0646\u0627\u06cc\u06cc \u0634\u062e\u0635\u06cc\u062a \u0648 \u0648\u06cc\u0698\u06af\u06cc \u0647\u0627\u06cc \u06a9\u0644\u0627\u0633\u06cc \u0645\u062e\u062a\u0644\u0641\u060c \u0622\u0646\u0647\u0627 \u0631\u0627 \u067e\u06cc\u06af\u06cc\u0631\u06cc \u06a9\u0646\u0646\u062f.  \u0686\u0647 \u06cc\u06a9 \u06a9\u0627\u0631\u0627\u06a9\u062a\u0631 \u062f\u0631 \u0633\u0637\u062d \u06cc\u06a9 \u0628\u0627\u0634\u062f \u06cc\u0627 \u0633\u0637\u062d \u0628\u06cc\u0633\u062a\u060c \u06a9\u0644\u0627\u0633 Armor \u06cc\u06a9 \u0634\u062e\u0635\u06cc\u062a (\u06cc\u0627 \u0628\u0647 \u0627\u062e\u062a\u0635\u0627\u0631 AC) \u06cc\u06a9 \u0639\u0646\u0635\u0631 \u062f\u0641\u0627\u0639\u06cc \u0645\u0647\u0645 \u0627\u0633\u062a.  \u0628\u0627 \u0627\u0646\u0639\u06a9\u0627\u0633 \u0627\u06cc\u0646\u06a9\u0647 \u06cc\u06a9 \u0634\u062e\u0635\u06cc\u062a \u0686\u0642\u062f\u0631 \u0632\u0631\u0647 \u067e\u0648\u0634 \u06cc\u0627 \u06af\u0631\u06cc\u0632\u0627\u0646 \u0627\u0633\u062a\u060c AC \u06cc\u06a9 \u06a9\u0627\u0631\u0627\u06a9\u062a\u0631 \u06a9\u0644 \u0639\u062f\u062f\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0645\u0648\u062c\u0648\u062f\u06cc \u062f\u06cc\u06af\u0631 \u0628\u0631\u0627\u06cc \u0636\u0631\u0628\u0647 \u0632\u062f\u0646 \u0628\u0647 \u06cc\u06a9 \u0634\u062e\u0635\u06cc\u062a \u0628\u0627 \u06cc\u06a9 \u062d\u0645\u0644\u0647 \u0628\u0627\u06cc\u062f \u0628\u067e\u06cc\u0686\u062f.<\/p>\n<p><!-- No winning ad found for zone: below first paragraph! --><br \/>\n<!-- No winning ad found for zone: mid intro! --><\/p>\n<p><span class=\"related-single\">\u0645\u0631\u062a\u0628\u0637: D&#038;D: \u0628\u0647\u062a\u0631\u06cc\u0646 \u0648\u06cc\u0698\u06af\u06cc \u0647\u0627\u06cc \u06a9\u0644\u0627\u0633 \u0628\u0631\u0627\u06cc \u0645\u0628\u0627\u0631\u0632\u0647<\/span><\/p>\n<p>\u0627\u06cc\u0646 \u0628\u0647 \u0627\u06cc\u0646 \u0645\u0639\u0646\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0647\u0631 \u0686\u0647 AC \u0634\u062e\u0635\u06cc\u062a \u0628\u0627\u0644\u0627\u062a\u0631 \u0628\u0627\u0634\u062f\u060c \u0636\u0631\u0628\u0647 \u0632\u062f\u0646 \u0628\u0647 \u0622\u0646\u0647\u0627 \u062f\u0634\u0648\u0627\u0631\u062a\u0631 \u062e\u0648\u0627\u0647\u062f \u0628\u0648\u062f.  \u0628\u0647 \u0647\u0645\u06cc\u0646 \u062f\u0644\u06cc\u0644\u060c \u0627\u06cc\u0646 \u0627\u06cc\u062f\u0647 \u0639\u0627\u0644\u06cc \u0628\u0631\u0627\u06cc \u0628\u0627\u0632\u06cc\u06a9\u0646\u0627\u0646 \u0627\u0633\u062a \u06a9\u0647 \u0646\u0633\u0628\u062a \u0628\u0647 AC \u0634\u062e\u0635\u06cc\u062a \u0647\u0627\u06cc \u062e\u0648\u062f \u0622\u06af\u0627\u0647 \u0628\u0627\u0634\u0646\u062f \u0648 \u062f\u0631 \u0637\u0648\u0644 \u06cc\u06a9 \u06a9\u0645\u067e\u06cc\u0646 \u0628\u0631\u0627\u06cc \u0627\u0641\u0632\u0627\u06cc\u0634 \u0622\u0646 \u062a\u0644\u0627\u0634 \u06a9\u0646\u0646\u062f.  \u0628\u0646\u0627\u0628\u0631\u0627\u06cc\u0646 \u0645\u0627 \u0642\u0635\u062f \u062f\u0627\u0631\u06cc\u0645 \u0631\u0627\u0647 \u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641\u06cc \u0631\u0627 \u06a9\u0647 \u0628\u0627\u0632\u06cc\u06a9\u0646\u0627\u0646 \u0645\u06cc \u062a\u0648\u0627\u0646\u0646\u062f \u0628\u0631\u0627\u06cc \u0628\u0647\u0628\u0648\u062f AC \u0634\u062e\u0635\u06cc\u062a \u062e\u0648\u062f \u062f\u0631 Dungeons &#038; Dragons \u0627\u0646\u062c\u0627\u0645 \u062f\u0647\u0646\u062f \u0631\u0627 \u0628\u0631\u0631\u0633\u06cc \u06a9\u0646\u06cc\u0645.<\/p>\n<p><em><strong>\u0628\u0647 \u0631\u0648\u0632 \u0634\u062f\u0647 \u062f\u0631 10 \u0645\u0627\u0631\u0633 2023 \u062a\u0648\u0633\u0637 \u0628\u0631\u0627\u0646\u062f\u0646 \u0644\u06cc\u0632\u0627\u0631\u062f\u06cc: <\/strong>\u0628\u062e\u0634\u06cc \u0627\u0632 \u0632\u06cc\u0628\u0627\u06cc\u06cc \u0646\u0633\u062e\u0647 5 D&#038;D \u0627\u06cc\u0646 \u0627\u0633\u062a \u06a9\u0647 \u0686\u06af\u0648\u0646\u0647 \u0645\u062c\u0645\u0648\u0639\u0647 \u0642\u0648\u0627\u0646\u06cc\u0646 \u0627\u062c\u0627\u0632\u0647 \u0645\u06cc \u062f\u0647\u062f \u062a\u0627 \u0628\u0631\u062e\u06cc \u0627\u0632 \u067e\u06cc\u0686\u06cc\u062f\u06af\u06cc \u0647\u0627\u06cc \u0639\u0645\u062f\u0647 \u0631\u0627 \u0641\u0631\u0627\u0647\u0645 \u06a9\u0646\u062f\u060c \u062f\u0631 \u062d\u0627\u0644\u06cc \u06a9\u0647 \u0647\u0645\u0686\u0646\u0627\u0646 \u0628\u0631\u0627\u06cc \u0628\u0627\u0632\u06cc\u06a9\u0646\u0627\u0646 \u0645\u0639\u0645\u0648\u0644\u06cc \u062a\u0631 \u0648 \u0622\u0633\u0627\u0646 \u0628\u0647 \u062f\u0646\u0628\u0627\u0644 \u0622\u0646 \u0627\u0633\u062a.  \u0648 \u0628\u0627 \u0647\u0631 \u0645\u06a9\u0645\u0644\u060c \u0645\u0627\u062c\u0631\u0627\u062c\u0648\u06cc\u06cc \u0648 \u0642\u0648\u0627\u0646\u06cc\u0646 \u062c\u062f\u06cc\u062f\u060c \u06af\u0632\u06cc\u0646\u0647 \u0647\u0627\u06cc \u0628\u06cc\u0634\u062a\u0631\u06cc \u062f\u0631 \u062f\u0633\u062a\u0631\u0633 \u0634\u0645\u0627 \u0642\u0631\u0627\u0631 \u0645\u06cc \u06af\u06cc\u0631\u062f.  \u0627\u06cc\u0646 \u0634\u0627\u0645\u0644 \u0631\u0627\u0647 \u0647\u0627\u06cc \u0628\u06cc\u0634\u062a\u0631\u06cc \u0628\u0631\u0627\u06cc \u0627\u0641\u0632\u0627\u06cc\u0634 AC \u0634\u0645\u0627 \u062f\u0631 5e \u0627\u0633\u062a.  \u0645\u0627 \u0627\u06cc\u0646 \u0644\u06cc\u0633\u062a \u0631\u0627 \u0628\u0627 \u0648\u0631\u0648\u062f\u06cc \u0647\u0627\u06cc \u0628\u06cc\u0634\u062a\u0631\u06cc \u0628\u0647 \u0631\u0648\u0632 \u06a9\u0631\u062f\u0647 \u0627\u06cc\u0645 \u062a\u0627 \u0628\u062a\u0648\u0627\u0646\u06cc\u062f \u0647\u0645\u0647 \u0628\u0647\u062a\u0631\u06cc\u0646 \u06af\u0632\u06cc\u0646\u0647 \u0647\u0627 \u0631\u0627 \u062f\u0631\u0633\u062a \u062f\u0631 \u0645\u0642\u0627\u0628\u0644 \u062e\u0648\u062f \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f.<\/em><\/p>\n<p><!-- Zone: native in content. --><\/p>\n<p><!-- Zone: connected below ad. --><\/p>\n<p><!-- No repeatable ad for zone: every entry repeatable. --><!-- Repeatable debug data: {\"adPosition\":0,\"skipEvery\":null,\"nbrPlacementFilledEachSkip\":0,\"nbrPlacementsScanned\":0,\"ruleCount\":false,\"degradationStartingPoint\":null,\"actualCount\":0} --><\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter-rtl ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u0641\u0647\u0631\u0633\u062a \u0645\u0637\u0627\u0644\u0628<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"\u062a\u063a\u06cc\u06cc\u0631 \u0648\u0636\u0639\u06cc\u062a \u0641\u0647\u0631\u0633\u062a \u0645\u0637\u0627\u0644\u0628\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/nabfollower.com\/blog\/dungeons-dragons-dnd-ways-to-increase-armor-class-ac\/#6_%D9%85%D9%87%D8%A7%D8%B1%D8%AA_%D8%AE%D9%88%D8%AF_%D8%B1%D8%A7_%D8%A8%D9%87%D8%A8%D9%88%D8%AF_%D8%A8%D8%AE%D8%B4%DB%8C%D8%AF\" >6  \u0645\u0647\u0627\u0631\u062a \u062e\u0648\u062f \u0631\u0627 \u0628\u0647\u0628\u0648\u062f \u0628\u062e\u0634\u06cc\u062f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/nabfollower.com\/blog\/dungeons-dragons-dnd-ways-to-increase-armor-class-ac\/#5_%D8%B2%D8%B1%D9%87_%D8%AE%D9%88%D8%AF_%D8%B1%D8%A7_%D8%A7%D8%B1%D8%AA%D9%82%D8%A7_%D8%AF%D9%87%DB%8C%D8%AF\" >5  \u0632\u0631\u0647 \u062e\u0648\u062f \u0631\u0627 \u0627\u0631\u062a\u0642\u0627 \u062f\u0647\u06cc\u062f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/nabfollower.com\/blog\/dungeons-dragons-dnd-ways-to-increase-armor-class-ac\/#4_%D8%B3%D8%A8%DA%A9_%D9%85%D8%A8%D8%A7%D8%B1%D8%B2%D9%87_%D8%AF%D9%81%D8%A7%D8%B9%DB%8C_%D8%B1%D8%A7_%D8%A8%D9%87_%D8%AF%D8%B3%D8%AA_%D8%A2%D9%88%D8%B1%DB%8C%D8%AF\" >4  \u0633\u0628\u06a9 \u0645\u0628\u0627\u0631\u0632\u0647 \u062f\u0641\u0627\u0639\u06cc \u0631\u0627 \u0628\u0647 \u062f\u0633\u062a \u0622\u0648\u0631\u06cc\u062f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/nabfollower.com\/blog\/dungeons-dragons-dnd-ways-to-increase-armor-class-ac\/#3_%D8%A7%D8%B2_A_Shield_%D8%A7%D8%B3%D8%AA%D9%81%D8%A7%D8%AF%D9%87_%DA%A9%D9%86%DB%8C%D8%AF\" >3  \u0627\u0632 A Shield \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/nabfollower.com\/blog\/dungeons-dragons-dnd-ways-to-increase-armor-class-ac\/#2_%D8%A7%D8%B2_%D8%A2%DB%8C%D8%AA%D9%85_%D9%87%D8%A7%DB%8C_%D8%AC%D8%A7%D8%AF%D9%88%DB%8C%DB%8C_%D8%A8%D9%87%D8%A8%D9%88%D8%AF_AC_%D8%A7%D8%B3%D8%AA%D9%81%D8%A7%D8%AF%D9%87_%DA%A9%D9%86%DB%8C%D8%AF\" >2  \u0627\u0632 \u0622\u06cc\u062a\u0645 \u0647\u0627\u06cc \u062c\u0627\u062f\u0648\u06cc\u06cc \u0628\u0647\u0628\u0648\u062f AC \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/nabfollower.com\/blog\/dungeons-dragons-dnd-ways-to-increase-armor-class-ac\/#1_%D9%86%DA%98%D8%A7%D8%AF%D9%87%D8%A7_%D9%88_%D8%B2%DB%8C%D8%B1_%DA%A9%D9%84%D8%A7%D8%B3_%D9%87%D8%A7%DB%8C%DB%8C_%D8%B1%D8%A7_%D8%AF%D8%B1_%D9%86%D8%B8%D8%B1_%D8%A8%DA%AF%DB%8C%D8%B1%DB%8C%D8%AF_%DA%A9%D9%87_AC_%D8%B1%D8%A7_%D8%A8%D9%87%D8%A8%D9%88%D8%AF_%D9%85%DB%8C_%D8%A8%D8%AE%D8%B4%D9%86%D8%AF\" >1  \u0646\u0698\u0627\u062f\u0647\u0627 \u0648 \u0632\u06cc\u0631 \u06a9\u0644\u0627\u0633 \u0647\u0627\u06cc\u06cc \u0631\u0627 \u062f\u0631 \u0646\u0638\u0631 \u0628\u06af\u06cc\u0631\u06cc\u062f \u06a9\u0647 AC \u0631\u0627 \u0628\u0647\u0628\u0648\u062f \u0645\u06cc \u0628\u062e\u0634\u0646\u062f<\/a><\/li><\/ul><\/nav><\/div>\n<h2 id=\"improve-your-dexterity\"><span class=\"ez-toc-section\" id=\"6_%D9%85%D9%87%D8%A7%D8%B1%D8%AA_%D8%AE%D9%88%D8%AF_%D8%B1%D8%A7_%D8%A8%D9%87%D8%A8%D9%88%D8%AF_%D8%A8%D8%AE%D8%B4%DB%8C%D8%AF\"><\/span> <span class=\"item-num\">6 <\/span> <span>\u0645\u0647\u0627\u0631\u062a \u062e\u0648\u062f \u0631\u0627 \u0628\u0647\u0628\u0648\u062f \u0628\u062e\u0634\u06cc\u062f<\/span> <span class=\"ez-toc-section-end\"><\/span><\/h2>\n<div class=\"body-img landscape\">\n<div class=\"responsive-img image-expandable img-article-item\" style=\"padding-bottom:50%\" data-img-url=\"https:\/\/nabfollower.com\/blog\/wp-content\/uploads\/2023\/03\/6-\u0631\u0627\u0647-\u0628\u0631\u0627\u06cc-\u0627\u0641\u0632\u0627\u06cc\u0634-\u06a9\u0644\u0627\u0633-\u0632\u0631\u0647\u06cc-\u062e\u0648\u062f-\u062f\u0631-DD.jpg\" data-modal-id=\"single-image-modal\" data-modal-container-id=\"single-image-modal-container\" data-img-caption=\"&quot;Drizzt Do&amp;#39;Urden art by Wizards of the Coast&quot;\">\n<figure> <picture> <!--[if IE 9]> <video style=\"display: none;\"><![endif]--><source media=\"(min-width: 1024px)\"  data-\/><source media=\"(min-width: 768px)\"  data-\/><source media=\"(min-width: 481px)\"  data-\/><source media=\"(min-width: 0px)\"  data-\/><!--[if IE 9]><\/video><![endif]--> <\/picture><figcaption class=\"body-img-caption\">\u0647\u0646\u0631 Drizzt Do&#8217;Urden \u062a\u0648\u0633\u0637 Wizards of the Coast<\/figcaption><\/figure>\n<\/p><\/div>\n<\/p><\/div>\n<p>  \u0634\u0627\u06cc\u062f \u0633\u0627\u062f\u0647 \u062a\u0631\u06cc\u0646 \u0631\u0627\u0647 \u0628\u0631\u0627\u06cc \u0628\u0647\u0628\u0648\u062f AC \u062a\u0642\u0631\u06cc\u0628\u0627\u064b \u0647\u0631 \u0634\u062e\u0635\u06cc\u062a\u06cc\u060c \u0628\u0647\u0628\u0648\u062f \u0627\u0645\u062a\u06cc\u0627\u0632 \u062a\u0648\u0627\u0646\u0627\u06cc\u06cc \u0645\u0647\u0627\u0631\u062a \u0634\u0645\u0627 \u0628\u0627\u0634\u062f.  \u0628\u0631\u0627\u06cc \u06a9\u0633\u0627\u0646\u06cc \u06a9\u0647 \u0632\u0631\u0647 \u0646\u0645\u06cc \u067e\u0648\u0634\u0646\u062f \u06cc\u0627 \u0628\u0631\u0627\u06cc \u06a9\u0633\u0627\u0646\u06cc \u06a9\u0647 \u0627\u0632 \u0632\u0631\u0647 \u0633\u0628\u06a9 \u06cc\u0627 \u0645\u062a\u0648\u0633\u0637 \u200b\u200b\u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc \u06a9\u0646\u0646\u062f\u060c \u06cc\u06a9 \u0634\u062e\u0635\u06cc\u062a \u0627\u0635\u0644\u0627\u062d \u06a9\u0646\u0646\u062f\u0647 \u0627\u0645\u062a\u06cc\u0627\u0632 \u0645\u0647\u0627\u0631\u062a \u0645\u0647\u0627\u0631\u062a \u062e\u0648\u062f \u0631\u0627 \u0628\u0647 AC \u062e\u0648\u062f \u0627\u0636\u0627\u0641\u0647 \u0645\u06cc \u06a9\u0646\u062f.  \u0627\u06cc\u0646 \u0628\u062f\u0627\u0646 \u0645\u0639\u0646\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0637\u06cc\u0641 \u06af\u0633\u062a\u0631\u062f\u0647 \u0627\u06cc \u0627\u0632 \u06a9\u0627\u0631\u0627\u06a9\u062a\u0631\u0647\u0627 \u0645\u06cc \u062a\u0648\u0627\u0646\u0646\u062f \u0628\u0647 \u0637\u0648\u0631 \u0642\u0627\u0628\u0644 \u0627\u0639\u062a\u0645\u0627\u062f\u06cc AC \u062e\u0648\u062f \u0631\u0627 \u0628\u0627 \u0628\u0647\u0628\u0648\u062f \u0645\u0647\u0627\u0631\u062a \u062e\u0648\u062f \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u0628\u062e\u0634\u06cc \u0627\u0632 \u0627\u0631\u062a\u0642\u0627\u0621 \u0633\u0637\u062d \u0628\u0647\u0628\u0648\u062f \u062f\u0647\u0646\u062f.<\/p>\n<p>\u062a\u0648\u062c\u0647 \u0628\u0647 \u0627\u06cc\u0646 \u0646\u06a9\u062a\u0647 \u0645\u0647\u0645 \u0627\u0633\u062a \u06a9\u0647 \u0634\u062e\u0635\u06cc\u062a\u200c\u0647\u0627\u06cc\u06cc \u06a9\u0647 \u0627\u0632 \u0632\u0631\u0647 \u0645\u062a\u0648\u0633\u0637 \u200b\u200b\u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f \u0641\u0642\u0637 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0627\u06cc\u0646 \u0627\u0635\u0644\u0627\u062d\u200c\u06a9\u0646\u0646\u062f\u0647 \u0631\u0627 \u0628\u0647 \u062d\u062f\u0627\u06a9\u062b\u0631 2+ \u0627\u0636\u0627\u0641\u0647 \u06a9\u0646\u0646\u062f\u060c \u0645\u06af\u0631 \u0627\u06cc\u0646\u06a9\u0647 \u0634\u0627\u0647\u06a9\u0627\u0631 Medium Armor Master \u0631\u0627 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u0646\u062f \u06a9\u0647 \u062f\u0631 \u0639\u0648\u0636 \u0627\u06cc\u0646 \u06a9\u0644\u0627\u0647 \u0631\u0627 \u0628\u0647 +3 \u0628\u0631\u0633\u0627\u0646\u062f.  \u0627\u06cc\u0646 \u06af\u0632\u06cc\u0646\u0647\u060c \u0645\u062a\u0623\u0633\u0641\u0627\u0646\u0647\u060c \u0645\u0631\u0628\u0648\u0637 \u0628\u0647 \u06a9\u0633\u0627\u0646\u06cc \u0646\u06cc\u0633\u062a \u06a9\u0647 \u0627\u0632 \u0632\u0631\u0647\u200c\u0647\u0627\u06cc \u0633\u0646\u06af\u06cc\u0646 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f\u060c \u0632\u06cc\u0631\u0627 \u0634\u062e\u0635\u06cc\u062a\u200c\u0647\u0627\u06cc\u06cc \u06a9\u0647 \u0627\u0632 \u0686\u0646\u06cc\u0646 \u0632\u0631\u0647\u200c\u0647\u0627\u06cc\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f\u060c \u0646\u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0627\u0635\u0644\u0627\u062d\u200c\u06a9\u0646\u0646\u062f\u0647 \u0645\u0647\u0627\u0631\u062a \u062e\u0648\u062f \u0631\u0627 \u0628\u0647 \u06a9\u0644\u0627\u0633 \u0632\u0631\u0647 \u062e\u0648\u062f \u0627\u0636\u0627\u0641\u0647 \u06a9\u0646\u0646\u062f.<\/p>\n<p><!-- Zone: every entry repeatable. --><\/p>\n<h2 id=\"upgrade-your-armor\"><span class=\"ez-toc-section\" id=\"5_%D8%B2%D8%B1%D9%87_%D8%AE%D9%88%D8%AF_%D8%B1%D8%A7_%D8%A7%D8%B1%D8%AA%D9%82%D8%A7_%D8%AF%D9%87%DB%8C%D8%AF\"><\/span> <span class=\"item-num\">5 <\/span> <span>\u0632\u0631\u0647 \u062e\u0648\u062f \u0631\u0627 \u0627\u0631\u062a\u0642\u0627 \u062f\u0647\u06cc\u062f<\/span> <span class=\"ez-toc-section-end\"><\/span><\/h2>\n<div class=\"body-img landscape\">\n<div class=\"responsive-img image-expandable img-article-item\" style=\"padding-bottom:50%\" data-img-url=\"https:\/\/nabfollower.com\/blog\/wp-content\/uploads\/2023\/03\/6-\u0631\u0627\u0647-\u0628\u0631\u0627\u06cc-\u0627\u0641\u0632\u0627\u06cc\u0634-\u06a9\u0644\u0627\u0633-\u0632\u0631\u0647\u06cc-\u062e\u0648\u062f-\u062f\u0631-DD.jpeg\" data-modal-id=\"single-image-modal\" data-modal-container-id=\"single-image-modal-container\" data-img-caption=\"&quot;Armorer Artificers from Tasha&amp;#39;s Cauldron of Everything by Brian Valeza&quot;\">\n<figure> <picture> <!--[if IE 9]> <video style=\"display: none;\"><![endif]--><source media=\"(min-width: 1024px)\"  data-\/><source media=\"(min-width: 768px)\"  data-\/><source media=\"(min-width: 481px)\"  data-\/><source media=\"(min-width: 0px)\"  data-\/><!--[if IE 9]><\/video><![endif]--><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"600\" class=\"lazyload\" alt=\"\u062f\u0648 \u0632\u0631\u0647 \u067e\u0648\u0634 \u062f\u0631 \u062d\u0627\u0644 \u0645\u0628\u0627\u0631\u0632\u0647 \u0628\u0627 \u06af\u0631\u0648\u0647\u06cc \u0627\u0632 \u06af\u0646\u0648\u0644 \u0647\u0627.\" src=\"https:\/\/nabfollower.com\/blog\/wp-content\/uploads\/2023\/03\/6-\u0631\u0627\u0647-\u0628\u0631\u0627\u06cc-\u0627\u0641\u0632\u0627\u06cc\u0634-\u06a9\u0644\u0627\u0633-\u0632\u0631\u0647\u06cc-\u062e\u0648\u062f-\u062f\u0631-DD.jpeg\" title=\"\"> <\/picture><figcaption class=\"body-img-caption\">Armorer Artificers \u0627\u0632 Tasha&#8217;s Cauldron of Everything \u0627\u062b\u0631 \u0628\u0631\u0627\u06cc\u0627\u0646 \u0648\u0627\u0644\u0632\u0627<\/figcaption><\/figure>\n<\/p><\/div>\n<\/p><\/div>\n<p>  \u0627\u0632 \u0622\u0646\u062c\u0627\u06cc\u06cc \u06a9\u0647 \u06cc\u06a9\u06cc \u0627\u0632 \u0631\u0627\u06cc\u062c\u200c\u062a\u0631\u06cc\u0646 \u0645\u0646\u0627\u0628\u0639 \u0628\u0647\u0628\u0648\u062f AC \u0627\u0632 \u0632\u0631\u0647 \u06cc\u06a9 \u0634\u062e\u0635\u06cc\u062a \u0627\u0633\u062a\u060c \u0628\u0647 \u062f\u0633\u062a \u0622\u0648\u0631\u062f\u0646 \u0632\u0631\u0647 \u0628\u0647\u062a\u0631 \u06cc\u0627 \u0627\u0631\u062a\u0642\u0627\u0621 \u0632\u0631\u0647 \u06cc\u06a9 \u06a9\u0627\u0631\u0627\u06a9\u062a\u0631 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0648\u0633\u06cc\u0644\u0647\u200c\u0627\u06cc \u0633\u0627\u062f\u0647 \u0628\u0631\u0627\u06cc \u0628\u0647\u0628\u0648\u062f AC \u0628\u0627\u0634\u062f.  \u0634\u062e\u0635\u06cc\u062a\u200c\u0647\u0627\u06cc\u06cc \u06a9\u0647 \u062f\u0631 \u0632\u0631\u0647\u200c\u0647\u0627\u06cc \u0633\u0646\u06af\u06cc\u0646 \u0645\u0647\u0627\u0631\u062a \u062f\u0627\u0631\u0646\u062f\u060c \u0627\u063a\u0644\u0628 \u0628\u0627 \u067e\u0633\u062a \u0632\u0646\u062c\u06cc\u0631\u0647\u200c\u0627\u06cc \u0634\u0631\u0648\u0639 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f\u060c \u0628\u0646\u0627\u0628\u0631\u0627\u06cc\u0646 \u062f\u0633\u062a\u06cc\u0627\u0628\u06cc \u0628\u0647 \u0635\u0641\u062d\u0647 \u06a9\u0627\u0645\u0644 \u0628\u0631\u062a\u0631 \u0627\u063a\u0644\u0628 \u06af\u0627\u0645\u06cc \u0639\u0627\u0644\u06cc \u0628\u0631\u0627\u06cc \u062f\u0631\u06cc\u0627\u0641\u062a AC \u0628\u0627\u0644\u0627\u062a\u0631 \u0627\u0633\u062a.  \u0628\u0647 \u0637\u0648\u0631 \u0645\u0634\u0627\u0628\u0647\u060c \u0628\u0631\u0627\u06cc \u06a9\u0633\u0627\u0646\u06cc \u06a9\u0647 \u0627\u0632 \u0632\u0631\u0647 \u0633\u0628\u06a9 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc \u06a9\u0646\u0646\u062f\u060c \u062a\u063a\u06cc\u06cc\u0631 \u0627\u0632 \u0686\u0631\u0645 \u0628\u0647 \u0686\u0631\u0645 \u0645\u06cc\u062e \u062f\u0627\u0631 \u0627\u0631\u062a\u0642\u0627\u0621 \u0645\u0642\u0631\u0648\u0646 \u0628\u0647 \u0635\u0631\u0641\u0647 \u0648 \u0627\u0631\u0632\u0634\u0645\u0646\u062f\u06cc \u0627\u0633\u062a.<\/p>\n<p><span class=\"related-single\">\u0645\u0631\u062a\u0628\u0637: \u0628\u0647\u062a\u0631\u06cc\u0646 \u0627\u0646\u0648\u0627\u0639 \u0632\u0631\u0647 \u062f\u0631 \u0633\u06cc\u0627\u0647 \u0686\u0627\u0644 \u0647\u0627 \u0648 \u0627\u0698\u062f\u0647\u0627<\/span><\/p>\n<p>\u0647\u0646\u06af\u0627\u0645\u06cc \u06a9\u0647 \u06cc\u06a9 \u0634\u062e\u0635\u06cc\u062a \u0628\u0647 \u0646\u0648\u0639 \u0632\u0631\u0647 \u0628\u0647\u06cc\u0646\u0647 \u062e\u0648\u062f \u0645\u062c\u0647\u0632 \u0634\u062f\u060c \u0645\u0633\u06cc\u0631 \u0631\u0648\u0634\u0646 \u0628\u0631\u0627\u06cc \u0628\u0647 \u062f\u0633\u062a \u0622\u0648\u0631\u062f\u0646 \u0632\u0631\u0647 \u062d\u062a\u06cc \u0628\u0647\u062a\u0631 \u0627\u06cc\u0646 \u0627\u0633\u062a \u06a9\u0647 \u0633\u0639\u06cc \u06a9\u0646\u06cc\u062f \u0632\u0631\u0647 \u0647\u0627\u06cc +1\u060c +2 \u06cc\u0627 +3 \u0627\u0632 \u0622\u0646 \u0646\u0648\u0639 \u0631\u0627 \u0628\u062f\u0633\u062a \u0622\u0648\u0631\u06cc\u062f.  \u0628\u0627 \u0627\u0631\u0627\u0626\u0647 \u06cc\u06a9 \u062c\u0627\u06cc\u0632\u0647 \u0627\u0636\u0627\u0641\u06cc AC \u0627\u0632 \u062a\u0639\u062f\u0627\u062f \u0645\u0631\u0628\u0648\u0637\u0647\u060c \u0627\u06cc\u0646 \u0627\u0634\u06a9\u0627\u0644 \u0628\u0631\u062a\u0631 \u0632\u0631\u0647 \u0627\u0632 \u0646\u0638\u0631 \u0641\u0646\u06cc \u062c\u0627\u062f\u0648\u06cc\u06cc \u0647\u0633\u062a\u0646\u062f.  \u062f\u0633\u062a\u0631\u0633\u06cc \u0628\u0647 \u0686\u0646\u06cc\u0646 \u0632\u0631\u0647\u200c\u0647\u0627\u06cc\u06cc \u0627\u0632 DM \u062a\u0627 DM \u0628\u0633\u06cc\u0627\u0631 \u0645\u062a\u063a\u06cc\u0631 \u0627\u0633\u062a\u060c \u0632\u06cc\u0631\u0627 \u0628\u0631\u062e\u06cc \u0628\u0647 \u0628\u0627\u0632\u06cc\u06a9\u0646\u0627\u0646 \u0627\u06cc\u0646 \u0627\u0645\u06a9\u0627\u0646 \u0631\u0627 \u0645\u06cc\u200c\u062f\u0647\u0646\u062f \u06a9\u0647 \u0628\u0631\u0627\u06cc \u0627\u0631\u062a\u0642\u0627\u06cc \u0632\u0631\u0647\u200c\u0647\u0627\u06cc \u062e\u0648\u062f \u0628\u0647 \u0627\u06cc\u0646 \u0641\u0631\u0645\u200c\u0647\u0627\u06cc \u0628\u0631\u062a\u0631\u060c \u0637\u0644\u0627 \u0628\u067e\u0631\u062f\u0627\u0632\u0646\u062f\u060c \u062f\u0631 \u062d\u0627\u0644\u06cc \u06a9\u0647 \u0628\u0631\u062e\u06cc \u062f\u06cc\u06af\u0631 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0632\u0631\u0647\u200c\u0647\u0627\u06cc +1\u060c +2 \u0648 +3 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u0646\u062f \u06a9\u0647 \u0646\u0627\u062f\u0631 \u0627\u0633\u062a. \u0628\u0631\u0627\u06cc.<\/p>\n<p><!-- Zone: every entry repeatable. --><\/p>\n<h2 id=\"gain-the-defense-fighting-style\"><span class=\"ez-toc-section\" id=\"4_%D8%B3%D8%A8%DA%A9_%D9%85%D8%A8%D8%A7%D8%B1%D8%B2%D9%87_%D8%AF%D9%81%D8%A7%D8%B9%DB%8C_%D8%B1%D8%A7_%D8%A8%D9%87_%D8%AF%D8%B3%D8%AA_%D8%A2%D9%88%D8%B1%DB%8C%D8%AF\"><\/span> <span class=\"item-num\">4 <\/span> <span>\u0633\u0628\u06a9 \u0645\u0628\u0627\u0631\u0632\u0647 \u062f\u0641\u0627\u0639\u06cc \u0631\u0627 \u0628\u0647 \u062f\u0633\u062a \u0622\u0648\u0631\u06cc\u062f<\/span> <span class=\"ez-toc-section-end\"><\/span><\/h2>\n<div class=\"body-img landscape\">\n<div class=\"responsive-img image-expandable img-article-item\" style=\"padding-bottom:50%\" data-img-url=\"https:\/\/nabfollower.com\/blog\/wp-content\/uploads\/2023\/03\/1678700707_76_6-\u0631\u0627\u0647-\u0628\u0631\u0627\u06cc-\u0627\u0641\u0632\u0627\u06cc\u0634-\u06a9\u0644\u0627\u0633-\u0632\u0631\u0647\u06cc-\u062e\u0648\u062f-\u062f\u0631-DD.jpg\" data-modal-id=\"single-image-modal\" data-modal-container-id=\"single-image-modal-container\" data-img-caption=\"&quot;Dungeons &amp;amp; Dragons Player&amp;#39;s Handbook by Wizards of the Coast&quot;\">\n<figure> <picture> <!--[if IE 9]> <video style=\"display: none;\"><![endif]--><source media=\"(min-width: 1024px)\"  data-\/><source media=\"(min-width: 768px)\"  data-\/><source media=\"(min-width: 481px)\"  data-\/><source media=\"(min-width: 0px)\"  data-\/><!--[if IE 9]><\/video><![endif]--><img loading=\"lazy\" decoding=\"async\" width=\"1400\" height=\"700\" class=\"lazyload\" alt=\"\u067e\u0631\u062a\u0631\u0647 \u062c\u0646\u06af\u0646\u062f\u0647 D&#038;D.\" src=\"https:\/\/nabfollower.com\/blog\/wp-content\/uploads\/2023\/03\/1678700707_76_6-\u0631\u0627\u0647-\u0628\u0631\u0627\u06cc-\u0627\u0641\u0632\u0627\u06cc\u0634-\u06a9\u0644\u0627\u0633-\u0632\u0631\u0647\u06cc-\u062e\u0648\u062f-\u062f\u0631-DD.jpg\" title=\"\"> <\/picture><figcaption class=\"body-img-caption\">\u0631\u0627\u0647\u0646\u0645\u0627\u06cc \u0628\u0627\u0632\u06cc Dungeons &#038; Dragons \u062a\u0648\u0633\u0637 Wizards of the Coast<\/figcaption><\/figure>\n<\/p><\/div>\n<\/p><\/div>\n<p>  \u06cc\u06a9\u06cc \u0627\u0632 \u0648\u06cc\u0698\u06af\u06cc \u0647\u0627\u06cc\u06cc \u06a9\u0647 \u062f\u0631 \u0628\u06cc\u0646 \u06a9\u0644\u0627\u0633 \u0647\u0627\u06cc \u0631\u0632\u0645\u06cc \u0645\u062e\u062a\u0644\u0641 \u0645\u0627\u0646\u0646\u062f \u0645\u0628\u0627\u0631\u0632\u0627\u0646 \u0648 \u067e\u0627\u0644\u0627\u062f\u06cc\u0646 \u0647\u0627 \u06cc\u0627\u0641\u062a \u0645\u06cc \u0634\u0648\u062f\u060c \u062a\u0648\u0627\u0646\u0627\u06cc\u06cc \u0628\u0647 \u062f\u0633\u062a \u0622\u0648\u0631\u062f\u0646 \u0633\u0628\u06a9 \u0645\u0628\u0627\u0631\u0632\u0647 \u0627\u0633\u062a.  \u0633\u0628\u06a9\u200c\u0647\u0627\u06cc \u0645\u0628\u0627\u0631\u0632\u0647 \u0627\u0632 \u0645\u0632\u0627\u06cc\u0627\u06cc \u0627\u062d\u062a\u0645\u0627\u0644\u06cc \u0647\u0633\u062a\u0646\u062f \u06a9\u0647 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0647\u0631 \u0686\u06cc\u0632\u06cc \u0627\u0632 \u0627\u0645\u062a\u06cc\u0627\u0632 \u062a\u0627 \u0636\u0631\u0628\u0647 \u0632\u062f\u0646 \u0628\u0627 \u0646\u0648\u0639 \u062e\u0627\u0635\u06cc \u0627\u0632 \u0633\u0644\u0627\u062d \u06cc\u0627 \u062d\u062a\u06cc \u062f\u0633\u062a\u0631\u0633\u06cc \u0628\u0647 \u06a9\u0627\u0646\u062a\u0631\u06cc\u067e\u200c\u0647\u0627 \u0631\u0627 \u062f\u0631 \u0645\u0648\u0631\u062f Paladins \u0648 Rangers \u0627\u0631\u0627\u0626\u0647 \u062f\u0647\u0646\u062f.  \u062f\u0631 \u062d\u0627\u0644\u06cc \u06a9\u0647 \u06cc\u06a9\u06cc \u0627\u0632 \u0633\u0627\u062f\u0647\u200c\u062a\u0631\u06cc\u0646 \u0633\u0628\u06a9\u200c\u0647\u0627\u06cc \u0645\u0628\u0627\u0631\u0632\u0647 \u0627\u0633\u062a\u060c \u0633\u0628\u06a9 Defence Fighting \u0628\u06cc\u0627\u0646 \u0645\u06cc\u200c\u06a9\u0646\u062f \u06a9\u0647 \u062a\u0627 \u0632\u0645\u0627\u0646\u06cc \u06a9\u0647 \u0634\u062e\u0635\u06cc\u062a \u062f\u0631 \u062f\u0633\u062a \u0632\u0631\u0647 \u067e\u0648\u0634 \u0628\u0627\u0634\u062f\u060c \u0622\u0646\u0647\u0627 +1 \u0628\u0647 AC \u062e\u0648\u062f \u0645\u06cc\u200c\u0628\u0631\u0646\u062f.<\/p>\n<p>\u062f\u0631 \u062d\u0627\u0644\u06cc \u06a9\u0647 \u0627\u06cc\u0646 \u0633\u0628\u06a9 \u0645\u0628\u0627\u0631\u0632\u0647 \u0631\u0627 \u0645\u06cc \u062a\u0648\u0627\u0646 \u0628\u0647 \u0631\u0627\u062d\u062a\u06cc \u0628\u0631\u0627\u06cc \u0627\u06a9\u062b\u0631 \u0634\u062e\u0635\u06cc\u062a \u0647\u0627\u06cc \u0631\u0632\u0645\u06cc \u0628\u0647 \u062f\u0633\u062a \u0622\u0648\u0631\u062f\u060c \u0628\u0647 \u0644\u0637\u0641 \u0634\u0627\u0647\u06a9\u0627\u0631 Fighting Initiate\u060c \u0634\u062e\u0635\u06cc\u062a\u06cc \u0627\u0632 <em>\u0647\u0631 <\/em>\u06a9\u0644\u0627\u0633 \u062a\u0648\u0627\u0646\u0627\u06cc\u06cc \u06cc\u0627\u062f\u06af\u06cc\u0631\u06cc \u0633\u0628\u06a9 \u0645\u0628\u0627\u0631\u0632\u0647 \u0631\u0627 \u062f\u0627\u0631\u062f.  \u0627\u06cc\u0646 \u0628\u062f\u0627\u0646 \u0645\u0639\u0646\u0627\u0633\u062a \u06a9\u0647 \u0627\u06af\u0631 \u0634\u062e\u0635\u06cc\u062a\u06cc \u0628\u062e\u0648\u0627\u0647\u062f \u0631\u0648\u06cc \u0628\u0647\u0628\u0648\u062f AC \u062e\u0648\u062f \u062a\u0645\u0631\u06a9\u0632 \u06a9\u0646\u062f\u060c \u0627\u0633\u0627\u0633\u0627\u064b \u0645\u06cc \u062a\u0648\u0627\u0646\u062f \u06cc\u06a9 \u0634\u0627\u0647\u06a9\u0627\u0631 \u0628\u0631\u0627\u06cc \u0628\u0647\u0628\u0648\u062f AC \u062e\u0648\u062f \u0628\u0627 +1 \u062e\u0631\u062c \u06a9\u0646\u062f.<\/p>\n<p><!-- Zone: every entry repeatable. --><\/p>\n<h2 id=\"use-a-shield\"><span class=\"ez-toc-section\" id=\"3_%D8%A7%D8%B2_A_Shield_%D8%A7%D8%B3%D8%AA%D9%81%D8%A7%D8%AF%D9%87_%DA%A9%D9%86%DB%8C%D8%AF\"><\/span> <span class=\"item-num\">3 <\/span> <span>\u0627\u0632 A Shield \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f<\/span> <span class=\"ez-toc-section-end\"><\/span><\/h2>\n<div class=\"body-img landscape\">\n<div class=\"responsive-img image-expandable img-article-item\" style=\"padding-bottom:50%\" data-img-url=\"https:\/\/nabfollower.com\/blog\/wp-content\/uploads\/2023\/03\/1678700707_86_6-\u0631\u0627\u0647-\u0628\u0631\u0627\u06cc-\u0627\u0641\u0632\u0627\u06cc\u0634-\u06a9\u0644\u0627\u0633-\u0632\u0631\u0647\u06cc-\u062e\u0648\u062f-\u062f\u0631-DD.jpg\" data-modal-id=\"single-image-modal\" data-modal-container-id=\"single-image-modal-container\" data-img-caption=\"&quot;Nadaar, Selfless Paladin by Aaron Miller&quot;\">\n<figure> <picture> <!--[if IE 9]> <video style=\"display: none;\"><![endif]--><source media=\"(min-width: 1024px)\"  data-\/><source media=\"(min-width: 768px)\"  data-\/><source media=\"(min-width: 481px)\"  data-\/><source media=\"(min-width: 0px)\"  data-\/><!--[if IE 9]><\/video><![endif]--><img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"1000\" class=\"lazyload\" alt=\"\u0646\u0627\u062f\u0627\u0631 \u067e\u0627\u0644\u0627\u062f\u06cc\u0646 \u0627\u0698\u062f\u0647\u0627 \u062f\u0631 d&#038;d\" src=\"https:\/\/nabfollower.com\/blog\/wp-content\/uploads\/2023\/03\/1678700707_86_6-\u0631\u0627\u0647-\u0628\u0631\u0627\u06cc-\u0627\u0641\u0632\u0627\u06cc\u0634-\u06a9\u0644\u0627\u0633-\u0632\u0631\u0647\u06cc-\u062e\u0648\u062f-\u062f\u0631-DD.jpg\" title=\"\"> <\/picture><figcaption class=\"body-img-caption\">\u0646\u0627\u062f\u0627\u0631\u060c \u067e\u0627\u0644\u0627\u062f\u06cc\u0646 \u0628\u06cc \u062e\u0648\u062f \u0627\u062b\u0631 \u0622\u0631\u0648\u0646 \u0645\u06cc\u0644\u0631<\/figcaption><\/figure>\n<\/p><\/div>\n<\/p><\/div>\n<p>\u0634\u06cc\u0644\u062f\u0647\u0627 \u062a\u062c\u0647\u06cc\u0632\u0627\u062a \u0628\u0633\u06cc\u0627\u0631 \u0645\u0641\u06cc\u062f\u06cc \u0628\u0631\u0627\u06cc \u0647\u0631 \u06a9\u0633\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0645\u06cc\u200c\u062e\u0648\u0627\u0647\u062f \u0628\u0647 \u0631\u0627\u062d\u062a\u06cc \u0628\u0627 AC \u0628\u0631\u062e\u0648\u0631\u062f \u06a9\u0646\u062f.  \u0622\u0646\u0647\u0627 \u062f\u0631 \u0635\u0648\u0631\u062a \u062a\u062c\u0647\u06cc\u0632 \u06cc\u06a9 AC \u0645\u0633\u0637\u062d +2 \u0631\u0627 \u0628\u0647 \u0628\u0627\u0631\u06af\u06cc\u0631\u06cc \u0634\u0645\u0627 \u0627\u0636\u0627\u0641\u0647 \u0645\u06cc \u06a9\u0646\u0646\u062f.  \u0645\u062d\u062f\u0648\u062f\u06cc\u062a \u0627\u0635\u0644\u06cc \u0627\u06cc\u0646 \u0627\u0633\u062a \u06a9\u0647 \u062f\u0631 \u062d\u06cc\u0646 \u0627\u0646\u062c\u0627\u0645 \u0627\u06cc\u0646 \u06a9\u0627\u0631 \u0641\u0642\u0637 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u0627\u0632 \u0648\u0633\u0627\u06cc\u0644 \u0648 \u0633\u0644\u0627\u062d\u200c\u0647\u0627\u06cc \u06cc\u06a9 \u062f\u0633\u062a \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f\u060c \u06a9\u0647 \u0628\u0627\u0639\u062b \u0645\u06cc\u200c\u0634\u0648\u062f \u0627\u06cc\u0646 \u06cc\u06a9 \u0645\u0639\u0627\u0645\u0644\u0647 \u0645\u0633\u062a\u0642\u06cc\u0645 \u0628\u0627 \u0622\u0633\u06cc\u0628 \u062f\u0648 \u062f\u0633\u062a \u0648 AC \u0628\u06cc\u0634\u062a\u0631 \u0628\u0627\u0634\u062f.  \u062c\u0627\u062f\u0648\u06cc\u06cc \u06a9\u0647 \u0628\u0647 \u062f\u0631\u0633\u062a\u06cc \u0633\u0627\u062e\u062a\u0647 \u0634\u062f\u0647 \u0628\u0627\u0634\u062f \u0645\u06cc \u062a\u0648\u0627\u0646\u062f \u0627\u0632 \u0627\u06cc\u0646 \u0645\u0632\u06cc\u062a \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u062f\u060c \u0632\u06cc\u0631\u0627 \u062c\u0627\u062f\u0648 \u06cc\u06a9 \u0639\u0645\u0644 \u06cc\u06a9 \u062f\u0633\u062a \u0627\u0633\u062a.  \u0628\u0647\u062a\u0631\u06cc\u0646 \u0627\u0632 \u0647\u0645\u0647\u060c \u0627\u06cc\u0646 \u0627\u0645\u06a9\u0627\u0646 \u0631\u0627 \u0628\u0631\u0627\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0633\u067e\u0631\u0647\u0627\u06cc \u062c\u0627\u062f\u0648\u06cc\u06cc \u0628\u0627\u0632 \u0645\u06cc \u06a9\u0646\u062f.<\/p>\n<p>\u0633\u062e\u062a \u062a\u0631\u06cc\u0646 \u0642\u0633\u0645\u062a \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0627\u06cc\u0646 \u0645\u0632\u06cc\u062a \u0627\u06cc\u0646 \u0627\u0633\u062a \u06a9\u0647 \u0631\u0627\u0647 \u0647\u0627\u06cc \u0632\u06cc\u0627\u062f\u06cc \u0628\u0631\u0627\u06cc \u0645\u0647\u0627\u0631\u062a \u062f\u0627\u0634\u062a\u0646 \u062f\u0631 \u06cc\u06a9 \u0633\u067e\u0631 \u0648\u062c\u0648\u062f \u0646\u062f\u0627\u0631\u062f.  \u06a9\u0644\u0627\u0633 \u0647\u0627\u06cc \u062e\u0627\u0635\u06cc \u0628\u0627 \u0645\u0647\u0627\u0631\u062a \u0634\u06cc\u0644\u062f \u0634\u0631\u0648\u0639 \u062e\u0648\u0627\u0647\u0646\u062f \u0634\u062f.  \u0647\u0631 \u06a9\u0644\u0627\u0633 \u062f\u06cc\u06af\u0631\u06cc \u0641\u0642\u0637 \u062f\u0648 \u06af\u0632\u06cc\u0646\u0647 \u062e\u0648\u0627\u0647\u062f \u062f\u0627\u0634\u062a: Feats \u0648 Multiclassing.  \u0634\u0627\u0647\u06a9\u0627\u0631 Moderately Armored \u0628\u0647 \u0632\u0631\u0647\u200c\u0647\u0627\u06cc \u0645\u062a\u0648\u0633\u0637 \u200b\u200b\u0648 \u0633\u067e\u0631 \u0645\u0647\u0627\u0631\u062a \u0645\u06cc\u200c\u062f\u0647\u062f\u060c \u0627\u06af\u0631\u0686\u0647 \u0627\u0628\u062a\u062f\u0627 \u0628\u0647 \u0645\u0647\u0627\u0631\u062a \u0632\u0631\u0647 \u0633\u0628\u06a9 \u0646\u06cc\u0627\u0632 \u062f\u0627\u0631\u062f.  Xanathar&#8217;s Guide to Everything \u0633\u06cc\u0633\u062a\u0645\u06cc \u0631\u0627 \u0628\u0631\u0627\u06cc \u06cc\u0627\u062f\u06af\u06cc\u0631\u06cc \u06cc\u06a9 \u0627\u0628\u0632\u0627\u0631 \u062c\u062f\u06cc\u062f \u06cc\u0627 \u0645\u0647\u0627\u0631\u062a \u0632\u0628\u0627\u0646 \u062f\u0631 \u0628\u062e\u0634 Downtime \u0627\u0631\u0627\u0626\u0647 \u0645\u06cc \u062f\u0647\u062f.  \u0633\u067e\u0631\u0647\u0627 \u062f\u0631 \u0641\u0647\u0631\u0633\u062a PHB &#8220;\u0627\u0628\u0632\u0627\u0631\u0647\u0627&#8221; \u0642\u0631\u0627\u0631 \u0646\u062f\u0627\u0631\u0646\u062f\u060c \u0648 \u0637\u0628\u0642\u0647 \u0628\u0646\u062f\u06cc \u0622\u0646\u0647\u0627 \u0645\u0648\u0636\u0648\u0639\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0645\u0639\u0645\u0648\u0644\u0627\u064b \u0645\u0648\u0631\u062f \u0628\u062d\u062b \u0627\u0633\u062a\u060c \u0628\u0646\u0627\u0628\u0631\u0627\u06cc\u0646 \u0627\u06cc\u0646\u06a9\u0647 \u0622\u06cc\u0627 \u0627\u06cc\u0646 \u06af\u0632\u06cc\u0646\u0647 \u0642\u0627\u0628\u0644 \u0627\u062c\u0631\u0627 \u0627\u0633\u062a \u06cc\u0627 \u0646\u0647\u060c \u0628\u0647 DM \u0634\u0645\u0627 \u0628\u0633\u062a\u06af\u06cc \u062f\u0627\u0631\u062f.<\/p>\n<p><!-- Zone: every entry repeatable. --><\/p>\n<h2 id=\"use-ac-improving-magic-items\"><span class=\"ez-toc-section\" id=\"2_%D8%A7%D8%B2_%D8%A2%DB%8C%D8%AA%D9%85_%D9%87%D8%A7%DB%8C_%D8%AC%D8%A7%D8%AF%D9%88%DB%8C%DB%8C_%D8%A8%D9%87%D8%A8%D9%88%D8%AF_AC_%D8%A7%D8%B3%D8%AA%D9%81%D8%A7%D8%AF%D9%87_%DA%A9%D9%86%DB%8C%D8%AF\"><\/span> <span class=\"item-num\">2 <\/span> <span>\u0627\u0632 \u0622\u06cc\u062a\u0645 \u0647\u0627\u06cc \u062c\u0627\u062f\u0648\u06cc\u06cc \u0628\u0647\u0628\u0648\u062f AC \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f<\/span> <span class=\"ez-toc-section-end\"><\/span><\/h2>\n<div class=\"body-img landscape\">\n<div class=\"responsive-img image-expandable img-article-item\" style=\"padding-bottom:50%\" data-img-url=\"https:\/\/nabfollower.com\/blog\/wp-content\/uploads\/2023\/03\/1678700708_850_6-\u0631\u0627\u0647-\u0628\u0631\u0627\u06cc-\u0627\u0641\u0632\u0627\u06cc\u0634-\u06a9\u0644\u0627\u0633-\u0632\u0631\u0647\u06cc-\u062e\u0648\u062f-\u062f\u0631-DD.jpg\" data-modal-id=\"single-image-modal\" data-modal-container-id=\"single-image-modal-container\" data-img-caption=\"&quot;Sword Coast Adventurer&amp;#39;s Guide Cover Art by Tyler Jacobson&quot;\">\n<figure> <picture> <!--[if IE 9]> <video style=\"display: none;\"><![endif]--><source media=\"(min-width: 1024px)\"  data-\/><source media=\"(min-width: 768px)\"  data-\/><source media=\"(min-width: 481px)\"  data-\/><source media=\"(min-width: 0px)\"  data-\/><!--[if IE 9]><\/video><![endif]--><img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"1000\" class=\"lazyload\" alt=\"\u06af\u0631\u0648\u0647\u06cc \u0627\u0632 \u0645\u0627\u062c\u0631\u0627\u062c\u0648\u06cc\u0627\u0646 \u062f\u0631 D&#038;D \u0628\u0627 \u0627\u0646\u0628\u0648\u0647\u06cc \u0627\u0632 \u062f\u0634\u0645\u0646\u0627\u0646 \u0631\u0648\u0628\u0631\u0648 \u0645\u06cc \u0634\u0648\u0646\u062f\" src=\"https:\/\/nabfollower.com\/blog\/wp-content\/uploads\/2023\/03\/1678700708_850_6-\u0631\u0627\u0647-\u0628\u0631\u0627\u06cc-\u0627\u0641\u0632\u0627\u06cc\u0634-\u06a9\u0644\u0627\u0633-\u0632\u0631\u0647\u06cc-\u062e\u0648\u062f-\u062f\u0631-DD.jpg\" title=\"\"> <\/picture><figcaption class=\"body-img-caption\">\u0647\u0646\u0631 \u062c\u0644\u062f \u06a9\u062a\u0627\u0628 \u0631\u0627\u0647\u0646\u0645\u0627\u06cc \u0645\u0627\u062c\u0631\u0627\u062c\u0648\u06cc\u0627\u0646\u0647 \u0633\u0627\u062d\u0644 \u0634\u0645\u0634\u06cc\u0631 \u0627\u062b\u0631 \u062a\u0627\u06cc\u0644\u0631 \u062c\u0627\u06a9\u0648\u0628\u0633\u0648\u0646<\/figcaption><\/figure>\n<\/p><\/div>\n<\/p><\/div>\n<p>  \u0639\u0644\u0627\u0648\u0647 \u0628\u0631 \u0632\u0631\u0647 \u0634\u0645\u0627\u060c \u062a\u062c\u0647\u06cc\u0632\u0627\u062a \u062f\u06cc\u06af\u0631\u06cc \u0645\u0627\u0646\u0646\u062f \u0622\u06cc\u062a\u0645 \u0647\u0627\u06cc \u062c\u0627\u062f\u0648\u06cc\u06cc \u0646\u06cc\u0632 \u0645\u06cc \u062a\u0648\u0627\u0646\u0646\u062f \u0628\u0631\u0627\u06cc \u0628\u0647\u0628\u0648\u062f AC \u06a9\u0627\u0631\u0627\u06a9\u062a\u0631 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0634\u0648\u0646\u062f.  \u062f\u0631 \u062d\u0627\u0644\u06cc \u06a9\u0647 \u06cc\u06a9 \u0634\u062e\u0635\u06cc\u062a \u0641\u0642\u0637 \u0628\u0647 \u0633\u0647 \u0627\u0633\u0644\u0627\u062a \u0647\u0645\u0627\u0647\u0646\u06af\u06cc \u062f\u0633\u062a\u0631\u0633\u06cc \u062f\u0627\u0631\u062f (\u0628\u0647 \u0627\u0633\u062a\u062b\u0646\u0627\u06cc Artificers)\u060c \u0686\u0646\u062f\u06cc\u0646 \u0622\u06cc\u062a\u0645 \u062c\u0627\u062f\u0648\u06cc\u06cc \u0639\u0627\u0644\u06cc \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u062f \u06a9\u0647 \u0645\u06cc \u062a\u0648\u0627\u0646\u062f \u0628\u0647 \u062a\u0642\u0648\u06cc\u062a \u062f\u0641\u0627\u0639 \u0634\u0645\u0627 \u06a9\u0645\u06a9 \u06a9\u0646\u062f.  \u0627\u0648\u0644\u0627\u064b\u060c Bracers of Defense \u06cc\u06a9 \u0622\u06cc\u062a\u0645 \u062c\u0627\u062f\u0648\u06cc\u06cc \u06a9\u0645\u06cc\u0627\u0628 \u0642\u0627\u0628\u0644 \u062a\u0646\u0638\u06cc\u0645 \u0627\u0633\u062a \u06a9\u0647 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f AC \u06a9\u0627\u0631\u0627\u06a9\u062a\u0631 \u0631\u0627 \u062a\u0627 \u0632\u0645\u0627\u0646\u06cc \u06a9\u0647 \u0632\u0631\u0647 \u0646\u067e\u0648\u0634\u06cc\u062f\u0647 \u0628\u0627\u0634\u062f \u062a\u0627 2+ \u0628\u0647\u0628\u0648\u062f \u0628\u062e\u0634\u062f.<\/p>\n<p><span class=\"related-single\">\u0645\u0637\u0627\u0644\u0628 \u0645\u0631\u062a\u0628\u0637: \u0633\u06cc\u0627\u0647 \u0686\u0627\u0644 \u0647\u0627 \u0648 \u0627\u0698\u062f\u0647\u0627: \u0622\u06cc\u062a\u0645 \u0647\u0627\u06cc \u062c\u0627\u062f\u0648\u06cc\u06cc \u062f\u0633\u062a \u06a9\u0645 \u06af\u0631\u0641\u062a\u0647 \u0634\u062f\u0647 \u06a9\u0647 \u0628\u0647\u062a\u0631 \u0627\u0632 \u0622\u0646 \u0686\u06cc\u0632\u06cc \u0647\u0633\u062a\u0646\u062f \u06a9\u0647 \u0641\u06a9\u0631 \u0645\u06cc \u06a9\u0646\u06cc\u062f<\/span><\/p>\n<p>\u0627\u06cc\u0646 \u0628\u0627\u0639\u062b \u0645\u06cc\u200c\u0634\u0648\u062f \u06a9\u0647 \u0622\u0646\u200c\u0647\u0627 \u0628\u0631\u0627\u06cc \u0634\u062e\u0635\u06cc\u062a\u200c\u0647\u0627\u06cc\u06cc \u0645\u0627\u0646\u0646\u062f \u0631\u0627\u0647\u0628 \u06cc\u0627 \u0628\u0631\u0628\u0631\u06cc\u0646 \u0628\u0627 \u062a\u0648\u0627\u0646\u0627\u06cc\u06cc \u062f\u0641\u0627\u0639\u06cc Unarmored\u060c \u06cc\u0627 \u062c\u0627\u062f\u0648\u06af\u0631 \u06cc\u0627 \u062c\u0627\u062f\u0648\u06af\u0631 \u06a9\u0647 \u0645\u0647\u0627\u0631\u062a \u0632\u0631\u0647\u06cc \u0646\u062f\u0627\u0631\u0646\u062f\u060c \u0627\u0646\u062a\u062e\u0627\u0628\u06cc \u0639\u0627\u0644\u06cc \u0628\u0627\u0634\u0646\u062f.  \u0639\u0644\u0627\u0648\u0647 \u0628\u0631 \u0627\u06cc\u0646\u060c \u06cc\u06a9\u06cc \u062f\u06cc\u06af\u0631 \u0627\u0632 \u0622\u06cc\u062a\u0645\u200c\u0647\u0627\u06cc \u062c\u0627\u062f\u0648\u06cc\u06cc \u06a9\u0645\u06cc\u0627\u0628\u060c Ring of Protection\u060c \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u06cc\u06a9 +1 \u0628\u0647 AC \u06a9\u0627\u0631\u0627\u06a9\u062a\u0631 \u0628\u062f\u0648\u0646 \u0647\u06cc\u0686 \u0631\u0634\u062a\u0647\u200c\u0627\u06cc \u0645\u062a\u0635\u0644 \u06a9\u0646\u062f.<\/p>\n<p><!-- Zone: every entry repeatable. --><\/p>\n<h2 id=\"consider-races-and-subclasses-that-improve-ac\"><span class=\"ez-toc-section\" id=\"1_%D9%86%DA%98%D8%A7%D8%AF%D9%87%D8%A7_%D9%88_%D8%B2%DB%8C%D8%B1_%DA%A9%D9%84%D8%A7%D8%B3_%D9%87%D8%A7%DB%8C%DB%8C_%D8%B1%D8%A7_%D8%AF%D8%B1_%D9%86%D8%B8%D8%B1_%D8%A8%DA%AF%DB%8C%D8%B1%DB%8C%D8%AF_%DA%A9%D9%87_AC_%D8%B1%D8%A7_%D8%A8%D9%87%D8%A8%D9%88%D8%AF_%D9%85%DB%8C_%D8%A8%D8%AE%D8%B4%D9%86%D8%AF\"><\/span> <span class=\"item-num\">1 <\/span> <span>\u0646\u0698\u0627\u062f\u0647\u0627 \u0648 \u0632\u06cc\u0631 \u06a9\u0644\u0627\u0633 \u0647\u0627\u06cc\u06cc \u0631\u0627 \u062f\u0631 \u0646\u0638\u0631 \u0628\u06af\u06cc\u0631\u06cc\u062f \u06a9\u0647 AC \u0631\u0627 \u0628\u0647\u0628\u0648\u062f \u0645\u06cc \u0628\u062e\u0634\u0646\u062f<\/span> <span class=\"ez-toc-section-end\"><\/span><\/h2>\n<div class=\"body-img landscape\">\n<div class=\"responsive-img image-expandable img-article-item\" style=\"padding-bottom:50%\" data-img-url=\"https:\/\/nabfollower.com\/blog\/wp-content\/uploads\/2023\/03\/1678700708_892_6-\u0631\u0627\u0647-\u0628\u0631\u0627\u06cc-\u0627\u0641\u0632\u0627\u06cc\u0634-\u06a9\u0644\u0627\u0633-\u0632\u0631\u0647\u06cc-\u062e\u0648\u062f-\u062f\u0631-DD.jpg\" data-modal-id=\"single-image-modal\" data-modal-container-id=\"single-image-modal-container\" data-img-caption=\"&quot;Tortle by Wizards of the Coast&quot;\">\n<figure> <picture> <!--[if IE 9]> <video style=\"display: none;\"><![endif]--><source media=\"(min-width: 1024px)\"  data-\/><source media=\"(min-width: 768px)\"  data-\/><source media=\"(min-width: 481px)\"  data-\/><source media=\"(min-width: 0px)\"  data-\/><!--[if IE 9]><\/video><![endif]--><img loading=\"lazy\" decoding=\"async\" width=\"1364\" height=\"682\" class=\"lazyload\" alt=\"\u067e\u0631\u062a\u0631\u0647 \u06cc\u06a9 \u0644\u0627\u06a9 \u067e\u0634\u062a \u062f\u0631 D&#038;D\" src=\"https:\/\/nabfollower.com\/blog\/wp-content\/uploads\/2023\/03\/1678700708_892_6-\u0631\u0627\u0647-\u0628\u0631\u0627\u06cc-\u0627\u0641\u0632\u0627\u06cc\u0634-\u06a9\u0644\u0627\u0633-\u0632\u0631\u0647\u06cc-\u062e\u0648\u062f-\u062f\u0631-DD.jpg\" title=\"\"> <\/picture><figcaption class=\"body-img-caption\">\u0644\u0627\u06a9 \u067e\u0634\u062a \u062a\u0648\u0633\u0637 \u062c\u0627\u062f\u0648\u06af\u0631\u0627\u0646 \u0633\u0627\u062d\u0644<\/figcaption><\/figure>\n<\/p><\/div>\n<\/p><\/div>\n<p>  \u062f\u0631 \u062d\u0627\u0644\u06cc \u06a9\u0647 \u06af\u0632\u06cc\u0646\u0647 \u0627\u06cc \u0628\u0631\u0627\u06cc \u06a9\u0633\u0627\u0646\u06cc \u0646\u06cc\u0633\u062a \u06a9\u0647 \u0627\u0632 \u0642\u0628\u0644 \u0628\u0627 \u06cc\u06a9 \u06a9\u0645\u067e\u06cc\u0646 \u062f\u0631 \u062d\u0627\u0644 \u0627\u0646\u062c\u0627\u0645 \u0647\u0633\u062a\u0646\u062f\u060c \u06af\u0632\u06cc\u0646\u0647 \u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641\u06cc \u0628\u0631\u0627\u06cc \u0628\u0627\u0632\u06cc\u06a9\u0646\u0627\u0646 \u062f\u0631 \u0645\u06cc\u0627\u0646 \u062e\u0644\u0642 \u0634\u062e\u0635\u06cc\u062a \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u062f \u06a9\u0647 \u0645\u06cc \u062a\u0648\u0627\u0646\u062f \u06cc\u06a9 \u0634\u062e\u0635\u06cc\u062a AC \u0628\u0647\u0628\u0648\u062f \u06cc\u0627\u0641\u062a\u0647 \u0631\u0627 \u0627\u0631\u0627\u0626\u0647 \u062f\u0647\u062f.  \u0628\u0631\u0627\u06cc \u06a9\u0633\u0627\u0646\u06cc \u06a9\u0647 \u0628\u0647 \u062f\u0646\u0628\u0627\u0644 \u0632\u06cc\u0631 \u06a9\u0644\u0627\u0633\u200c\u0647\u0627\u06cc \u062e\u0627\u0635\u06cc \u0647\u0633\u062a\u0646\u062f \u06a9\u0647 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f AC \u0641\u0631\u062f \u0631\u0627 \u0628\u0647\u0628\u0648\u062f \u0628\u062e\u0634\u0646\u062f\u060c Forge Domain Cleric \u0648 Armorer Artificer \u0647\u0631 \u06a9\u062f\u0627\u0645 \u0627\u0628\u0632\u0627\u0631\u06cc \u0628\u0631\u0627\u06cc \u0628\u0647\u0628\u0648\u062f AC \u062e\u0648\u062f \u0627\u0632 \u0637\u0631\u06cc\u0642 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0648\u06cc\u0698\u06af\u06cc\u200c\u0647\u0627\u06cc \u062a\u062e\u0635\u0635\u06cc \u062f\u0627\u0631\u0646\u062f.  \u0642\u0627\u0628\u0644\u06cc\u062a Draconic Resilience \u0627\u0632 Draconic Bloodline Sorcerer \u0645\u06cc \u062a\u0648\u0627\u0646\u062f \u0628\u0647 \u062a\u0642\u0648\u06cc\u062a \u0637\u0644\u0633\u0645 \u0627\u0632 \u0642\u0628\u0644 \u0646\u0631\u0645 \u06a9\u0645\u06a9 \u06a9\u0646\u062f.<\/p>\n<p>\u0628\u0631\u0627\u06cc \u06a9\u0633\u0627\u0646\u06cc \u06a9\u0647 \u0628\u0647 \u062f\u0646\u0628\u0627\u0644 \u0628\u0647\u0631\u0647 \u0628\u0631\u062f\u0646 \u0627\u0632 \u0632\u0631\u0647 \u0637\u0628\u06cc\u0639\u06cc \u0627\u0632 \u0637\u0631\u06cc\u0642 \u0645\u0633\u0627\u0628\u0642\u0647 \u062e\u0648\u062f \u0647\u0633\u062a\u0646\u062f \u0648 \u0628\u0647 \u0637\u0648\u0631 \u0628\u0627\u0644\u0642\u0648\u0647 \u0646\u06cc\u0627\u0632 \u0628\u0647 \u0632\u0631\u0647 \u0631\u0627 \u0627\u0632 \u0628\u06cc\u0646 \u0645\u06cc \u0628\u0631\u0646\u062f\u060c \u0646\u0698\u0627\u062f\u0647\u0627\u06cc \u0632\u06cc\u0631 \u06cc\u06a9 \u0634\u062e\u0635\u06cc\u062a \u0628\u0627 \u0632\u0631\u0647 \u0637\u0628\u06cc\u0639\u06cc \u0627\u0631\u0627\u0626\u0647 \u0645\u06cc \u062f\u0647\u0646\u062f:<\/p>\n<ul>\n<li>\n<p> \u0645\u0627\u0631\u0645\u0648\u0644\u06a9 <\/li>\n<li>\n<p> \u0644\u0648\u06a9\u0627\u062a\u0647 <\/li>\n<li>\n<p> \u0644\u0648\u06a9\u0633\u0648\u062f\u0648\u0646 <\/li>\n<li>\n<p> \u0633\u06cc\u0645\u06cc\u06a9 \u0647\u06cc\u0628\u0631\u06cc\u062f <\/li>\n<li>\n<p> \u0644\u0627\u06a9 \u067e\u0634\u062a <\/li>\n<li>\n<p> Warforged <\/li>\n<\/ul>\n<p>\u0639\u0644\u0627\u0648\u0647 \u0628\u0631 \u0645\u0633\u0627\u0628\u0642\u0627\u062a \u0628\u0627\u0644\u0627\u060c Shifters \u0627\u0632 \u0627\u0646\u0648\u0627\u0639 Beasthide \u062f\u0631 \u0635\u0648\u0631\u062a \u062c\u0627\u0628\u062c\u0627\u06cc\u06cc \u0628\u0647 \u06cc\u06a9 \u062c\u0627\u06cc\u0632\u0647 +1 \u0628\u0631\u0627\u06cc AC \u062e\u0648\u062f \u062f\u0633\u062a\u0631\u0633\u06cc \u067e\u06cc\u062f\u0627 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f.  \u0628\u0631\u062e\u0644\u0627\u0641 \u062a\u0648\u0627\u0646\u0627\u06cc\u06cc\u200c\u0647\u0627\u06cc \u0632\u0631\u0647\u200c\u062f\u0627\u0631 \u0637\u0628\u06cc\u0639\u06cc \u0646\u0698\u0627\u062f\u0647\u0627\u06cc \u0630\u06a9\u0631 \u0634\u062f\u0647 \u0642\u0628\u0644\u06cc\u060c \u0627\u06cc\u0646 \u062c\u0627\u06cc\u0632\u0647 Beasthide AC \u062d\u062a\u06cc \u0627\u06af\u0631 \u0634\u062e\u0635\u06cc\u062a\u06cc \u06a9\u0647 \u062f\u0631 \u062f\u0633\u062a \u0627\u0633\u062a \u0632\u0631\u0647 \u067e\u0648\u0634\u06cc\u062f\u0647 \u0628\u0627\u0634\u062f \u0646\u06cc\u0632 \u0627\u0639\u0645\u0627\u0644 \u0645\u06cc\u200c\u0634\u0648\u062f.<\/p>\n<p><span class=\"next-single\">\u0628\u0639\u062f\u06cc: \u0647\u0645\u0647 \u0632\u06cc\u0631 \u06a9\u0644\u0627\u0633 \u0647\u0627\u06cc \u062c\u0646\u06af\u0646\u062f\u0647 Dungeons &#038; Dragons\u060c \u0631\u062a\u0628\u0647 \u0628\u0646\u062f\u06cc \u0634\u062f\u0647 \u0628\u0631 \u0627\u0633\u0627\u0633 \u0645\u062d\u0628\u0648\u0628\u06cc\u062a<\/span><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u0647\u0646\u06af\u0627\u0645 \u0634\u0631\u06a9\u062a \u062f\u0631 \u0645\u0628\u0627\u0631\u0632\u0627\u062a \u062f\u0631 Dungeons &#038; Dragons\u060c \u0645\u06a9\u0627\u0646\u06cc\u06a9 \u0647\u0627\u06cc \u0632\u06cc\u0627\u062f\u06cc \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u062f \u06a9\u0647 \u0628\u0627\u0632\u06cc\u06a9\u0646\u0627\u0646 \u0628\u0627\u06cc\u062f \u0639\u0644\u0627\u0648\u0647 \u0628\u0631 \u0627\u0645\u062a\u06cc\u0627\u0632\u0627\u062a \u062a\u0648\u0627\u0646\u0627\u06cc\u06cc \u0634\u062e\u0635\u06cc\u062a \u0648 \u0648\u06cc\u0698\u06af\u06cc \u0647\u0627\u06cc \u06a9\u0644\u0627\u0633\u06cc \u0645\u062e\u062a\u0644\u0641\u060c \u0622\u0646\u0647\u0627 \u0631\u0627 \u067e\u06cc\u06af\u06cc\u0631\u06cc \u06a9\u0646\u0646\u062f. \u0686\u0647 \u06cc\u06a9 \u06a9\u0627\u0631\u0627\u06a9\u062a\u0631 \u062f\u0631 \u0633\u0637\u062d \u06cc\u06a9 \u0628\u0627\u0634\u062f \u06cc\u0627 \u0633\u0637\u062d \u0628\u06cc\u0633\u062a\u060c \u06a9\u0644\u0627\u0633 Armor \u06cc\u06a9 \u0634\u062e\u0635\u06cc\u062a (\u06cc\u0627 \u0628\u0647 \u0627\u062e\u062a\u0635\u0627\u0631 AC) \u06cc\u06a9 \u0639\u0646\u0635\u0631 \u062f\u0641\u0627\u0639\u06cc \u0645\u0647\u0645 \u0627\u0633\u062a. \u0628\u0627 \u0627\u0646\u0639\u06a9\u0627\u0633 &hellip;<\/p>\n","protected":false},"author":2,"featured_media":11805,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[352],"tags":[],"class_list":["post-11804","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-game"],"_links":{"self":[{"href":"https:\/\/nabfollower.com\/blog\/wp-json\/wp\/v2\/posts\/11804","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nabfollower.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nabfollower.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nabfollower.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/nabfollower.com\/blog\/wp-json\/wp\/v2\/comments?post=11804"}],"version-history":[{"count":0,"href":"https:\/\/nabfollower.com\/blog\/wp-json\/wp\/v2\/posts\/11804\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nabfollower.com\/blog\/wp-json\/wp\/v2\/media\/11805"}],"wp:attachment":[{"href":"https:\/\/nabfollower.com\/blog\/wp-json\/wp\/v2\/media?parent=11804"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nabfollower.com\/blog\/wp-json\/wp\/v2\/categories?post=11804"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nabfollower.com\/blog\/wp-json\/wp\/v2\/tags?post=11804"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}