{"id":18243,"date":"2023-04-18T21:57:52","date_gmt":"2023-04-18T18:27:52","guid":{"rendered":"https:\/\/nabfollower.com\/blog\/99591996-cms\/"},"modified":"2023-04-18T21:57:52","modified_gmt":"2023-04-18T18:27:52","slug":"99591996-cms","status":"publish","type":"post","link":"https:\/\/nabfollower.com\/blog\/99591996-cms\/","title":{"rendered":"\u0627\u067e\u0644 \u0648 \u06af\u0648\u06af\u0644 \u0628\u0647 \u0622\u0645\u0627\u0632\u0648\u0646 \u062f\u0631 \u0645\u0648\u0631\u062f \u0627\u067e\u0644\u06cc\u06a9\u06cc\u0634\u0646 Kindle \u0647\u0634\u062f\u0627\u0631 \u062f\u0627\u062f\u0646\u062f"},"content":{"rendered":"<div data-articlebody=\"1\">\n<div class=\"_3Bevy\">\n<figure><\/figure>\n<\/div>\n<p>\u0633\u06cc\u0628<span> \u0648 \u0645\u062a\u0639\u0644\u0642 \u0628\u0647 \u0627\u0644\u0641\u0628\u0627 <\/span>\u06af\u0648\u06af\u0644<span> \u0647\u0634\u062f\u0627\u0631 \u062f\u0627\u062f\u0647 \u0627\u0646\u062f <\/span>\u0622\u0645\u0627\u0632\u0648\u0646<span> \u067e\u0633 \u0627\u0632 \u0627\u06cc\u0646\u06a9\u0647 \u0634\u0631\u06a9\u062a\u200c\u0647\u0627 \u0641\u0647\u0645\u06cc\u062f\u0646\u062f \u06a9\u0647 \u06a9\u0648\u062f\u06a9\u0627\u0646 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0628\u0647 \u0639\u06a9\u0633\u200c\u0647\u0627\u06cc \u063a\u06cc\u0631\u0627\u062e\u0644\u0627\u0642\u06cc \u062c\u0646\u0633\u06cc \u062f\u0631 \u0633\u0627\u06cc\u062a \u0645\u062d\u0628\u0648\u0628 \u062f\u0633\u062a\u0631\u0633\u06cc \u067e\u06cc\u062f\u0627 \u06a9\u0646\u0646\u062f <\/span>\u0631\u0648\u0634\u0646 \u0634\u062f\u0646<span> \u0628\u0631\u0646\u0627\u0645\u0647  \u0627\u06cc\u0646 \u0634\u0631\u06a9\u062a \u0647\u0627 \u0627\u0632 \u0622\u0645\u0627\u0632\u0648\u0646 \u062e\u0648\u0627\u0633\u062a\u0646\u062f \u062a\u0627 \u0627\u0639\u062a\u062f\u0627\u0644 \u0645\u062d\u062a\u0648\u0627\u06cc \u062e\u0648\u062f \u0631\u0627 \u062a\u0642\u0648\u06cc\u062a \u06a9\u0646\u062f.<\/span><\/p>\n<p><span>\u06cc\u06a9 \u06af\u0632\u0627\u0631\u0634 \u0631\u0648\u06cc\u062a\u0631\u0632 \u0628\u0647 \u0646\u0642\u0644 \u0627\u0632 \u0627\u067e\u0644 \u0645\u06cc\u200c\u06af\u0648\u06cc\u062f: \u00ab\u0645\u0627 \u0627\u06cc\u0646 \u0646\u06af\u0631\u0627\u0646\u06cc\u200c\u0647\u0627 \u0631\u0627 \u0628\u0627 \u062a\u0648\u0633\u0639\u0647\u200c\u062f\u0647\u0646\u062f\u0647 \u062f\u0631 \u0645\u06cc\u0627\u0646 \u06af\u0630\u0627\u0634\u062a\u0647\u200c\u0627\u06cc\u0645 \u0648 \u0628\u0627 \u0622\u0646\u0647\u0627 \u06a9\u0627\u0631 \u0645\u06cc\u200c\u06a9\u0646\u06cc\u0645 \u062a\u0627 \u0627\u0637\u0645\u06cc\u0646\u0627\u0646 \u062d\u0627\u0635\u0644 \u06a9\u0646\u06cc\u0645 \u06a9\u0647 \u0628\u0631\u0646\u0627\u0645\u0647\u200c\u0634\u0627\u0646 \u0628\u0627 \u062f\u0633\u062a\u0648\u0631\u0627\u0644\u0639\u0645\u0644\u200c\u0647\u0627\u06cc \u0645\u0627 \u0645\u0637\u0627\u0628\u0642\u062a \u062f\u0627\u0631\u062f\u00bb. <\/span><\/p>\n<p><span>  \u0627\u0632 \u0633\u0648\u06cc \u062f\u06cc\u06af\u0631\u060c \u06af\u0648\u06af\u0644 \u06af\u0641\u062a \u06a9\u0647 &#8220;\u06af\u0648\u06af\u0644 \u067e\u0644\u06cc \u0628\u0647 \u0628\u0631\u0646\u0627\u0645\u0647 \u0647\u0627\u06cc\u06cc \u06a9\u0647 \u062d\u0627\u0648\u06cc \u0645\u062d\u062a\u0648\u0627\u06cc \u062c\u0646\u0633\u06cc \u0647\u0633\u062a\u0646\u062f \u06cc\u0627 \u062a\u0628\u0644\u06cc\u063a \u0645\u06cc \u06a9\u0646\u0646\u062f \u0627\u062c\u0627\u0632\u0647 \u0646\u0645\u06cc \u062f\u0647\u062f \u0648 \u0645\u0627 \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0648\u0631\u062f \u0628\u0627 \u062a\u0648\u0633\u0639\u0647 \u062f\u0647\u0646\u062f\u0647 \u062f\u0631 \u062a\u0645\u0627\u0633 \u0628\u0648\u062f\u0647 \u0627\u06cc\u0645.&#8221;<\/span><\/p>\n<p><span>\u0631\u0648\u06cc\u062a\u0631\u0632 \u06af\u0632\u0627\u0631\u0634 \u062f\u0627\u062f \u06a9\u0647 \u06a9\u0648\u062f\u06a9\u0627\u0646 \u0645\u06cc \u062a\u0648\u0627\u0646\u0646\u062f \u0628\u0647 \u062d\u062c\u0645 \u0622\u0646\u0644\u0627\u06cc\u0646 \u0639\u06a9\u0633 \u0647\u0627\u06cc \u0632\u0646\u0627\u0646 \u0628\u0631\u0647\u0646\u0647 \u062f\u0633\u062a\u0631\u0633\u06cc \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u0646\u062f \u0648 \u0622\u0646\u0647\u0627 \u0631\u0627 \u0645\u0634\u0627\u0647\u062f\u0647 \u06a9\u0646\u0646\u062f.  \u0628\u0631\u062e\u06cc \u0628\u0647 \u0646\u0638\u0631 \u0645\u06cc \u0631\u0633\u06cc\u062f \u06a9\u0647 \u0632\u0646\u0627\u0646 \u0648 \u0645\u0631\u062f\u0627\u0646 \u0631\u0627 \u062f\u0631 \u062d\u0627\u0644 \u0627\u0646\u062c\u0627\u0645 \u0627\u0639\u0645\u0627\u0644 \u062c\u0646\u0633\u06cc \u0646\u0634\u0627\u0646 \u0645\u06cc \u062f\u0627\u062f\u0646\u062f.  \u06af\u0648\u06af\u0644 \u0648 \u0627\u067e\u0644 \u0627\u0639\u0644\u0627\u0645 \u06a9\u0631\u062f\u0646\u062f \u06a9\u0647 \u0646\u06af\u0631\u0627\u0646\u06cc \u0647\u0627\u06cc\u0634\u0627\u0646 \u062f\u0631 \u0645\u0648\u0631\u062f \u0646\u0642\u0636 \u0633\u06cc\u0627\u0633\u062a \u0647\u0627 \u0627\u0633\u062a.<\/span><\/p>\n<div class=\"s3yCW\">\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter-rtl ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u0641\u0647\u0631\u0633\u062a \u0645\u0637\u0627\u0644\u0628<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"\u062a\u063a\u06cc\u06cc\u0631 \u0648\u0636\u0639\u06cc\u062a \u0641\u0647\u0631\u0633\u062a \u0645\u0637\u0627\u0644\u0628\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/nabfollower.com\/blog\/99591996-cms\/#%D9%87%D9%85%DA%86%D9%86%DB%8C%D9%86_%D8%A8%D8%AE%D9%88%D8%A7%D9%86%DB%8C%D8%AF\" >\u0647\u0645\u0686\u0646\u06cc\u0646 \u0628\u062e\u0648\u0627\u0646\u06cc\u062f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/nabfollower.com\/blog\/99591996-cms\/#%D9%87%D9%85%DA%86%D9%86%DB%8C%D9%86_%D8%A8%D8%AE%D9%88%D8%A7%D9%86%DB%8C%D8%AF-2\" >\u0647\u0645\u0686\u0646\u06cc\u0646 \u0628\u062e\u0648\u0627\u0646\u06cc\u062f<\/a><\/li><\/ul><\/nav><\/div>\n<h4><span class=\"ez-toc-section\" id=\"%D9%87%D9%85%DA%86%D9%86%DB%8C%D9%86_%D8%A8%D8%AE%D9%88%D8%A7%D9%86%DB%8C%D8%AF\"><\/span>\u0647\u0645\u0686\u0646\u06cc\u0646 \u0628\u062e\u0648\u0627\u0646\u06cc\u062f<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<div class=\"_2JNfJ\">\n<div class=\"_2XCtL\">\n<div class=\"_1KkXY\">\n<div class=\"P8dj3\"><img decoding=\"async\" src=\"https:\/\/nabfollower.com\/blog\/wp-content\/uploads\/2022\/11\/\u0646\u062d\u0648\u0647-\u0627\u0646\u062a\u0642\u0627\u0644-\u0645\u0648\u062c\u0648\u062f\u06cc-Amazon-Pay-\u0628\u0647-\u062d\u0633\u0627\u0628-\u0628\u0627\u0646\u06a9\u06cc.cms.png\" style=\"object-fit:contain;object-position:center\" alt=\"\u0648\u0632\u06cc\u0631 \u0631\u0648\u0633\u06cc\u0647 \u0645\u06cc \u06af\u0648\u06cc\u062f \u0641\u0639\u0644\u0627\u064b \u0628\u0644\u0648\u06a9 \u0648\u06cc\u06a9\u06cc \u067e\u062f\u06cc\u0627 \u0631\u0627 \u0628\u0631\u0646\u0627\u0645\u0647 \u0631\u06cc\u0632\u06cc \u0646\u0645\u06cc \u06a9\u0646\u062f\" title=\"\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p><span>\u0627\u06cc\u0646 \u062e\u0628\u0631\u06af\u0632\u0627\u0631\u06cc \u0628\u0647 \u0646\u0642\u0644 \u0627\u0632 \u062f\u0648 \u062e\u0627\u0646\u0648\u0627\u062f\u0647 \u06af\u0641\u062a\u0647 \u0627\u0633\u062a \u06a9\u0647 \u00ab\u067e\u0633\u0631\u0627\u0646 \u067e\u06cc\u0634 \u0627\u0632 \u0646\u0648\u062c\u0648\u0627\u0646\u06cc \u0622\u0646\u0647\u0627 \u0645\u0637\u0627\u0644\u0628 \u0635\u0631\u06cc\u062d \u0631\u0627 \u0627\u0632 \u0637\u0631\u06cc\u0642 \u0622\u0645\u0627\u0632\u0648\u0646 \u062f\u0627\u0646\u0644\u0648\u062f \u06a9\u0631\u062f\u0647 \u0627\u0646\u062f. <\/span>\u06a9\u06cc\u0646\u062f\u0644 \u0646\u0627\u0645\u062d\u062f\u0648\u062f<span> \u062e\u062f\u0645\u0627\u062a \u0627\u0634\u062a\u0631\u0627\u06a9 \u06a9\u062a\u0627\u0628 \u0627\u0644\u06a9\u062a\u0631\u0648\u0646\u06cc\u06a9\u06cc \u0648 \u0645\u0634\u0627\u0647\u062f\u0647 \u0639\u06a9\u0633\u200c\u0647\u0627\u06cc \u062a\u0645\u0627\u0645 \u0631\u0646\u06af\u06cc \u062f\u0631 \u0627\u067e\u0644\u06cc\u06a9\u06cc\u0634\u0646 \u06a9\u06cc\u0646\u062f\u0644 \u0622\u06cc\u0641\u0648\u0646. <\/span><\/p>\n<p><span>\u062f\u0631 \u0627\u06cc\u0646 \u06af\u0632\u0627\u0631\u0634 \u0647\u0645\u0686\u0646\u06cc\u0646 \u0627\u0634\u0627\u0631\u0647 \u0634\u062f \u06a9\u0647 \u067e\u0648\u0631\u0646\u0648\u06af\u0631\u0627\u0641\u06cc \u0627\u0632 \u0637\u0631\u06cc\u0642 \u0641\u0631\u0648\u0634\u06af\u0627\u0647 \u0622\u0646\u0644\u0627\u06cc\u0646 Kindle \u0622\u0645\u0627\u0632\u0648\u0646 \u0646\u06cc\u0632 \u062f\u0631 \u062f\u0633\u062a\u0631\u0633 \u0627\u0633\u062a \u0648 \u062f\u0631 \u0646\u0633\u062e\u0647 \u0647\u0627\u06cc \u0628\u0631\u0646\u0627\u0645\u0647 Kindle \u0642\u0627\u0628\u0644 \u0645\u0634\u0627\u0647\u062f\u0647 \u0627\u0633\u062a.<\/span><\/p>\n<p><strong><span><strong>\u062f\u0631 \u0627\u06cc\u0646\u062c\u0627 \u0686\u06cc\u0632\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0622\u0645\u0627\u0632\u0648\u0646 \u0646\u06cc\u0632 \u0645\u06cc \u06af\u0648\u06cc\u062f<\/strong><\/span><br \/><\/strong><span>\u0622\u0645\u0627\u0632\u0648\u0646 \u06af\u0641\u062a\u0647 \u0627\u0633\u062a \u06a9\u0647 \u062f\u0631 \u062d\u0627\u0644 \u0628\u0631\u0631\u0633\u06cc \u062a\u0645\u0627\u0645 \u0627\u0637\u0644\u0627\u0639\u0627\u062a \u0645\u0648\u062c\u0648\u062f \u0627\u0633\u062a.<\/span><\/p>\n<p><span>\u0645\u0627 \u0645\u062a\u0639\u0647\u062f \u0628\u0647 \u0627\u0631\u0627\u0626\u0647 \u062a\u062c\u0631\u0628\u0647 \u062e\u0631\u06cc\u062f \u0648 \u0645\u0637\u0627\u0644\u0639\u0647 \u0627\u06cc\u0645\u0646 \u0628\u0631\u0627\u06cc \u0645\u0634\u062a\u0631\u06cc\u0627\u0646 \u0648 \u062e\u0627\u0646\u0648\u0627\u062f\u0647 \u0647\u0627\u06cc\u0634\u0627\u0646 \u0647\u0633\u062a\u06cc\u0645 \u0648 \u0645\u0633\u0627\u0626\u0644\u06cc \u0627\u0632 \u0627\u06cc\u0646 \u062f\u0633\u062a \u0631\u0627 \u062c\u062f\u06cc \u0645\u06cc \u06af\u06cc\u0631\u06cc\u0645.  \u0645\u0627 \u062f\u0631 \u062d\u0627\u0644 \u0628\u0631\u0631\u0633\u06cc \u0647\u0645\u0647 \u0627\u0637\u0644\u0627\u0639\u0627\u062a \u0645\u0648\u062c\u0648\u062f \u0647\u0633\u062a\u06cc\u0645 \u0648 \u0628\u0631 \u0627\u0633\u0627\u0633 \u06cc\u0627\u0641\u062a\u0647\u200c\u0647\u0627\u06cc \u062e\u0648\u062f \u0627\u0642\u062f\u0627\u0645 \u0645\u06cc\u200c\u06a9\u0646\u06cc\u0645.\u00bb \u0628\u0647 \u0646\u0642\u0644 \u0627\u0632 \u0622\u0645\u0627\u0632\u0648\u0646.<\/span><\/p>\n<div class=\"s3yCW\">\n<h4><span class=\"ez-toc-section\" id=\"%D9%87%D9%85%DA%86%D9%86%DB%8C%D9%86_%D8%A8%D8%AE%D9%88%D8%A7%D9%86%DB%8C%D8%AF-2\"><\/span>\u0647\u0645\u0686\u0646\u06cc\u0646 \u0628\u062e\u0648\u0627\u0646\u06cc\u062f<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<div class=\"_2JNfJ\">\n<div class=\"_2XCtL\">\n<div class=\"_1KkXY\">\n<div class=\"P8dj3\"><img decoding=\"async\" src=\"https:\/\/nabfollower.com\/blog\/wp-content\/uploads\/2022\/11\/\u0646\u062d\u0648\u0647-\u0627\u0646\u062a\u0642\u0627\u0644-\u0645\u0648\u062c\u0648\u062f\u06cc-Amazon-Pay-\u0628\u0647-\u062d\u0633\u0627\u0628-\u0628\u0627\u0646\u06a9\u06cc.cms.png\" style=\"object-fit:contain;object-position:center\" alt=\"\u0622\u0645\u0627\u0632\u0648\u0646 \u062f\u0631 \u0633\u0627\u0644 2022 \u0647\u06cc\u0686 \u0633\u0647\u0627\u0645 \u062c\u062f\u06cc\u062f\u06cc \u0628\u0647 \u0645\u062f\u06cc\u0631 \u0639\u0627\u0645\u0644 \u0634\u0631\u06a9\u062a \u0627\u0646\u062f\u06cc \u062c\u0627\u0633\u06cc \u0646\u062f\u0627\u062f\" title=\"\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p><span>\u0645\u0637\u0627\u0644\u0628 \u0645\u0631\u0628\u0648\u0637 \u0628\u0647 \u0628\u0632\u0631\u06af\u0633\u0627\u0644\u0627\u0646 \u0627\u0632 \u0637\u0631\u06cc\u0642 \u0622\u0645\u0627\u0632\u0648\u0646 \u0628\u0647 \u0648\u06cc\u0698\u06af\u06cc \u062e\u0648\u062f \u0627\u0646\u062a\u0634\u0627\u0631\u06cc \u0645\u0631\u062a\u0628\u0637 \u0627\u0633\u062a <\/span>Kindle Direct Publishing<span> \u0628\u0627\u0632\u0648  \u0646\u0648\u06cc\u0633\u0646\u062f\u06af\u0627\u0646 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u06a9\u062a\u0627\u0628\u200c\u0647\u0627\u06cc \u062e\u0648\u062f \u0631\u0627 \u062a\u0642\u0631\u06cc\u0628\u0627\u064b \u0641\u0648\u0631\u0627\u064b \u0627\u0632 \u0637\u0631\u06cc\u0642 \u0622\u0645\u0627\u0632\u0648\u0646 \u0645\u0646\u062a\u0634\u0631 \u06a9\u0646\u0646\u062f \u0648 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0645\u062d\u062a\u0648\u0627 \u0631\u0627 \u0628\u0631\u0627\u06cc \u0633\u0631\u0648\u06cc\u0633 Kindle Unlimited \u062f\u0631 \u062f\u0633\u062a\u0631\u0633 \u0642\u0631\u0627\u0631 \u062f\u0647\u0646\u062f. <\/span><\/p>\n<p><span>\u0637\u0628\u0642 \u0634\u0631\u0627\u06cc\u0637 \u0622\u0645\u0627\u0632\u0648\u0646 \u0628\u0631\u0627\u06cc \u0628\u0627\u0632\u0648\u06cc \u062e\u0648\u062f \u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a \u062e\u0648\u062f\u060c \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0627\u0632 \u0641\u0631\u0648\u0634 \u0645\u062d\u062a\u0648\u0627\u06cc\u06cc \u06a9\u0647 \u0622\u0646 \u0631\u0627 \u00ab\u062a\u0648\u0647\u06cc\u0646\u200c\u0622\u0645\u06cc\u0632 \u06cc\u0627 \u0646\u0627\u0645\u0646\u0627\u0633\u0628\u00bb \u0645\u06cc\u200c\u062f\u0627\u0646\u062f\u060c \u06a9\u0647 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u062d\u0627\u0648\u06cc \u0645\u062d\u062a\u0648\u0627\u06cc \u00ab\u062d\u0627\u0648\u06cc \u0647\u0631\u0632\u0647\u200c\u0646\u06af\u0627\u0631\u06cc\u00bb \u0628\u0627\u0634\u062f\u060c \u062e\u0648\u062f\u062f\u0627\u0631\u06cc \u06a9\u0646\u062f.<\/span><\/p>\n<p><span>\u0631\u0648\u06cc\u062a\u0631\u0632 \u06af\u0641\u062a \u06a9\u0647 \u0647\u06cc\u0686 \u06a9\u0646\u062a\u0631\u0644 \u0648\u0627\u0644\u062f\u06cc\u0646\u06cc \u0628\u0631\u0627\u06cc \u0633\u0631\u0648\u06cc\u0633 Kindle Unlimited \u0648\u062c\u0648\u062f \u0646\u062f\u0627\u0631\u062f.<\/span><\/p>\n<p><span class=\"_1Gm5L _1cFg8\">\u0641\u06cc\u0633 \u0628\u0648\u06a9<\/span><span class=\"_3cJnZ _1cFg8\">\u062a\u0648\u06cc\u06cc\u062a\u0631<\/span><span class=\"_2Gi9S _1cFg8\">\u0644\u06cc\u0646\u06a9\u062f\u06cc\u0646<\/span><\/p>\n<hr class=\"tp_16\"\/><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u0633\u06cc\u0628 \u0648 \u0645\u062a\u0639\u0644\u0642 \u0628\u0647 \u0627\u0644\u0641\u0628\u0627 \u06af\u0648\u06af\u0644 \u0647\u0634\u062f\u0627\u0631 \u062f\u0627\u062f\u0647 \u0627\u0646\u062f \u0622\u0645\u0627\u0632\u0648\u0646 \u067e\u0633 \u0627\u0632 \u0627\u06cc\u0646\u06a9\u0647 \u0634\u0631\u06a9\u062a\u200c\u0647\u0627 \u0641\u0647\u0645\u06cc\u062f\u0646\u062f \u06a9\u0647 \u06a9\u0648\u062f\u06a9\u0627\u0646 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0628\u0647 \u0639\u06a9\u0633\u200c\u0647\u0627\u06cc \u063a\u06cc\u0631\u0627\u062e\u0644\u0627\u0642\u06cc \u062c\u0646\u0633\u06cc \u062f\u0631 \u0633\u0627\u06cc\u062a \u0645\u062d\u0628\u0648\u0628 \u062f\u0633\u062a\u0631\u0633\u06cc \u067e\u06cc\u062f\u0627 \u06a9\u0646\u0646\u062f \u0631\u0648\u0634\u0646 \u0634\u062f\u0646 \u0628\u0631\u0646\u0627\u0645\u0647 \u0627\u06cc\u0646 \u0634\u0631\u06a9\u062a \u0647\u0627 \u0627\u0632 \u0622\u0645\u0627\u0632\u0648\u0646 \u062e\u0648\u0627\u0633\u062a\u0646\u062f \u062a\u0627 \u0627\u0639\u062a\u062f\u0627\u0644 \u0645\u062d\u062a\u0648\u0627\u06cc \u062e\u0648\u062f \u0631\u0627 \u062a\u0642\u0648\u06cc\u062a \u06a9\u0646\u062f. \u06cc\u06a9 \u06af\u0632\u0627\u0631\u0634 \u0631\u0648\u06cc\u062a\u0631\u0632 \u0628\u0647 \u0646\u0642\u0644 \u0627\u0632 \u0627\u067e\u0644 \u0645\u06cc\u200c\u06af\u0648\u06cc\u062f: \u00ab\u0645\u0627 \u0627\u06cc\u0646 \u0646\u06af\u0631\u0627\u0646\u06cc\u200c\u0647\u0627 &hellip;<\/p>\n","protected":false},"author":2,"featured_media":18244,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[26],"tags":[],"class_list":["post-18243","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-social"],"_links":{"self":[{"href":"https:\/\/nabfollower.com\/blog\/wp-json\/wp\/v2\/posts\/18243","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nabfollower.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nabfollower.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nabfollower.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/nabfollower.com\/blog\/wp-json\/wp\/v2\/comments?post=18243"}],"version-history":[{"count":0,"href":"https:\/\/nabfollower.com\/blog\/wp-json\/wp\/v2\/posts\/18243\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nabfollower.com\/blog\/wp-json\/wp\/v2\/media\/18244"}],"wp:attachment":[{"href":"https:\/\/nabfollower.com\/blog\/wp-json\/wp\/v2\/media?parent=18243"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nabfollower.com\/blog\/wp-json\/wp\/v2\/categories?post=18243"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nabfollower.com\/blog\/wp-json\/wp\/v2\/tags?post=18243"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}