{"id":25627,"date":"2023-06-04T15:05:37","date_gmt":"2023-06-04T11:35:37","guid":{"rendered":"https:\/\/nabfollower.com\/blog\/a-comprehensive-guide-to-using-css-grid-for-creating-flexible-and-responsive-layouts-m4b\/"},"modified":"2023-06-04T15:05:37","modified_gmt":"2023-06-04T11:35:37","slug":"a-comprehensive-guide-to-using-css-grid-for-creating-flexible-and-responsive-layouts-m4b","status":"publish","type":"post","link":"https:\/\/nabfollower.com\/blog\/a-comprehensive-guide-to-using-css-grid-for-creating-flexible-and-responsive-layouts-m4b\/","title":{"rendered":"CSS Grid: \u0631\u0627\u0647\u0646\u0645\u0627\u06cc \u062c\u0627\u0645\u0639 \u0628\u0631\u0627\u06cc \u0686\u06cc\u062f\u0645\u0627\u0646 \u0647\u0627\u06cc \u0627\u0646\u0639\u0637\u0627\u0641 \u067e\u0630\u06cc\u0631 \u0648 \u067e\u0627\u0633\u062e\u06af\u0648"},"content":{"rendered":"<div data-article-id=\"1490166\" id=\"article-body\">\n<p>\u062f\u0631 \u0686\u0634\u0645\u200c\u0627\u0646\u062f\u0627\u0632 \u062a\u0648\u0633\u0639\u0647 \u0648\u0628 \u0627\u0645\u0631\u0648\u0632\u06cc\u060c \u0627\u06cc\u062c\u0627\u062f \u0637\u0631\u062d\u200c\u0628\u0646\u062f\u06cc\u200c\u0647\u0627\u06cc \u0627\u0646\u0639\u0637\u0627\u0641\u200c\u067e\u0630\u06cc\u0631 \u0648 \u067e\u0627\u0633\u062e\u200c\u06af\u0648 \u0628\u0631\u0627\u06cc \u0627\u0637\u0645\u06cc\u0646\u0627\u0646 \u0627\u0632 \u062a\u062c\u0631\u0628\u0647 \u06a9\u0627\u0631\u0628\u0631\u06cc \u0628\u0647\u06cc\u0646\u0647 \u062f\u0631 \u062f\u0633\u062a\u06af\u0627\u0647\u200c\u0647\u0627 \u0648 \u0627\u0646\u062f\u0627\u0632\u0647\u200c\u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641 \u0635\u0641\u062d\u0647 \u0646\u0645\u0627\u06cc\u0634 \u0636\u0631\u0648\u0631\u06cc \u0627\u0633\u062a.  CSS Grid\u060c \u06cc\u06a9 \u0645\u0627\u0698\u0648\u0644 \u0637\u0631\u062d\u200c\u0628\u0646\u062f\u06cc \u0642\u062f\u0631\u062a\u0645\u0646\u062f \u0645\u0639\u0631\u0641\u06cc \u0634\u062f\u0647 \u062f\u0631 CSS3\u060c \u0631\u0627\u0647\u200c\u062d\u0644\u06cc \u062c\u0627\u0645\u0639 \u0628\u0631\u0627\u06cc \u0633\u0627\u062e\u062a \u0637\u0631\u062d\u200c\u0628\u0646\u062f\u06cc\u200c\u0647\u0627\u06cc \u067e\u06cc\u0686\u06cc\u062f\u0647 \u0645\u0628\u062a\u0646\u06cc \u0628\u0631 \u0634\u0628\u06a9\u0647 \u0628\u0647 \u0631\u0627\u062d\u062a\u06cc \u0627\u0631\u0627\u0626\u0647 \u0645\u06cc\u200c\u062f\u0647\u062f.  \u062f\u0631 \u0627\u06cc\u0646 \u0631\u0627\u0647\u0646\u0645\u0627\u060c CSS Grid \u0631\u0627 \u0628\u0647 \u0637\u0648\u0631 \u0639\u0645\u06cc\u0642 \u0628\u0631\u0631\u0633\u06cc \u0645\u06cc \u06a9\u0646\u06cc\u0645 \u0648 \u06cc\u0627\u062f \u0645\u06cc \u06af\u06cc\u0631\u06cc\u0645 \u06a9\u0647 \u0686\u06af\u0648\u0646\u0647 \u0627\u0632 \u0642\u0627\u0628\u0644\u06cc\u062a \u0647\u0627\u06cc \u0622\u0646 \u0628\u0631\u0627\u06cc \u0627\u06cc\u062c\u0627\u062f \u0637\u0631\u062d \u0647\u0627\u06cc \u0627\u0646\u0639\u0637\u0627\u0641 \u067e\u0630\u06cc\u0631 \u0648 \u067e\u0627\u0633\u062e\u06af\u0648 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u0645.<\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter-rtl ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u0641\u0647\u0631\u0633\u062a \u0645\u0637\u0627\u0644\u0628<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"\u062a\u063a\u06cc\u06cc\u0631 \u0648\u0636\u0639\u06cc\u062a \u0641\u0647\u0631\u0633\u062a \u0645\u0637\u0627\u0644\u0628\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/nabfollower.com\/blog\/a-comprehensive-guide-to-using-css-grid-for-creating-flexible-and-responsive-layouts-m4b\/#%D8%AF%D8%B1%DA%A9_CSS_Grid\" >\u062f\u0631\u06a9 CSS Grid<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/nabfollower.com\/blog\/a-comprehensive-guide-to-using-css-grid-for-creating-flexible-and-responsive-layouts-m4b\/#%D8%A7%DB%8C%D8%AC%D8%A7%D8%AF_%DB%8C%DA%A9_%D8%B7%D8%B1%D8%AD_%D8%A8%D9%86%D8%AF%DB%8C_%D9%BE%D8%A7%DB%8C%D9%87_%D8%B4%D8%A8%DA%A9%D9%87\" >\u0627\u06cc\u062c\u0627\u062f \u06cc\u06a9 \u0637\u0631\u062d \u0628\u0646\u062f\u06cc \u067e\u0627\u06cc\u0647 \u0634\u0628\u06a9\u0647<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/nabfollower.com\/blog\/a-comprehensive-guide-to-using-css-grid-for-creating-flexible-and-responsive-layouts-m4b\/#%D8%AA%DA%A9%D9%86%DB%8C%DA%A9_%D9%87%D8%A7%DB%8C_%DA%86%DB%8C%D8%AF%D9%85%D8%A7%D9%86_%D8%B4%D8%A8%DA%A9%D9%87\" >\u062a\u06a9\u0646\u06cc\u06a9 \u0647\u0627\u06cc \u0686\u06cc\u062f\u0645\u0627\u0646 \u0634\u0628\u06a9\u0647<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/nabfollower.com\/blog\/a-comprehensive-guide-to-using-css-grid-for-creating-flexible-and-responsive-layouts-m4b\/#%DA%A9%D8%A7%D8%B1_%D8%A8%D8%A7_Grid_Properties\" >\u06a9\u0627\u0631 \u0628\u0627 Grid Properties<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/nabfollower.com\/blog\/a-comprehensive-guide-to-using-css-grid-for-creating-flexible-and-responsive-layouts-m4b\/#%D8%AA%DA%A9%D9%86%DB%8C%DA%A9_%D9%87%D8%A7%DB%8C_%D8%B4%D8%A8%DA%A9%D9%87_%D9%BE%DB%8C%D8%B4%D8%B1%D9%81%D8%AA%D9%87\" >\u062a\u06a9\u0646\u06cc\u06a9 \u0647\u0627\u06cc \u0634\u0628\u06a9\u0647 \u067e\u06cc\u0634\u0631\u0641\u062a\u0647<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/nabfollower.com\/blog\/a-comprehensive-guide-to-using-css-grid-for-creating-flexible-and-responsive-layouts-m4b\/#%D9%BE%D8%A7%D8%B3%D8%AE%DA%AF%D9%88_%DA%A9%D8%B1%D8%AF%D9%86_%DA%86%DB%8C%D8%AF%D9%85%D8%A7%D9%86_%D9%87%D8%A7%DB%8C_%D8%B4%D8%A8%DA%A9%D9%87\" >\u067e\u0627\u0633\u062e\u06af\u0648 \u06a9\u0631\u062f\u0646 \u0686\u06cc\u062f\u0645\u0627\u0646 \u0647\u0627\u06cc \u0634\u0628\u06a9\u0647<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/nabfollower.com\/blog\/a-comprehensive-guide-to-using-css-grid-for-creating-flexible-and-responsive-layouts-m4b\/#%D8%AA%D8%B1%DA%A9%DB%8C%D8%A8_CSS_Grid_%D8%A8%D8%A7_%D8%B3%D8%A7%DB%8C%D8%B1_%D8%B1%D9%88%D8%B4_%D9%87%D8%A7%DB%8C_Layout\" >\u062a\u0631\u06a9\u06cc\u0628 CSS Grid \u0628\u0627 \u0633\u0627\u06cc\u0631 \u0631\u0648\u0634 \u0647\u0627\u06cc Layout<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/nabfollower.com\/blog\/a-comprehensive-guide-to-using-css-grid-for-creating-flexible-and-responsive-layouts-m4b\/#%D8%A8%D9%87%DB%8C%D9%86%D9%87_%D8%B3%D8%A7%D8%B2%DB%8C_%D8%B9%D9%85%D9%84%DA%A9%D8%B1%D8%AF_%D8%B4%D8%A8%DA%A9%D9%87\" >\u0628\u0647\u06cc\u0646\u0647 \u0633\u0627\u0632\u06cc \u0639\u0645\u0644\u06a9\u0631\u062f \u0634\u0628\u06a9\u0647<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/nabfollower.com\/blog\/a-comprehensive-guide-to-using-css-grid-for-creating-flexible-and-responsive-layouts-m4b\/#%D9%86%D8%AA%DB%8C%D8%AC%D9%87\" >\u0646\u062a\u06cc\u062c\u0647<\/a><\/li><\/ul><\/nav><\/div>\n<h3><span class=\"ez-toc-section\" id=\"%D8%AF%D8%B1%DA%A9_CSS_Grid\"><\/span>\n<p>  \u062f\u0631\u06a9 CSS Grid<br \/>\n<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>CSS Grid \u062d\u0648\u0644 \u0645\u0641\u0647\u0648\u0645 \u0638\u0631\u0641 \u0634\u0628\u06a9\u0647 \u0648 \u0622\u06cc\u062a\u0645 \u0647\u0627\u06cc \u0634\u0628\u06a9\u0647 \u0645\u06cc \u0686\u0631\u062e\u062f.  \u0638\u0631\u0641 \u0634\u0628\u06a9\u0647 \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u0639\u0646\u0635\u0631 \u0627\u0635\u0644\u06cc \u06a9\u0647 \u0634\u0628\u06a9\u0647 \u0631\u0627 \u062f\u0631 \u062e\u0648\u062f \u062c\u0627\u06cc \u0645\u06cc \u062f\u0647\u062f\u060c \u0639\u0645\u0644 \u0645\u06cc \u06a9\u0646\u062f\u060c \u062f\u0631 \u062d\u0627\u0644\u06cc \u06a9\u0647 \u0622\u06cc\u062a\u0645 \u0647\u0627\u06cc \u0634\u0628\u06a9\u0647\u060c \u0639\u0646\u0627\u0635\u0631 \u0641\u0631\u0632\u0646\u062f \u062f\u0631\u0648\u0646 \u0634\u0628\u06a9\u0647 \u0647\u0633\u062a\u0646\u062f.  \u062f\u0631\u06a9 \u062e\u0637\u0648\u0637 \u0634\u0628\u06a9\u0647\u060c \u0633\u0644\u0648\u0644\u200c\u0647\u0627 \u0648 \u0646\u0648\u0627\u062d\u06cc\u060c \u0648 \u0647\u0645\u0686\u0646\u06cc\u0646 \u062e\u0637\u0648\u0637 \u0634\u0628\u06a9\u0647 \u0648 \u0634\u06a9\u0627\u0641\u200c\u0647\u0627\u060c \u0628\u0631\u0627\u06cc \u0627\u06cc\u062c\u0627\u062f \u0637\u0631\u062d\u200c\u0628\u0646\u062f\u06cc \u0634\u0628\u06a9\u0647 \u0645\u0648\u062b\u0631 \u0628\u0633\u06cc\u0627\u0631 \u0645\u0647\u0645 \u0627\u0633\u062a.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/nabfollower.com\/blog\/wp-content\/uploads\/2023\/06\/CSS-Grid-\u0631\u0627\u0647\u0646\u0645\u0627\u06cc-\u062c\u0627\u0645\u0639-\u0628\u0631\u0627\u06cc-\u0686\u06cc\u062f\u0645\u0627\u0646-\u0647\u0627\u06cc-\u0627\u0646\u0639\u0637\u0627\u0641-\u067e\u0630\u06cc\u0631-\u0648.jpg\" alt=\"\u0637\u0631\u062d \u0628\u0646\u062f\u06cc \u0634\u0628\u06a9\u0647 CSS\" loading=\"lazy\" width=\"800\" height=\"577\" title=\"\"><\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%A7%DB%8C%D8%AC%D8%A7%D8%AF_%DB%8C%DA%A9_%D8%B7%D8%B1%D8%AD_%D8%A8%D9%86%D8%AF%DB%8C_%D9%BE%D8%A7%DB%8C%D9%87_%D8%B4%D8%A8%DA%A9%D9%87\"><\/span>\n<p>  \u0627\u06cc\u062c\u0627\u062f \u06cc\u06a9 \u0637\u0631\u062d \u0628\u0646\u062f\u06cc \u067e\u0627\u06cc\u0647 \u0634\u0628\u06a9\u0647<br \/>\n<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0628\u0631\u0627\u06cc \u0631\u0627\u0647\u200c\u0627\u0646\u062f\u0627\u0632\u06cc \u06cc\u06a9 \u0637\u0631\u062d\u200c\u0628\u0646\u062f\u06cc \u0627\u0648\u0644\u06cc\u0647 \u0634\u0628\u06a9\u0647\u060c \u0628\u0627 \u062a\u0639\u0631\u06cc\u0641 \u0638\u0631\u0641 \u0634\u0628\u06a9\u0647 \u0634\u0631\u0648\u0639 \u0645\u06cc\u200c\u06a9\u0646\u06cc\u0645.  \u0628\u0627 \u062a\u0639\u06cc\u06cc\u0646 \u062a\u0639\u062f\u0627\u062f \u0648 \u0627\u0646\u062f\u0627\u0632\u0647 \u0633\u062a\u0648\u0646 \u0647\u0627 \u0648 \u0631\u062f\u06cc\u0641 \u0647\u0627\u06cc \u0634\u0628\u06a9\u0647\u060c \u0633\u0627\u062e\u062a\u0627\u0631 \u0634\u0628\u06a9\u0647 \u0631\u0627 \u0627\u06cc\u062c\u0627\u062f \u0645\u06cc \u06a9\u0646\u06cc\u0645.  \u0628\u0627 <em>\u0634\u0628\u06a9\u0647-\u0627\u0644\u06af\u0648-\u0633\u062a\u0648\u0646 \u0647\u0627<\/em> \u0648 <em>grid-template-rows<\/em> \u062e\u0648\u0627\u0635\u060c \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u0645 \u0633\u062a\u0648\u0646\u200c\u0647\u0627\u06cc\u06cc \u0628\u0627 \u0639\u0631\u0636 \u0645\u0633\u0627\u0648\u06cc \u0627\u06cc\u062c\u0627\u062f \u06a9\u0646\u06cc\u0645\u060c \u0627\u0646\u062f\u0627\u0632\u0647\u200c\u0647\u0627\u06cc \u062b\u0627\u0628\u062a \u06cc\u0627 \u0627\u0646\u0639\u0637\u0627\u0641\u200c\u067e\u0630\u06cc\u0631 \u0631\u0627 \u0645\u0634\u062e\u0635 \u06a9\u0646\u06cc\u0645\u060c \u06cc\u0627 \u0627\u0632 \u0648\u0627\u062d\u062f\u0647\u0627\u06cc \u06a9\u0633\u0631\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u0645.  \u0647\u0646\u06af\u0627\u0645\u06cc \u06a9\u0647 \u0633\u0627\u062e\u062a\u0627\u0631 \u0634\u0628\u06a9\u0647 \u062a\u0639\u0631\u06cc\u0641 \u0634\u062f\u060c \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u0645 \u0622\u06cc\u062a\u0645\u200c\u0647\u0627\u06cc \u0634\u0628\u06a9\u0647\u200c\u0627\u06cc \u0631\u0627 \u0628\u0627 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u062a\u06a9\u0646\u06cc\u06a9\u200c\u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641 \u0642\u0631\u0627\u0631 \u062f\u0627\u062f\u0646 \u062f\u0631\u0648\u0646 \u0634\u0628\u06a9\u0647 \u0642\u0631\u0627\u0631 \u062f\u0647\u06cc\u0645.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%AA%DA%A9%D9%86%DB%8C%DA%A9_%D9%87%D8%A7%DB%8C_%DA%86%DB%8C%D8%AF%D9%85%D8%A7%D9%86_%D8%B4%D8%A8%DA%A9%D9%87\"><\/span>\n<p>  \u062a\u06a9\u0646\u06cc\u06a9 \u0647\u0627\u06cc \u0686\u06cc\u062f\u0645\u0627\u0646 \u0634\u0628\u06a9\u0647<br \/>\n<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>CSS Grid \u0686\u0646\u062f\u06cc\u0646 \u062a\u06a9\u0646\u06cc\u06a9 \u0628\u0631\u0627\u06cc \u0627\u06cc\u062c\u0627\u062f \u0637\u0631\u062d\u200c\u0628\u0646\u062f\u06cc\u200c\u0647\u0627\u06cc \u067e\u0648\u06cc\u0627 \u0648 \u0647\u0645\u0647\u200c\u06a9\u0627\u0631\u0647 \u0627\u0631\u0627\u0626\u0647 \u0645\u06cc\u200c\u062f\u0647\u062f.  \u0645\u0627 \u0631\u0648\u0634\u200c\u0647\u0627\u06cc\u06cc \u0645\u0627\u0646\u0646\u062f \u0627\u06cc\u062c\u0627\u062f \u0633\u062a\u0648\u0646\u200c\u0647\u0627\u06cc\u06cc \u0628\u0627 \u0639\u0631\u0636 \u0645\u0633\u0627\u0648\u06cc\u060c \u067e\u0627\u0633\u062e\u200c\u062f\u0647\u06cc \u0637\u0631\u062d\u200c\u0628\u0646\u062f\u06cc\u200c\u0647\u0627 \u0628\u0627 \u062a\u0637\u0628\u06cc\u0642 \u0628\u0627 \u0627\u0646\u062f\u0627\u0632\u0647\u200c\u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641 \u0635\u0641\u062d\u0647\u060c \u0648 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0645\u0646\u0627\u0637\u0642 \u0634\u0628\u06a9\u0647\u200c\u0627\u06cc \u0646\u0627\u0645\u200c\u06af\u0630\u0627\u0631\u06cc\u200c\u0634\u062f\u0647 \u0628\u0631\u0627\u06cc \u0633\u0627\u062f\u0647\u200c\u0633\u0627\u0632\u06cc \u0642\u0631\u0627\u0631\u06af\u06cc\u0631\u06cc \u0648 \u062a\u0631\u0627\u0632 \u0631\u0627 \u0628\u0631\u0631\u0633\u06cc \u0645\u06cc\u200c\u06a9\u0646\u06cc\u0645.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%DA%A9%D8%A7%D8%B1_%D8%A8%D8%A7_Grid_Properties\"><\/span>\n<p>  \u06a9\u0627\u0631 \u0628\u0627 Grid Properties<br \/>\n<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u062f\u0631 \u0627\u06cc\u0646 \u0628\u062e\u0634\u060c \u0628\u0647 \u062e\u0635\u0648\u0635\u06cc\u0627\u062a \u0627\u0633\u0627\u0633\u06cc \u0634\u0628\u06a9\u0647 \u0645\u06cc \u067e\u0631\u062f\u0627\u0632\u06cc\u0645 \u06a9\u0647 \u0638\u0627\u0647\u0631 \u0648 \u0631\u0641\u062a\u0627\u0631 \u0686\u06cc\u062f\u0645\u0627\u0646 \u0647\u0627\u06cc \u0634\u0628\u06a9\u0647 \u0631\u0627 \u0628\u0647 \u062e\u0648\u0628\u06cc \u062a\u0646\u0638\u06cc\u0645 \u0645\u06cc \u06a9\u0646\u062f.  \u0645\u0627 \u0628\u062d\u062b \u0645\u06cc\u06a9\u0646\u06cc\u0645 <em>\u0634\u0628\u06a9\u0647-\u0627\u0644\u06af\u0648-\u0633\u062a\u0648\u0646 \u0647\u0627<\/em> \u0648 <em>grid-template-rows<\/em>\u060c \u06a9\u0647 \u0627\u0645\u06a9\u0627\u0646 \u062a\u0639\u0627\u0631\u06cc\u0641 \u0635\u0631\u06cc\u062d \u0634\u0628\u06a9\u0647 \u0631\u0627 \u0641\u0631\u0627\u0647\u0645 \u0645\u06cc \u06a9\u0646\u062f.  \u0639\u0644\u0627\u0648\u0647 \u0628\u0631 \u0627\u06cc\u0646\u060c \u0645\u0627 \u0628\u0631\u0631\u0633\u06cc \u0645\u06cc \u06a9\u0646\u06cc\u0645 <em>\u0634\u0628\u06a9\u0647-\u0627\u0644\u06af\u0648-\u0645\u0646\u0627\u0637\u0642<\/em>\u06cc\u06a9 \u0648\u06cc\u0698\u06af\u06cc \u0642\u062f\u0631\u062a\u0645\u0646\u062f \u0628\u0631\u0627\u06cc \u0633\u0627\u0632\u0645\u0627\u0646\u062f\u0647\u06cc \u0628\u0635\u0631\u06cc \u0648 \u0686\u06cc\u062f\u0645\u0627\u0646 \u0622\u06cc\u062a\u0645 \u0647\u0627\u06cc \u0634\u0628\u06a9\u0647.  \u0645\u0627 \u0646\u06cc\u0632 \u067e\u0648\u0634\u0634 \u0645\u06cc \u062f\u0647\u06cc\u0645 <em>\u0634\u06a9\u0627\u0641 \u0634\u0628\u06a9\u0647<\/em> \u0648 <em>\u0634\u0628\u06a9\u0647-\u0631\u062f\u06cc\u0641-\u0634\u06a9\u0627\u0641<\/em>\u060c \u06a9\u0647 \u0641\u0627\u0635\u0644\u0647 \u0628\u06cc\u0646 \u0622\u06cc\u062a\u0645 \u0647\u0627\u06cc \u0634\u0628\u06a9\u0647 \u0631\u0627 \u06a9\u0646\u062a\u0631\u0644 \u0645\u06cc \u06a9\u0646\u062f.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%AA%DA%A9%D9%86%DB%8C%DA%A9_%D9%87%D8%A7%DB%8C_%D8%B4%D8%A8%DA%A9%D9%87_%D9%BE%DB%8C%D8%B4%D8%B1%D9%81%D8%AA%D9%87\"><\/span>\n<p>  \u062a\u06a9\u0646\u06cc\u06a9 \u0647\u0627\u06cc \u0634\u0628\u06a9\u0647 \u067e\u06cc\u0634\u0631\u0641\u062a\u0647<br \/>\n<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0628\u0631\u0627\u06cc \u062a\u0642\u0648\u06cc\u062a \u0628\u06cc\u0634\u062a\u0631 \u0637\u0631\u062d\u200c\u0628\u0646\u062f\u06cc\u200c\u0647\u0627\u06cc \u0634\u0628\u06a9\u0647\u060c \u062a\u06a9\u0646\u06cc\u06a9\u200c\u0647\u0627\u06cc \u067e\u06cc\u0634\u0631\u0641\u062a\u0647\u200c\u0627\u06cc \u0631\u0627 \u06a9\u0647 \u062a\u0648\u0633\u0637 CSS Grid \u0627\u0631\u0627\u0626\u0647 \u0634\u062f\u0647 \u0627\u0633\u062a \u0631\u0627 \u0628\u0631\u0631\u0633\u06cc \u0645\u06cc\u200c\u06a9\u0646\u06cc\u0645.  \u0645\u0627 \u062e\u0637\u0648\u0637 \u0634\u0628\u06a9\u0647 \u0648 \u067e\u0648\u0634\u0634 \u0634\u0628\u06a9\u0647 \u0631\u0627 \u0628\u0631\u0631\u0633\u06cc \u0645\u06cc\u200c\u06a9\u0646\u06cc\u0645\u060c \u06a9\u0647 \u0645\u0627 \u0631\u0627 \u0642\u0627\u062f\u0631 \u0645\u06cc\u200c\u0633\u0627\u0632\u062f \u062a\u0627 \u0622\u06cc\u062a\u0645\u200c\u0647\u0627\u06cc \u0634\u0628\u06a9\u0647 \u0631\u0627 \u062f\u0631 \u0686\u0646\u062f\u06cc\u0646 \u0645\u0633\u06cc\u0631 \u0628\u0686\u0631\u062e\u0627\u0646\u06cc\u0645 \u0648 \u0645\u06a9\u0627\u0646 \u0622\u0646\u0647\u0627 \u0631\u0627 \u062f\u0642\u06cc\u0642\u0627\u064b \u06a9\u0646\u062a\u0631\u0644 \u06a9\u0646\u06cc\u0645.  \u0639\u0644\u0627\u0648\u0647 \u0628\u0631 \u0627\u06cc\u0646\u060c \u0645\u0627 \u0627\u0646\u062f\u0627\u0632\u0647 \u062e\u0648\u062f\u06a9\u0627\u0631 \u0648 \u0648\u0627\u062d\u062f\u0647\u0627\u06cc \u06a9\u0633\u0631\u06cc \u0631\u0627 \u06a9\u0634\u0641 \u0645\u06cc \u06a9\u0646\u06cc\u0645 \u06a9\u0647 \u06af\u0632\u06cc\u0646\u0647 \u0647\u0627\u06cc \u0627\u0646\u0639\u0637\u0627\u0641 \u067e\u0630\u06cc\u0631\u06cc \u0631\u0627 \u0628\u0631\u0627\u06cc \u062a\u0639\u06cc\u06cc\u0646 \u0627\u0646\u062f\u0627\u0632\u0647 \u0633\u062a\u0648\u0646 \u0648 \u0631\u062f\u06cc\u0641 \u0627\u0631\u0627\u0626\u0647 \u0645\u06cc \u062f\u0647\u0646\u062f.  \u0645\u0627 \u0647\u0645\u0686\u0646\u06cc\u0646 \u0628\u0647 \u0628\u0631\u0631\u0633\u06cc \u0642\u0631\u0627\u0631 \u062f\u0627\u062f\u0646 \u062e\u0648\u062f\u06a9\u0627\u0631 \u0634\u0628\u06a9\u0647 \u0645\u06cc \u067e\u0631\u062f\u0627\u0632\u06cc\u0645\u060c \u06a9\u0647 \u0628\u0647 \u0637\u0648\u0631 \u062e\u0648\u062f\u06a9\u0627\u0631 \u0645\u0648\u0627\u0631\u062f \u0634\u0628\u06a9\u0647 \u0631\u0627 \u062f\u0631 \u0634\u0628\u06a9\u0647 \u0642\u0631\u0627\u0631 \u0645\u06cc \u062f\u0647\u062f.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D9%BE%D8%A7%D8%B3%D8%AE%DA%AF%D9%88_%DA%A9%D8%B1%D8%AF%D9%86_%DA%86%DB%8C%D8%AF%D9%85%D8%A7%D9%86_%D9%87%D8%A7%DB%8C_%D8%B4%D8%A8%DA%A9%D9%87\"><\/span>\n<p>  \u067e\u0627\u0633\u062e\u06af\u0648 \u06a9\u0631\u062f\u0646 \u0686\u06cc\u062f\u0645\u0627\u0646 \u0647\u0627\u06cc \u0634\u0628\u06a9\u0647<br \/>\n<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0637\u0631\u0627\u062d\u06cc \u0648\u0628 \u0631\u06cc\u0633\u067e\u0627\u0646\u0633\u06cc\u0648 \u062f\u0631 \u062f\u0646\u06cc\u0627\u06cc \u0645\u0648\u0628\u0627\u06cc\u0644 \u0627\u0648\u0644 \u0627\u0645\u0631\u0648\u0632\u06cc \u0628\u0633\u06cc\u0627\u0631 \u0645\u0647\u0645 \u0627\u0633\u062a.  \u0645\u0627 \u06cc\u0627\u062f \u0645\u06cc\u200c\u06af\u06cc\u0631\u06cc\u0645 \u06a9\u0647 \u0686\u06af\u0648\u0646\u0647 \u0628\u0627 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u067e\u0631\u0633\u0634\u200c\u0647\u0627\u06cc \u0631\u0633\u0627\u0646\u0647\u200c\u0627\u06cc \u0628\u0631\u0627\u06cc \u062a\u0637\u0628\u06cc\u0642 \u0633\u0627\u062e\u062a\u0627\u0631 \u0634\u0628\u06a9\u0647 \u0648 \u0642\u0631\u0627\u0631\u06af\u06cc\u0631\u06cc \u0622\u06cc\u062a\u0645 \u0628\u0631 \u0627\u0633\u0627\u0633 \u0627\u0646\u062f\u0627\u0632\u0647\u200c\u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641 \u0635\u0641\u062d\u0647 \u0646\u0645\u0627\u06cc\u0634\u060c \u0686\u06cc\u062f\u0645\u0627\u0646\u200c\u0647\u0627\u06cc \u0634\u0628\u06a9\u0647\u200c\u0627\u06cc \u062e\u0648\u062f \u0631\u0627 \u067e\u0627\u0633\u062e\u06af\u0648 \u06a9\u0646\u06cc\u0645.  \u0628\u0627 \u0628\u0647 \u06a9\u0627\u0631\u06af\u06cc\u0631\u06cc \u062a\u06a9\u0646\u06cc\u06a9 \u0647\u0627\u06cc\u06cc \u0645\u0627\u0646\u0646\u062f \u0634\u0628\u06a9\u0647 \u0647\u0627\u06cc \u0633\u06cc\u0627\u0644 \u0648 <em>\u0634\u0628\u06a9\u0647-\u0627\u0644\u06af\u0648-\u0645\u0646\u0627\u0637\u0642<\/em>\u060c \u0645\u06cc \u062a\u0648\u0627\u0646\u06cc\u0645 \u0637\u0631\u062d \u0628\u0646\u062f\u06cc \u0647\u0627\u06cc\u06cc \u0627\u06cc\u062c\u0627\u062f \u06a9\u0646\u06cc\u0645 \u06a9\u0647 \u0628\u0647 \u0637\u0648\u0631 \u06cc\u06a9\u067e\u0627\u0631\u0686\u0647 \u0628\u0627 \u062f\u0633\u062a\u06af\u0627\u0647 \u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641 \u062a\u0646\u0638\u06cc\u0645 \u0634\u0648\u0646\u062f.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%AA%D8%B1%DA%A9%DB%8C%D8%A8_CSS_Grid_%D8%A8%D8%A7_%D8%B3%D8%A7%DB%8C%D8%B1_%D8%B1%D9%88%D8%B4_%D9%87%D8%A7%DB%8C_Layout\"><\/span>\n<p>  \u062a\u0631\u06a9\u06cc\u0628 CSS Grid \u0628\u0627 \u0633\u0627\u06cc\u0631 \u0631\u0648\u0634 \u0647\u0627\u06cc Layout<br \/>\n<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>CSS Grid \u0631\u0627 \u0645\u06cc \u062a\u0648\u0627\u0646 \u0628\u0627 \u0633\u0627\u06cc\u0631 \u0631\u0648\u0634 \u0647\u0627\u06cc \u0686\u06cc\u062f\u0645\u0627\u0646 \u062a\u0631\u06a9\u06cc\u0628 \u06a9\u0631\u062f \u062a\u0627 \u0628\u0647 \u0637\u0631\u0627\u062d\u06cc \u0647\u0627\u06cc \u0642\u062f\u0631\u062a\u0645\u0646\u062f\u062a\u0631 \u0648 \u0627\u0646\u0639\u0637\u0627\u0641 \u067e\u0630\u06cc\u0631\u062a\u0631\u06cc \u062f\u0633\u062a \u06cc\u0627\u0641\u062a.  \u0645\u0627 \u0686\u06af\u0648\u0646\u06af\u06cc \u0627\u062f\u063a\u0627\u0645 CSS Flexbox \u0631\u0627 \u062f\u0631 \u06a9\u0646\u0627\u0631 CSS Grid \u0628\u0631\u0627\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0646\u0642\u0627\u0637 \u0642\u0648\u062a \u0647\u0631 \u062f\u0648 \u062a\u06a9\u0646\u06cc\u06a9 \u0628\u0631\u0631\u0633\u06cc \u0645\u06cc \u06a9\u0646\u06cc\u0645.  \u0639\u0644\u0627\u0648\u0647 \u0628\u0631 \u0627\u06cc\u0646\u060c \u062f\u0631 \u0645\u0648\u0631\u062f \u0627\u06cc\u062c\u0627\u062f \u0634\u0628\u06a9\u0647\u200c\u0647\u0627 \u062f\u0631 \u0634\u0628\u06a9\u0647\u200c\u0647\u0627 \u0628\u0631\u0627\u06cc \u0627\u06cc\u062c\u0627\u062f \u0637\u0631\u062d\u200c\u0628\u0646\u062f\u06cc\u200c\u0647\u0627\u06cc \u062a\u0648\u062f\u0631\u062a\u0648 \u067e\u06cc\u0686\u06cc\u062f\u0647 \u0628\u062d\u062b \u0645\u06cc\u200c\u06a9\u0646\u06cc\u0645.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%A8%D9%87%DB%8C%D9%86%D9%87_%D8%B3%D8%A7%D8%B2%DB%8C_%D8%B9%D9%85%D9%84%DA%A9%D8%B1%D8%AF_%D8%B4%D8%A8%DA%A9%D9%87\"><\/span>\n<p>  \u0628\u0647\u06cc\u0646\u0647 \u0633\u0627\u0632\u06cc \u0639\u0645\u0644\u06a9\u0631\u062f \u0634\u0628\u06a9\u0647<br \/>\n<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0639\u0645\u0644\u06a9\u0631\u062f \u0634\u0628\u06a9\u0647 \u06a9\u0627\u0631\u0622\u0645\u062f \u0628\u0631\u0627\u06cc \u0627\u0631\u0627\u0626\u0647 \u06cc\u06a9 \u062a\u062c\u0631\u0628\u0647 \u06a9\u0627\u0631\u0628\u0631\u06cc \u0631\u0648\u0627\u0646 \u0628\u0633\u06cc\u0627\u0631 \u0645\u0647\u0645 \u0627\u0633\u062a.  \u0645\u0627 \u062f\u0631 \u0645\u0648\u0631\u062f \u062a\u06a9\u0646\u06cc\u06a9\u200c\u0647\u0627\u06cc\u06cc \u0628\u0631\u0627\u06cc \u0628\u0647\u06cc\u0646\u0647\u200c\u0633\u0627\u0632\u06cc \u0631\u0646\u062f\u0631 \u0648 \u0632\u0645\u0627\u0646 \u0686\u06cc\u062f\u0645\u0627\u0646 \u0634\u0628\u06a9\u0647\u060c \u0627\u0632 \u062c\u0645\u0644\u0647 \u0628\u0647 \u062d\u062f\u0627\u0642\u0644 \u0631\u0633\u0627\u0646\u062f\u0646 \u062a\u0639\u062f\u0627\u062f \u0622\u06cc\u062a\u0645\u200c\u0647\u0627\u06cc \u0634\u0628\u06a9\u0647 \u0648 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0628\u0647\u062a\u0631\u06cc\u0646 \u0634\u06cc\u0648\u0647\u200c\u0647\u0627\u06cc \u0639\u0645\u0644\u06a9\u0631\u062f \u0634\u0628\u06a9\u0647 CSS \u0628\u062d\u062b \u0645\u06cc\u200c\u06a9\u0646\u06cc\u0645.  \u0628\u0627 \u0627\u062c\u0631\u0627\u06cc \u0627\u06cc\u0646 \u0627\u0633\u062a\u0631\u0627\u062a\u0698\u06cc \u0647\u0627\u060c \u0645\u06cc \u062a\u0648\u0627\u0646\u06cc\u0645 \u0636\u0645\u0646 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 CSS Grid\u060c \u0639\u0645\u0644\u06a9\u0631\u062f \u0628\u0647\u06cc\u0646\u0647 \u0631\u0627 \u062a\u0636\u0645\u06cc\u0646 \u06a9\u0646\u06cc\u0645.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D9%86%D8%AA%DB%8C%D8%AC%D9%87\"><\/span>\n<p>  \u0646\u062a\u06cc\u062c\u0647<br \/>\n<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>CSS Grid \u0628\u0647 \u062a\u0648\u0633\u0639\u0647 \u062f\u0647\u0646\u062f\u06af\u0627\u0646 \u0648\u0628 \u0627\u06cc\u0646 \u0627\u0645\u06a9\u0627\u0646 \u0631\u0627 \u0645\u06cc \u062f\u0647\u062f \u06a9\u0647 \u0628\u062f\u0648\u0646 \u0632\u062d\u0645\u062a \u0637\u0631\u062d \u0628\u0646\u062f\u06cc \u0647\u0627\u06cc \u067e\u06cc\u0686\u06cc\u062f\u0647\u060c \u0627\u0646\u0639\u0637\u0627\u0641 \u067e\u0630\u06cc\u0631 \u0648 \u067e\u0627\u0633\u062e\u06af\u0648 \u0627\u06cc\u062c\u0627\u062f \u06a9\u0646\u0646\u062f.  \u062f\u0631 \u0627\u06cc\u0646 \u0631\u0627\u0647\u0646\u0645\u0627\u06cc \u062c\u0627\u0645\u0639\u060c \u0645\u0641\u0627\u0647\u06cc\u0645\u060c \u200b\u200b\u062a\u06a9\u0646\u06cc\u06a9\u200c\u0647\u0627 \u0648 \u0648\u06cc\u0698\u06af\u06cc\u200c\u0647\u0627\u06cc \u06a9\u0644\u06cc\u062f\u06cc CSS Grid \u0631\u0627 \u0628\u0631\u0631\u0633\u06cc \u06a9\u0631\u062f\u0647\u200c\u0627\u06cc\u0645.  \u0628\u0627 \u0622\u0632\u0645\u0627\u06cc\u0634\u060c \u062a\u0645\u0631\u06cc\u0646 \u0648 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0642\u0627\u0628\u0644\u06cc\u062a\u200c\u0647\u0627\u06cc CSS Grid\u060c \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u0627\u0645\u06a9\u0627\u0646\u0627\u062a \u0628\u06cc\u200c\u067e\u0627\u06cc\u0627\u0646\u06cc \u0631\u0627 \u0628\u0631\u0627\u06cc \u0627\u06cc\u062c\u0627\u062f \u0637\u0631\u062d\u200c\u0628\u0646\u062f\u06cc\u200c\u0647\u0627\u06cc \u0648\u0628 \u0627\u0632 \u0646\u0638\u0631 \u0628\u0635\u0631\u06cc \u062e\u06cc\u0631\u0647\u200c\u06a9\u0646\u0646\u062f\u0647 \u0648 \u0633\u0627\u0632\u06af\u0627\u0631 \u0628\u0627\u0632 \u06a9\u0646\u06cc\u062f.  CSS Grid \u0631\u0627 \u062f\u0631 \u0622\u063a\u0648\u0634 \u0628\u06af\u06cc\u0631\u06cc\u062f \u0648 \u0645\u0647\u0627\u0631\u062a \u0647\u0627\u06cc \u0637\u0631\u0627\u062d\u06cc \u0648\u0628 \u062e\u0648\u062f \u0631\u0627 \u0628\u0647 \u0627\u0631\u062a\u0641\u0627\u0639\u0627\u062a \u062c\u062f\u06cc\u062f\u06cc \u0628\u0628\u0631\u06cc\u062f!<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u062f\u0631 \u0686\u0634\u0645\u200c\u0627\u0646\u062f\u0627\u0632 \u062a\u0648\u0633\u0639\u0647 \u0648\u0628 \u0627\u0645\u0631\u0648\u0632\u06cc\u060c \u0627\u06cc\u062c\u0627\u062f \u0637\u0631\u062d\u200c\u0628\u0646\u062f\u06cc\u200c\u0647\u0627\u06cc \u0627\u0646\u0639\u0637\u0627\u0641\u200c\u067e\u0630\u06cc\u0631 \u0648 \u067e\u0627\u0633\u062e\u200c\u06af\u0648 \u0628\u0631\u0627\u06cc \u0627\u0637\u0645\u06cc\u0646\u0627\u0646 \u0627\u0632 \u062a\u062c\u0631\u0628\u0647 \u06a9\u0627\u0631\u0628\u0631\u06cc \u0628\u0647\u06cc\u0646\u0647 \u062f\u0631 \u062f\u0633\u062a\u06af\u0627\u0647\u200c\u0647\u0627 \u0648 \u0627\u0646\u062f\u0627\u0632\u0647\u200c\u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641 \u0635\u0641\u062d\u0647 \u0646\u0645\u0627\u06cc\u0634 \u0636\u0631\u0648\u0631\u06cc \u0627\u0633\u062a. CSS Grid\u060c \u06cc\u06a9 \u0645\u0627\u0698\u0648\u0644 \u0637\u0631\u062d\u200c\u0628\u0646\u062f\u06cc \u0642\u062f\u0631\u062a\u0645\u0646\u062f \u0645\u0639\u0631\u0641\u06cc \u0634\u062f\u0647 \u062f\u0631 CSS3\u060c \u0631\u0627\u0647\u200c\u062d\u0644\u06cc \u062c\u0627\u0645\u0639 \u0628\u0631\u0627\u06cc \u0633\u0627\u062e\u062a \u0637\u0631\u062d\u200c\u0628\u0646\u062f\u06cc\u200c\u0647\u0627\u06cc \u067e\u06cc\u0686\u06cc\u062f\u0647 \u0645\u0628\u062a\u0646\u06cc \u0628\u0631 \u0634\u0628\u06a9\u0647 \u0628\u0647 \u0631\u0627\u062d\u062a\u06cc \u0627\u0631\u0627\u0626\u0647 \u0645\u06cc\u200c\u062f\u0647\u062f. \u062f\u0631 \u0627\u06cc\u0646 \u0631\u0627\u0647\u0646\u0645\u0627\u060c CSS Grid \u0631\u0627 \u0628\u0647 &hellip;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[339],"tags":[],"class_list":["post-25627","post","type-post","status-publish","format-standard","hentry","category-dev"],"_links":{"self":[{"href":"https:\/\/nabfollower.com\/blog\/wp-json\/wp\/v2\/posts\/25627","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nabfollower.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nabfollower.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nabfollower.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/nabfollower.com\/blog\/wp-json\/wp\/v2\/comments?post=25627"}],"version-history":[{"count":0,"href":"https:\/\/nabfollower.com\/blog\/wp-json\/wp\/v2\/posts\/25627\/revisions"}],"wp:attachment":[{"href":"https:\/\/nabfollower.com\/blog\/wp-json\/wp\/v2\/media?parent=25627"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nabfollower.com\/blog\/wp-json\/wp\/v2\/categories?post=25627"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nabfollower.com\/blog\/wp-json\/wp\/v2\/tags?post=25627"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}