{"id":27959,"date":"2023-06-24T00:22:42","date_gmt":"2023-06-23T20:52:42","guid":{"rendered":"https:\/\/nabfollower.com\/blog\/deal-cancelled-bitgo-pulls-out-of-prime-trust-acquisition-users-report-withdrawal-issues-htm\/"},"modified":"2023-06-24T00:22:42","modified_gmt":"2023-06-23T20:52:42","slug":"deal-cancelled-bitgo-pulls-out-of-prime-trust-acquisition-users-report-withdrawal-issues-htm","status":"publish","type":"post","link":"https:\/\/nabfollower.com\/blog\/deal-cancelled-bitgo-pulls-out-of-prime-trust-acquisition-users-report-withdrawal-issues-htm\/","title":{"rendered":"BitGo \u0627\u0632 Prime Trust Acquisition \u062e\u0627\u0631\u062c \u0645\u06cc \u0634\u0648\u062f \u0648 \u06a9\u0627\u0631\u0628\u0631\u0627\u0646 \u0645\u0634\u06a9\u0644\u0627\u062a \u0645\u0631\u0628\u0648\u0637 \u0628\u0647 \u0628\u0631\u062f\u0627\u0634\u062a \u0631\u0627 \u06af\u0632\u0627\u0631\u0634 \u0645\u06cc \u06a9\u0646\u0646\u062f"},"content":{"rendered":"<div>\n<figure class=\"image\"><figcaption>\u0645\u0646\u0628\u0639: Pexels\/Canva<\/figcaption><\/figure>\n<p>BitGo\u060c \u067e\u0644\u062a\u0641\u0631\u0645 \u0645\u062a\u0648\u0644\u06cc \u0627\u0631\u0632\u0647\u0627\u06cc \u062f\u06cc\u062c\u06cc\u062a\u0627\u0644 \u0622\u0645\u0631\u06cc\u06a9\u0627\u060c \u062a\u0635\u0645\u06cc\u0645 \u06af\u0631\u0641\u062a\u0647 \u0627\u0633\u062a \u06a9\u0647 \u062e\u0631\u06cc\u062f Prime Trust \u0631\u0627 \u0644\u063a\u0648 \u06a9\u0646\u062f. <\/p>\n<p>\u067e\u0633 \u0627\u0632 \u0627\u06cc\u0646 \u0627\u0639\u0644\u0627\u0645\u06cc\u0647\u060c Prime Trust \u0627\u0642\u062f\u0627\u0645\u0627\u062a\u06cc \u0631\u0627 \u0628\u0631\u0627\u06cc \u062a\u0639\u0644\u06cc\u0642 \u0628\u0631\u062f\u0627\u0634\u062a \u0647\u0627 \u0627\u0646\u062c\u0627\u0645 \u062f\u0627\u062f\u0647 \u0627\u0633\u062a.<\/p>\n<p>\u0644\u063a\u0648 \u0642\u0631\u0627\u0631\u062f\u0627\u062f \u062a\u0646\u0647\u0627 \u062f\u0648 \u0647\u0641\u062a\u0647 \u067e\u0633 \u0627\u0632 \u0627\u0645\u0636\u0627\u06cc \u0646\u0627\u0645\u0647 \u063a\u06cc\u0631 \u0627\u0644\u0632\u0627\u0645 \u0622\u0648\u0631 BitGo \u0628\u0631\u0627\u06cc \u062e\u0631\u06cc\u062f Prime Trust \u0635\u0648\u0631\u062a \u06af\u0631\u0641\u062a.<\/p>\n<figure class=\"media\"><oembed data-embedo-height=\"400\" data-embedo-url=\"https:\/\/twitter.com\/BitGo\/status\/1671869979321577472\" loading=\"lazy\"\/><\/figure>\n<p>\u0627\u0646\u062a\u0638\u0627\u0631 \u0645\u06cc \u0631\u0641\u062a \u06a9\u0647 \u062e\u0631\u06cc\u062f Prime Trust \u062a\u0648\u0633\u0637 BitGo \u0627\u0632 Prime Trust \u062d\u0645\u0627\u06cc\u062a \u0645\u0627\u0644\u06cc \u06a9\u0646\u062f \u06a9\u0647 \u0628\u0627 \u0686\u0627\u0644\u0634 \u0647\u0627\u06cc \u0648\u0631\u0634\u06a9\u0633\u062a\u06af\u06cc \u0631\u0648\u0628\u0631\u0648 \u0634\u062f\u0647 \u0627\u0633\u062a.<\/p>\n<p>\u062f\u0631 \u0627\u0648\u0627\u06cc\u0644 \u0627\u06cc\u0646 \u0645\u0627\u0647\u060c \u0628\u0627\u0646\u06a9\u060c \u0632\u06cc\u0631\u0645\u062c\u0645\u0648\u0639\u0647 \u067e\u0631\u062f\u0627\u062e\u062a \u0647\u0627\u06cc \u067e\u0631\u0627\u06cc\u0645 \u062a\u0631\u0627\u0633\u062a\u060c \u062f\u0631\u062e\u0648\u0627\u0633\u062a \u062d\u0645\u0627\u06cc\u062a \u0627\u0632 \u0648\u0631\u0634\u06a9\u0633\u062a\u06af\u06cc \u062f\u0631 \u0627\u06cc\u0627\u0644\u0627\u062a \u0645\u062a\u062d\u062f\u0647 \u0631\u0627 \u0627\u0631\u0627\u0626\u0647 \u06a9\u0631\u062f. <\/p>\n<p>\u0628\u0631 \u0627\u0633\u0627\u0633 \u067e\u0631\u0648\u0646\u062f\u0647 \u0648\u0631\u0634\u06a9\u0633\u062a\u06af\u06cc\u060c \u0628\u0627\u0646\u06a9 \u062f\u0627\u0631\u0627\u06cc\u06cc\u200c\u0647\u0627\u06cc\u06cc \u0628\u0627\u0644\u063a \u0628\u0631 17.72 \u0645\u06cc\u0644\u06cc\u0648\u0646 \u062f\u0644\u0627\u0631 \u0648 \u0628\u062f\u0647\u06cc\u200c\u0647\u0627\u06cc\u06cc \u0628\u0627\u0644\u063a \u0628\u0631 5.4 \u0645\u06cc\u0644\u06cc\u0648\u0646 \u062f\u0644\u0627\u0631 \u0627\u0633\u062a.<\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter-rtl ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u0641\u0647\u0631\u0633\u062a \u0645\u0637\u0627\u0644\u0628<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"\u062a\u063a\u06cc\u06cc\u0631 \u0648\u0636\u0639\u06cc\u062a \u0641\u0647\u0631\u0633\u062a \u0645\u0637\u0627\u0644\u0628\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/nabfollower.com\/blog\/deal-cancelled-bitgo-pulls-out-of-prime-trust-acquisition-users-report-withdrawal-issues-htm\/#%D9%BE%D8%B1%D8%A7%DB%8C%D9%85_%D8%AA%D8%B1%D8%A7%D8%B3%D8%AA_%D9%87%DB%8C%DA%86_%D8%A2%D8%B1%D8%A7%D9%85%D8%B4%DB%8C_%D9%BE%DB%8C%D8%AF%D8%A7_%D9%86%D9%85%DB%8C_%DA%A9%D9%86%D8%AF\" >\u067e\u0631\u0627\u06cc\u0645 \u062a\u0631\u0627\u0633\u062a \u0647\u06cc\u0686 \u0622\u0631\u0627\u0645\u0634\u06cc \u067e\u06cc\u062f\u0627 \u0646\u0645\u06cc \u06a9\u0646\u062f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/nabfollower.com\/blog\/deal-cancelled-bitgo-pulls-out-of-prime-trust-acquisition-users-report-withdrawal-issues-htm\/#TrueUSD_%D9%82%D8%B1%D8%A7%D8%B1_%DA%AF%D8%B1%D9%81%D8%AA%D9%86_%D8%AF%D8%B1_%D9%85%D8%B9%D8%B1%D8%B6_Prime_Trust_%D8%B1%D8%A7_%D8%B1%D8%AF_%D9%85%DB%8C_%DA%A9%D9%86%D8%AF\" >TrueUSD \u0642\u0631\u0627\u0631 \u06af\u0631\u0641\u062a\u0646 \u062f\u0631 \u0645\u0639\u0631\u0636 Prime Trust \u0631\u0627 \u0631\u062f \u0645\u06cc \u06a9\u0646\u062f<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"%D9%BE%D8%B1%D8%A7%DB%8C%D9%85_%D8%AA%D8%B1%D8%A7%D8%B3%D8%AA_%D9%87%DB%8C%DA%86_%D8%A2%D8%B1%D8%A7%D9%85%D8%B4%DB%8C_%D9%BE%DB%8C%D8%AF%D8%A7_%D9%86%D9%85%DB%8C_%DA%A9%D9%86%D8%AF\"><\/span>\u067e\u0631\u0627\u06cc\u0645 \u062a\u0631\u0627\u0633\u062a \u0647\u06cc\u0686 \u0622\u0631\u0627\u0645\u0634\u06cc \u067e\u06cc\u062f\u0627 \u0646\u0645\u06cc \u06a9\u0646\u062f  <span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u067e\u0631\u0627\u06cc\u0645 \u062a\u0631\u0627\u0633\u062a \u0627\u062e\u06cc\u0631\u0627\u064b \u0628\u0627 \u0686\u0627\u0644\u0634 \u0647\u0627\u06cc\u06cc \u0645\u0648\u0627\u062c\u0647 \u0634\u062f\u0647 \u0627\u0633\u062a\u060c \u0627\u0632 \u062c\u0645\u0644\u0647 \u062c\u0627\u06cc\u06af\u0632\u06cc\u0646\u06cc \u0645\u062f\u06cc\u0631\u0639\u0627\u0645\u0644 \u062a\u0627\u0645 \u067e\u06cc\u06af\u0631 \u062f\u0631 \u0646\u0648\u0627\u0645\u0628\u0631 \u0648 \u0627\u062e\u0631\u0627\u062c \u06a9\u0627\u0631\u06a9\u0646\u0627\u0646 \u062f\u0631 \u0698\u0627\u0646\u0648\u06cc\u0647. <\/p>\n<p>\u0639\u0644\u0627\u0648\u0647 \u0628\u0631 \u0627\u06cc\u0646\u060c \u0633\u0627\u0644 \u06af\u0630\u0634\u062a\u0647\u060c \u0634\u0631\u06a9\u062a \u0648\u0627\u0645\u200c\u062f\u0647\u0646\u062f\u0647 \u06a9\u0631\u06cc\u067e\u062a\u0648 \u0633\u0644\u0633\u06cc\u0648\u0633\u060c \u0628\u0647 \u062f\u0644\u06cc\u0644 \u0631\u0633\u06cc\u062f\u06af\u06cc \u0628\u0647 \u0648\u0631\u0634\u06a9\u0633\u062a\u06af\u06cc\u060c \u062f\u0648 \u0634\u06a9\u0627\u06cc\u062a \u0631\u0627 \u0628\u0631\u0627\u06cc \u0628\u0627\u0632\u06cc\u0627\u0628\u06cc \u0648\u062c\u0648\u0647 \u0627\u0631\u0627\u0626\u0647 \u06a9\u0631\u062f.  \u067e\u0631\u0627\u06cc\u0645 \u062a\u0631\u0627\u0633\u062a \u06cc\u06a9\u06cc \u0627\u0632 \u0627\u0647\u062f\u0627\u0641 \u0627\u06cc\u0646 \u062f\u0639\u0627\u0648\u06cc \u0628\u0648\u062f. <\/p>\n<p>\u0633\u0644\u0633\u06cc\u0648\u0633 \u0627\u062f\u0639\u0627 \u06a9\u0631\u062f \u06a9\u0647 \u067e\u0631\u0627\u06cc\u0645 \u062a\u0631\u0627\u0633\u062a \u0632\u0645\u0627\u0646\u06cc \u06a9\u0647 \u0627\u06cc\u0646 \u062f\u0648 \u0642\u0631\u0627\u0631\u062f\u0627\u062f \u062e\u0648\u062f \u0631\u0627 \u062f\u0631 \u0698\u0648\u0626\u0646 2021 \u0641\u0633\u062e \u06a9\u0631\u062f\u0646\u062f\u060c \u062a\u0648\u06a9\u0646\u200c\u0647\u0627 \u0631\u0627 \u0628\u0647\u200c\u0637\u0648\u0631 \u0646\u0627\u062f\u0631\u0633\u062a \u067e\u0646\u0647\u0627\u0646 \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a.<\/p>\n<p>\u062f\u0631 \u0622\u06af\u0648\u0633\u062a \u0633\u0627\u0644 \u06af\u0630\u0634\u062a\u0647\u060c \u067e\u0631\u0627\u06cc\u0645 \u062a\u0631\u0627\u0633\u062a \u0628\u0627 \u0628\u0627\u0632\u067e\u0631\u062f\u0627\u062e\u062a \u062a\u0648\u06a9\u0646 \u0647\u0627\u06cc \u0631\u0645\u0632\u0646\u06af\u0627\u0631\u06cc \u0628\u0647 \u0627\u0631\u0632\u0634 17 \u0645\u06cc\u0644\u06cc\u0648\u0646 \u062f\u0644\u0627\u0631 \u0628\u0647 \u0633\u0644\u0633\u06cc\u0648\u0633 \u0645\u0648\u0627\u0641\u0642\u062a \u06a9\u0631\u062f. <\/p>\n<h2><span class=\"ez-toc-section\" id=\"TrueUSD_%D9%82%D8%B1%D8%A7%D8%B1_%DA%AF%D8%B1%D9%81%D8%AA%D9%86_%D8%AF%D8%B1_%D9%85%D8%B9%D8%B1%D8%B6_Prime_Trust_%D8%B1%D8%A7_%D8%B1%D8%AF_%D9%85%DB%8C_%DA%A9%D9%86%D8%AF\"><\/span>TrueUSD \u0642\u0631\u0627\u0631 \u06af\u0631\u0641\u062a\u0646 \u062f\u0631 \u0645\u0639\u0631\u0636 Prime Trust \u0631\u0627 \u0631\u062f \u0645\u06cc \u06a9\u0646\u062f<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u067e\u0633 \u0627\u0632 \u0627\u0646\u062a\u0634\u0627\u0631 \u06af\u0632\u0627\u0631\u0634\u200c\u0647\u0627\u06cc\u06cc \u0645\u0628\u0646\u06cc \u0628\u0631 \u062a\u0639\u0644\u06cc\u0642 \u0633\u067e\u0631\u062f\u0647\u200c\u0647\u0627 \u0648 \u0628\u0631\u062f\u0627\u0634\u062a\u200c\u0647\u0627\u06cc \u067e\u0631\u0627\u06cc\u0645 \u062a\u0631\u0627\u0633\u062a \u062f\u0631 \u0631\u0648\u0632 \u067e\u0646\u062c\u0634\u0646\u0628\u0647\u060c \u0646\u0627\u0634\u0631 TUSD TrueUSD \u0628\u0647 \u0645\u0634\u062a\u0631\u06cc\u0627\u0646 \u062e\u0648\u062f \u0627\u0637\u0645\u06cc\u0646\u0627\u0646 \u062f\u0627\u062f \u06a9\u0647 \u0647\u06cc\u0686 \u062a\u0645\u0627\u0633\u06cc \u0628\u0627 \u0627\u06cc\u0646 \u0634\u0631\u06a9\u062a \u0631\u0645\u0632\u0646\u06af\u0627\u0631\u06cc \u0645\u0634\u06a9\u0644\u200c\u062f\u0627\u0631 \u0646\u062f\u0627\u0631\u062f.<\/p>\n<p>\u0646\u0627\u0634\u0631 \u0627\u0633\u062a\u06cc\u0628\u0644 \u06a9\u0648\u06cc\u0646 \u0628\u0627 \u067e\u0634\u062a\u0648\u0627\u0646\u0647 \u062f\u0644\u0627\u0631 \u0647\u0645\u0686\u0646\u06cc\u0646 \u0627\u0639\u0644\u0627\u0645 \u06a9\u0631\u062f \u06a9\u0647 \u062f\u06cc\u06af\u0631 \u0627\u0632 Prime Trust \u0628\u0631\u0627\u06cc \u0636\u0631\u0628 \u06cc\u0627 \u0628\u0627\u0632\u062e\u0631\u06cc\u062f \u0627\u0633\u062a\u06cc\u0628\u0644 \u06a9\u0648\u06cc\u0646 TUSD \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0646\u0645\u06cc \u06a9\u0646\u062f \u0648 \u062f\u0631 \u062c\u0627\u0647\u0627\u06cc \u062f\u06cc\u06af\u0631 \u00ab\u0631\u0627\u0647 \u0622\u0647\u0646 \u0647\u0627\u06cc \u0686\u0646\u062f \u062f\u0644\u0627\u0631\u06cc\u00bb \u0631\u0627 \u062d\u0641\u0638 \u0645\u06cc \u06a9\u0646\u062f. <\/p>\n<figure class=\"media\"><oembed data-embedo-height=\"400\" data-embedo-url=\"https:\/\/twitter.com\/tusdio\/status\/1671898163039596544?s=20\" loading=\"lazy\"\/><\/figure>\n<p>\u062f\u0631 \u062d\u0627\u0644\u06cc \u06a9\u0647 \u0635\u0627\u062f\u0631\u06a9\u0646\u0646\u062f\u0647 TUSD \u0627\u0632 \u067e\u0644\u062a\u0641\u0631\u0645 \u0645\u062a\u0648\u0644\u06cc \u06a9\u0631\u06cc\u067e\u062a\u0648 \u0645\u0634\u06a9\u0644 \u062f\u0627\u0631 \u0641\u0627\u0635\u0644\u0647 \u06af\u0631\u0641\u062a\u060c \u0635\u0631\u0627\u0641\u06cc \u0631\u0645\u0632\u0627\u0631\u0632 \u06a9\u0648\u06cc\u0646 \u0645\u062a\u0631\u0648 \u0645\u062c\u0628\u0648\u0631 \u0634\u062f \u0628\u0631\u062f\u0627\u0634\u062a \u062f\u0644\u0627\u0631 \u0631\u0627 \u0627\u0632 \u067e\u0644\u062a\u0641\u0631\u0645 \u062e\u0648\u062f \u0645\u062a\u0648\u0642\u0641 \u06a9\u0646\u062f \u0632\u06cc\u0631\u0627 \u0627\u0632 Prime Trust \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u0634\u0631\u06cc\u06a9 \u067e\u0631\u062f\u0627\u062e\u062a \u062e\u0648\u062f \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc \u06a9\u0646\u062f. <\/p>\n<p>\u0627\u06cc\u0646 \u0635\u0631\u0627\u0641\u06cc \u062f\u0631 \u062a\u0648\u06cc\u06cc\u062a\u0631 \u0627\u0639\u0644\u0627\u0645 \u06a9\u0631\u062f \u06a9\u0647 \u062f\u0631 \u062d\u0627\u0644 \u062d\u0627\u0636\u0631 \u06a9\u0627\u0631 \u0631\u0648\u06cc \u0627\u0636\u0627\u0641\u0647 \u06a9\u0631\u062f\u0646 \u0634\u0631\u06a9\u0627\u06cc \u067e\u0631\u062f\u0627\u062e\u062a \u062c\u0627\u06cc\u06af\u0632\u06cc\u0646 \u0628\u0647 \u0627\u06a9\u0648\u0633\u06cc\u0633\u062a\u0645 \u062e\u0648\u062f \u0631\u0627 \u0622\u063a\u0627\u0632 \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a.<\/p>\n<\/p><\/div>\n<p><script async src=\"\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0645\u0646\u0628\u0639: Pexels\/Canva BitGo\u060c \u067e\u0644\u062a\u0641\u0631\u0645 \u0645\u062a\u0648\u0644\u06cc \u0627\u0631\u0632\u0647\u0627\u06cc \u062f\u06cc\u062c\u06cc\u062a\u0627\u0644 \u0622\u0645\u0631\u06cc\u06a9\u0627\u060c \u062a\u0635\u0645\u06cc\u0645 \u06af\u0631\u0641\u062a\u0647 \u0627\u0633\u062a \u06a9\u0647 \u062e\u0631\u06cc\u062f Prime Trust \u0631\u0627 \u0644\u063a\u0648 \u06a9\u0646\u062f. \u067e\u0633 \u0627\u0632 \u0627\u06cc\u0646 \u0627\u0639\u0644\u0627\u0645\u06cc\u0647\u060c Prime Trust \u0627\u0642\u062f\u0627\u0645\u0627\u062a\u06cc \u0631\u0627 \u0628\u0631\u0627\u06cc \u062a\u0639\u0644\u06cc\u0642 \u0628\u0631\u062f\u0627\u0634\u062a \u0647\u0627 \u0627\u0646\u062c\u0627\u0645 \u062f\u0627\u062f\u0647 \u0627\u0633\u062a. \u0644\u063a\u0648 \u0642\u0631\u0627\u0631\u062f\u0627\u062f \u062a\u0646\u0647\u0627 \u062f\u0648 \u0647\u0641\u062a\u0647 \u067e\u0633 \u0627\u0632 \u0627\u0645\u0636\u0627\u06cc \u0646\u0627\u0645\u0647 \u063a\u06cc\u0631 \u0627\u0644\u0632\u0627\u0645 \u0622\u0648\u0631 BitGo \u0628\u0631\u0627\u06cc \u062e\u0631\u06cc\u062f Prime Trust \u0635\u0648\u0631\u062a \u06af\u0631\u0641\u062a. \u0627\u0646\u062a\u0638\u0627\u0631 \u0645\u06cc \u0631\u0641\u062a &hellip;<\/p>\n","protected":false},"author":2,"featured_media":27960,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-27959","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cryptocurrency"],"_links":{"self":[{"href":"https:\/\/nabfollower.com\/blog\/wp-json\/wp\/v2\/posts\/27959","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nabfollower.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nabfollower.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nabfollower.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/nabfollower.com\/blog\/wp-json\/wp\/v2\/comments?post=27959"}],"version-history":[{"count":0,"href":"https:\/\/nabfollower.com\/blog\/wp-json\/wp\/v2\/posts\/27959\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nabfollower.com\/blog\/wp-json\/wp\/v2\/media\/27960"}],"wp:attachment":[{"href":"https:\/\/nabfollower.com\/blog\/wp-json\/wp\/v2\/media?parent=27959"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nabfollower.com\/blog\/wp-json\/wp\/v2\/categories?post=27959"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nabfollower.com\/blog\/wp-json\/wp\/v2\/tags?post=27959"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}