{"id":6280,"date":"2023-02-15T20:23:31","date_gmt":"2023-02-15T16:53:31","guid":{"rendered":"https:\/\/nabfollower.com\/blog\/enemies-to-lovers-romances-in-video-games\/"},"modified":"2023-02-15T20:23:31","modified_gmt":"2023-02-15T16:53:31","slug":"enemies-to-lovers-romances-in-video-games","status":"publish","type":"post","link":"https:\/\/nabfollower.com\/blog\/enemies-to-lovers-romances-in-video-games\/","title":{"rendered":"8 \u0628\u0647\u062a\u0631\u06cc\u0646 \u062f\u0634\u0645\u0646\u0627\u0646 \u0639\u0627\u0634\u0642\u0627\u0646 \u0639\u0627\u0634\u0642\u0627\u0646\u0647 \u062f\u0631 \u0628\u0627\u0632\u06cc \u0647\u0627"},"content":{"rendered":"<div id=\"article-body\">\n<p>\u0639\u0627\u0634\u0642\u0627\u0646\u0647 \u062f\u0631 \u0628\u0627\u0632\u06cc \u0647\u0627 \u0686\u06cc\u0632 \u062c\u062f\u06cc\u062f\u06cc \u0646\u06cc\u0633\u062a \u0648 \u0628\u0647 \u062f\u0627\u0633\u062a\u0627\u0646 \u06a9\u0644\u0627\u0633\u06cc\u06a9 \u0645\u0627\u0631\u06cc\u0648 \u06a9\u0647 \u0634\u0627\u0647\u0632\u0627\u062f\u0647 \u062e\u0627\u0646\u0645 \u0631\u0627 \u0646\u062c\u0627\u062a \u0645\u06cc \u062f\u0647\u062f\u060c \u0645\u06cc \u0631\u0633\u062f.  \u0634\u0645\u0627 \u0647\u0645\u0647 \u0646\u0648\u0639 \u0639\u0634\u0642 \u0631\u0627 \u0645\u06cc \u0628\u06cc\u0646\u06cc\u062f\u060c \u0686\u0647 \u062f\u0631 \u0639\u062c\u06cc\u0628 \u062a\u0631\u06cc\u0646 \u0634\u0631\u0627\u06cc\u0637 \u06af\u0631\u062f \u0647\u0645 \u0628\u06cc\u0627\u06cc\u06cc\u062f \u0648 \u0627\u062d\u0633\u0627\u0633 \u062e\u0648\u062f \u0631\u0627 \u062f\u0631 \u0645\u06cc\u0627\u0646 \u062e\u0637\u0631 \u067e\u06cc\u062f\u0627 \u06a9\u0646\u06cc\u062f\u060c \u0686\u0647 \u06a9\u0633\u06cc \u06a9\u0647 \u0628\u0627\u06cc\u062f \u0646\u062c\u0627\u062a\u0634 \u062f\u0647\u06cc\u062f \u0648 \u062f\u0631 \u0646\u0647\u0627\u06cc\u062a \u0628\u0647 \u0627\u0648 \u0628\u06cc\u0641\u062a\u06cc\u062f.  \u0686\u06cc\u0632\u0647\u0627\u06cc \u0645\u0639\u0645\u0648\u0644\u06cc \u0627\u0644\u0628\u062a\u0647.<\/p>\n<p><!-- No winning ad found for zone: below first paragraph! --><br \/>\n<!-- No winning ad found for zone: mid intro! --><\/p>\n<p><span class=\"related-single\">\u0645\u0637\u0627\u0644\u0628 \u0645\u0631\u062a\u0628\u0637: \u0628\u0627\u0632\u06cc \u0647\u0627\u06cc \u0639\u0627\u0634\u0642\u0627\u0646\u0647 \u0628\u0627 \u0628\u0647\u062a\u0631\u06cc\u0646 \u062f\u0627\u0633\u062a\u0627\u0646 \u0647\u0627<\/span><\/p>\n<p>\u0686\u06cc\u0632\u06cc \u06a9\u0647 \u06a9\u0645\u06cc \u06a9\u0645\u062a\u0631 \u0645\u0648\u0631\u062f \u0628\u0631\u0631\u0633\u06cc \u0642\u0631\u0627\u0631 \u06af\u0631\u0641\u062a\u0647 \u0627\u0633\u062a\u060c \u0648 \u0628\u0647 \u0637\u0648\u0631 \u0642\u0627\u0628\u0644 \u0628\u062d\u062b \u062c\u0627\u0644\u0628 \u062a\u0631 \u0648 \u0628\u0627\u0632\u062f\u0647\u06cc \u0628\u0627\u0644\u0627\u062a\u0631\u060c \u062a\u0645\u0627\u0634\u0627\u06cc \u06cc\u06a9 \u062c\u0641\u062a \u062f\u0634\u0645\u0646 \u062f\u0631 \u06af\u0644\u0648\u06cc \u06cc\u06a9\u062f\u06cc\u06af\u0631 \u0627\u0633\u062a \u06a9\u0647 \u0628\u0647 \u0622\u0631\u0627\u0645\u06cc \u0628\u0647 \u0686\u06cc\u0632\u06cc \u0646\u0631\u0645 \u062a\u0631 \u0648 \u0631\u0645\u0627\u0646\u062a\u06cc\u06a9 \u062a\u0628\u062f\u06cc\u0644 \u0645\u06cc \u0634\u0648\u0646\u062f.  \u0622\u0646\u0647\u0627 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u062f\u0631 \u067e\u0627\u06cc\u0627\u0646 \u06a9\u0627\u0631 \u0646\u06a9\u0646\u0646\u062f\u060c \u0627\u0645\u0627 \u062a\u0645\u0627\u0634\u0627\u06cc \u0633\u0641\u0631 \u0644\u0630\u062a \u0628\u062e\u0634 \u0627\u0633\u062a.<\/p>\n<p><!-- Zone: native in content. --><\/p>\n<div class=\"adsninja-ad-zone \" id=\"adsninja-ad-zone-div-gpt-ad-1605799317330-nic\" style=\"\">\n<div id=\"dynamically-injected-refresh-ad-zone-div-gpt-ad-1605799317330-nic\" class=\"dynamically-injected-refresh-ad-zone\">\n<div class=\"ad-current\">\n<div id=\"ad-zone-container-div-gpt-ad-1605799317330-nic\" class=\"ad-zone-container ad-zone-container-content-native-in-content adsninja-ad-zone-container-with-set-height\" data-no-fill-collapsable=\"false\"><strong class=\"ad-zone-advertising-tag\">\u06af\u06cc\u0645\u0631 \u0648\u06cc\u062f\u06cc\u0648\u06cc \u0631\u0648\u0632<\/strong><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p><!-- No repeatable ad for zone: every entry repeatable. --><!-- Repeatable debug data: {\"adPosition\":0,\"skipEvery\":null,\"nbrPlacementFilledEachSkip\":0,\"nbrPlacementsScanned\":0,\"ruleCount\":false,\"degradationStartingPoint\":null,\"actualCount\":0} --><\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter-rtl ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u0641\u0647\u0631\u0633\u062a \u0645\u0637\u0627\u0644\u0628<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"\u062a\u063a\u06cc\u06cc\u0631 \u0648\u0636\u0639\u06cc\u062a \u0641\u0647\u0631\u0633\u062a \u0645\u0637\u0627\u0644\u0628\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/nabfollower.com\/blog\/enemies-to-lovers-romances-in-video-games\/#8_Zagreus_%D9%88_Megara_%E2%80%93_%D9%87%D8%A7%D8%AF%D8%B3\" >8  Zagreus \u0648 Megara &#8211; \u0647\u0627\u062f\u0633<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/nabfollower.com\/blog\/enemies-to-lovers-romances-in-video-games\/#7_Hawke_And_Fenris_%E2%80%93_Dragon_Age_2\" >7  Hawke And Fenris &#8211; Dragon Age 2<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/nabfollower.com\/blog\/enemies-to-lovers-romances-in-video-games\/#6_Joker_And_Makoto_%E2%80%93_Persona_5\" >6  Joker And Makoto &#8211; Persona 5<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/nabfollower.com\/blog\/enemies-to-lovers-romances-in-video-games\/#5_%D8%A2%D8%AF%D8%A7_%D9%88%D8%A7%D9%86%DA%AF_%D9%88_%D9%84%D8%A6%D9%88%D9%86_%DA%A9%D9%86%D8%AF%DB%8C_%E2%80%93_%D8%B3%D8%B1%DB%8C_Resident_Evil\" >5  \u0622\u062f\u0627 \u0648\u0627\u0646\u06af \u0648 \u0644\u0626\u0648\u0646 \u06a9\u0646\u062f\u06cc &#8211; \u0633\u0631\u06cc Resident Evil<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/nabfollower.com\/blog\/enemies-to-lovers-romances-in-video-games\/#4_Lady_And_Dante_%E2%80%93_Devil_May_Cry_3_Dantes_Awakening\" >4  Lady And Dante &#8211; Devil May Cry 3: Dante&#8217;s Awakening<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/nabfollower.com\/blog\/enemies-to-lovers-romances-in-video-games\/#3_Dorian_And_Iron_Bull_%E2%80%93_DragonAge_Inquisition\" >3  Dorian And Iron Bull &#8211; DragonAge: Inquisition<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/nabfollower.com\/blog\/enemies-to-lovers-romances-in-video-games\/#2_%DA%A9%D9%88%D8%AF%DB%8C_%D9%88_%D9%85%DB%8C_%E2%80%93_%D8%AF%D9%88_%D9%86%D9%81%D8%B1_%D8%B7%D9%88%D9%84_%D9%85%DB%8C_%DA%A9%D8%B4%D8%AF\" >2  \u06a9\u0648\u062f\u06cc \u0648 \u0645\u06cc &#8211; \u062f\u0648 \u0646\u0641\u0631 \u0637\u0648\u0644 \u0645\u06cc \u06a9\u0634\u062f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/nabfollower.com\/blog\/enemies-to-lovers-romances-in-video-games\/#1_%D8%AF%D8%A7%D8%B1%D8%AB_%D8%B1%D9%88%D8%A7%D9%86_%D9%88_%D8%A8%D8%A7%D8%B3%D8%AA%DB%8C%D9%84%D8%A7_%E2%80%93_%D8%AC%D9%86%DA%AF_%D8%B3%D8%AA%D8%A7%D8%B1%DA%AF%D8%A7%D9%86_%D8%B4%D9%88%D8%A7%D9%84%DB%8C%D9%87_%D9%87%D8%A7%DB%8C_%D8%AC%D9%85%D9%87%D9%88%D8%B1%DB%8C_%D9%82%D8%AF%DB%8C%D9%85%DB%8C\" >1  \u062f\u0627\u0631\u062b \u0631\u0648\u0627\u0646 \u0648 \u0628\u0627\u0633\u062a\u06cc\u0644\u0627 &#8211; \u062c\u0646\u06af \u0633\u062a\u0627\u0631\u06af\u0627\u0646: \u0634\u0648\u0627\u0644\u06cc\u0647 \u0647\u0627\u06cc \u062c\u0645\u0647\u0648\u0631\u06cc \u0642\u062f\u06cc\u0645\u06cc<\/a><\/li><\/ul><\/nav><\/div>\n<h2 id=\"zagreus-and-megara---hades\"><span class=\"ez-toc-section\" id=\"8_Zagreus_%D9%88_Megara_%E2%80%93_%D9%87%D8%A7%D8%AF%D8%B3\"><\/span> <span class=\"item-num\">8 <\/span> <span>Zagreus \u0648 Megara &#8211; \u0647\u0627\u062f\u0633<\/span> <span class=\"ez-toc-section-end\"><\/span><\/h2>\n<div class=\"body-img landscape\">\n<div class=\"responsive-img image-expandable img-article-item\" style=\"padding-bottom:50%\" data-img-url=\"https:\/\/nabfollower.com\/blog\/wp-content\/uploads\/2023\/02\/8-\u0628\u0647\u062a\u0631\u06cc\u0646-\u062f\u0634\u0645\u0646\u0627\u0646-\u0639\u0627\u0634\u0642\u0627\u0646-\u0639\u0627\u0634\u0642\u0627\u0646\u0647-\u062f\u0631-\u0628\u0627\u0632\u06cc-\u0647\u0627.jpg\" data-modal-id=\"single-image-modal\" data-modal-container-id=\"single-image-modal-container\" data-img-caption=\"&quot;&quot;\">\n<figure> <picture> <!--[if IE 9]> <video style=\"display: none;\"><![endif]--><source media=\"(min-width: 1024px)\"  data-\/><source media=\"(min-width: 768px)\"  data-\/><source media=\"(min-width: 481px)\"  data-\/><source media=\"(min-width: 0px)\"  data-\/><!--[if IE 9]><\/video><![endif]--> <\/picture> <\/figure>\n<\/p><\/div>\n<\/p><\/div>\n<p>\u0627\u06af\u0631\u0686\u0647 \u0645\u06af \u0628\u0647 \u0637\u0648\u0631 \u0645\u0639\u0645\u0648\u0644 \u0628\u0647 \u0645\u0639\u0646\u0627\u06cc \u0633\u0646\u062a\u06cc \u00ab\u062f\u0634\u0645\u0646\u00bb \u062f\u0631 \u0646\u0638\u0631 \u06af\u0631\u0641\u062a\u0647 \u0646\u0645\u06cc\u200c\u0634\u0648\u062f\u060c \u0627\u0645\u0627 \u0648\u0638\u06cc\u0641\u0647 \u0645\u06af \u0627\u06cc\u0646 \u0627\u0633\u062a \u06a9\u0647 \u0627\u0632 \u0641\u0631\u0627\u0631 \u0632\u0627\u06af\u0631\u0626\u0648\u0633 \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u06a9\u0646\u062f\u060c \u0686\u0647 \u0628\u0647 \u0642\u06cc\u0645\u062a \u062c\u0627\u0646\u0634 \u0628\u0627\u0634\u062f \u06cc\u0627 \u0646\u0647.  \u0639\u0627\u0634\u0642\u0627\u0646 \u0633\u0627\u0628\u0642 \u0628\u0648\u062f\u0646 \u0622\u0646\u0647\u0627 \u06a9\u0645\u06a9 \u0686\u0646\u062f\u0627\u0646\u06cc \u0628\u0647 \u0645\u0633\u0627\u0626\u0644 \u0646\u06a9\u0631\u062f\u060c \u0632\u06cc\u0631\u0627 \u067e\u0633 \u0627\u0632 \u062c\u062f\u0627\u06cc\u06cc \u0622\u0646\u0647\u0627 \u062e\u0635\u0648\u0645\u062a \u0622\u0634\u06a9\u0627\u0631\u06cc \u0648\u062c\u0648\u062f \u062f\u0627\u0634\u062a\u060c \u0627\u06af\u0631\u0686\u0647 \u0645\u0627 \u0647\u0631\u06af\u0632 \u0645\u062a\u0648\u062c\u0647 \u0646\u0634\u062f\u06cc\u0645 \u06a9\u0647 \u062f\u0642\u06cc\u0642\u0627\u064b \u0686\u0647 \u0686\u06cc\u0632\u06cc \u0628\u0627\u0639\u062b \u0622\u0646 \u0634\u062f\u0647 \u0627\u0633\u062a.<\/p>\n<p>\u0647\u0646\u06af\u0627\u0645\u06cc \u06a9\u0647 \u0632\u0627\u06af \u0648 \u0645\u06af \u0628\u0627\u0631\u0647\u0627 \u0648 \u0628\u0627\u0631\u0647\u0627 \u0628\u0627 \u0647\u0645 \u0631\u0648\u0628\u0631\u0648 \u0645\u06cc \u0634\u0648\u0646\u062f\u060c \u0647\u0631 \u062f\u0648 \u0634\u0631\u0648\u0639 \u0628\u0647 \u0628\u0627\u0632 \u06a9\u0631\u062f\u0646 \u062f\u0631 \u0645\u0648\u0631\u062f \u0627\u062d\u0633\u0627\u0633 \u062e\u0648\u062f \u0648 \u0686\u06cc\u0632\u0647\u0627\u06cc\u06cc \u0645\u06cc \u06a9\u0646\u0646\u062f \u06a9\u0647 \u062f\u0631 \u06af\u0630\u0634\u062a\u0647 \u0628\u0631\u0627\u06cc \u0645\u062a\u0648\u0642\u0641 \u06a9\u0631\u062f\u0646 \u0631\u0627\u0628\u0637\u0647 \u0622\u0646\u0647\u0627 \u0627\u062a\u0641\u0627\u0642 \u0627\u0641\u062a\u0627\u062f\u0647 \u0627\u0633\u062a.  \u0628\u0647 \u0627\u0646\u062f\u0627\u0632\u0647 \u06a9\u0627\u0641\u06cc \u062f\u0631 \u0645\u0648\u0631\u062f \u0622\u0646 \u0635\u062d\u0628\u062a \u06a9\u0646\u06cc\u062f \u0648 \u0645\u06af \u062f\u0631 \u0645\u0648\u0631\u062f \u0627\u062d\u06cc\u0627\u06cc \u062f\u0648\u0628\u0627\u0631\u0647 \u0639\u0627\u0634\u0642\u0627\u0646\u0647 \u0628\u0647 \u0634\u0645\u0627 \u0645\u0631\u0627\u062c\u0639\u0647 \u062e\u0648\u0627\u0647\u062f \u06a9\u0631\u062f\u060c \u0627\u06cc\u062f\u0647 \u0627\u06cc \u06a9\u0647 \u0632\u0627\u06af\u0631\u0626\u0648\u0633 \u0628\u0647 \u0622\u0646 \u0639\u0644\u0627\u0642\u0647 \u062f\u0627\u0631\u062f.  \u0622\u06cc\u0627 \u0627\u06cc\u0646 \u062f\u0639\u0648\u0627 \u0628\u06cc\u0646 \u0634\u0645\u0627 \u062f\u0648 \u0646\u0641\u0631 \u0631\u0627 \u0645\u062a\u0648\u0642\u0641 \u0645\u06cc \u06a9\u0646\u062f\u061f  \u0646\u0647\u060c \u0648 \u0628\u0647 \u0646\u0638\u0631 \u0645\u06cc \u0631\u0633\u062f \u06a9\u0647 \u0647\u0631 \u062f\u0648 \u0622\u0646 \u0631\u0627 \u062a\u0631\u062c\u06cc\u062d \u0645\u06cc \u062f\u0647\u0646\u062f.<\/p>\n<p><!-- Zone: every entry repeatable. --><\/p>\n<h2 id=\"hawke-and-fenris---dragon-age-2\"><span class=\"ez-toc-section\" id=\"7_Hawke_And_Fenris_%E2%80%93_Dragon_Age_2\"><\/span> <span class=\"item-num\">7 <\/span> <span>Hawke And Fenris &#8211; Dragon Age 2<\/span> <span class=\"ez-toc-section-end\"><\/span><\/h2>\n<div class=\"body-img landscape\">\n<div class=\"responsive-img image-expandable img-article-item\" style=\"padding-bottom:50%\" data-img-url=\"https:\/\/nabfollower.com\/blog\/wp-content\/uploads\/2023\/02\/1676480009_980_8-\u0628\u0647\u062a\u0631\u06cc\u0646-\u062f\u0634\u0645\u0646\u0627\u0646-\u0639\u0627\u0634\u0642\u0627\u0646-\u0639\u0627\u0634\u0642\u0627\u0646\u0647-\u062f\u0631-\u0628\u0627\u0632\u06cc-\u0647\u0627.jpg\" data-modal-id=\"single-image-modal\" data-modal-container-id=\"single-image-modal-container\" data-img-caption=\"&quot;&quot;\">\n<figure> <picture> <!--[if IE 9]> <video style=\"display: none;\"><![endif]--><source media=\"(min-width: 1024px)\"  data-\/><source media=\"(min-width: 768px)\"  data-\/><source media=\"(min-width: 481px)\"  data-\/><source media=\"(min-width: 0px)\"  data-\/><!--[if IE 9]><\/video><![endif]--><img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"1000\" class=\"lazyload\" alt=\"\u0641\u0646\u0631\u06cc\u0633 \u062f\u0631 \u06cc\u06a9 \u0644\u062d\u0638\u0647 \u0644\u0637\u06cc\u0641 \u0628\u0647 \u0686\u0647\u0631\u0647 \u0647\u0627\u0648\u06a9\u0632 \u0647\u0627\u0648\u06a9 \u0645\u06cc \u0646\u0634\u06cc\u0646\u062f - Dragon Age 2\" src=\"https:\/\/nabfollower.com\/blog\/wp-content\/uploads\/2023\/02\/1676480009_980_8-\u0628\u0647\u062a\u0631\u06cc\u0646-\u062f\u0634\u0645\u0646\u0627\u0646-\u0639\u0627\u0634\u0642\u0627\u0646-\u0639\u0627\u0634\u0642\u0627\u0646\u0647-\u062f\u0631-\u0628\u0627\u0632\u06cc-\u0647\u0627.jpg\" title=\"\"> <\/picture> <\/figure>\n<\/p><\/div>\n<\/p><\/div>\n<p>\u0641\u0646\u0631\u06cc\u0633 \u062f\u0631 Dragon Age 2 \u06cc\u06a9 \u062c\u0646 \u0628\u0648\u062f \u06a9\u0647 \u0686\u06cc\u0632\u0647\u0627\u06cc \u0632\u06cc\u0627\u062f\u06cc \u0627\u0632 \u0627\u0648 \u06af\u0631\u0641\u062a\u0647 \u0628\u0648\u062f \u062f\u0631 \u062d\u0627\u0644\u06cc \u06a9\u0647 \u062f\u0631 \u0627\u0632\u0627\u06cc \u0622\u0646 \u0641\u0642\u0637 \u062f\u0631\u062f \u0648 \u0628\u0646\u062f\u06af\u06cc \u062f\u0631\u06cc\u0627\u0641\u062a \u0645\u06cc \u06a9\u0631\u062f.  \u0627\u0648 \u06a9\u0633\u06cc \u0631\u0627 \u0646\u062f\u0627\u0634\u062a \u06a9\u0647 \u0628\u0647 \u0627\u0648 \u0646\u0634\u0627\u0646 \u062f\u0647\u062f \u0639\u0634\u0642 \u0686\u06cc\u0633\u062a\u060c \u0628\u0646\u0627\u0628\u0631\u0627\u06cc\u0646 \u062a\u0646\u0647\u0627 \u0686\u06cc\u0632\u06cc \u06a9\u0647 \u0627\u0648 \u0631\u0627 \u0645\u062c\u0628\u0648\u0631 \u0645\u06cc \u06a9\u0631\u062f \u062a\u0627 \u0631\u0641\u062a\u0627\u0631\u0634 \u0631\u0627 \u062a\u062d\u0645\u0644 \u06a9\u0646\u062f\u060c \u06a9\u06cc\u0646\u0647 \u062a\u0648\u0632\u06cc \u0648 \u0630\u0648\u0642 \u0622\u0632\u0627\u062f\u06cc \u0628\u0648\u062f.  \u06a9\u0627\u0645\u0644\u0627\u064b \u0645\u0646\u0637\u0642\u06cc \u0627\u0633\u062a \u06a9\u0647 \u062f\u0631 \u062a\u0639\u0627\u0645\u0644 \u0628\u0627 \u0634\u0645\u0627\u060c \u0627\u0648 \u0628\u0647 \u0634\u062f\u062a \u0645\u0631\u0627\u0642\u0628 \u0627\u0633\u062a\u060c \u062a\u0627 \u062d\u062f\u06cc \u06a9\u0647 \u062e\u0635\u0645\u0627\u0646\u0647 \u0628\u0627\u0634\u062f.<\/p>\n<p>\u0627\u06af\u0631 \u0634\u0645\u0627 \u06cc\u06a9 \u062c\u0627\u062f\u0648\u06af\u0631 \u0647\u0633\u062a\u06cc\u062f \u06cc\u0627 \u0628\u0647 \u0637\u0648\u0631 \u06a9\u0644\u06cc \u0627\u0632 \u062c\u0627\u062f\u0648\u06af\u0631\u0627\u0646 \u062d\u0645\u0627\u06cc\u062a \u0645\u06cc \u06a9\u0646\u06cc\u062f\u060c \u0627\u0648 \u0627\u0628\u062a\u062f\u0627 \u0627\u0632 \u0634\u0645\u0627 \u0628\u062f\u0634 \u0646\u0645\u06cc \u0622\u06cc\u062f \u0648 \u062f\u0631 \u062d\u06cc\u0646 \u0645\u06a9\u0627\u0644\u0645\u0627\u062a \u0627\u0639\u062a\u0642\u0627\u062f\u0627\u062a \u0634\u0645\u0627 \u0631\u0627 \u0628\u0647 \u0686\u0627\u0644\u0634 \u0645\u06cc \u06a9\u0634\u062f.  \u0628\u0627 \u06af\u0630\u0634\u062a \u0632\u0645\u0627\u0646\u060c \u0641\u0646\u0631\u06cc\u0633 \u0634\u0631\u0648\u0639 \u0628\u0647 \u0646\u0631\u0645 \u0634\u062f\u0646 \u0646\u0633\u0628\u062a \u0628\u0647 \u0634\u0645\u0627 \u0645\u06cc \u06a9\u0646\u062f\u060c \u0628\u0647 \u0634\u0631\u0637\u06cc \u06a9\u0647 \u0627\u0648 \u0631\u0627 \u0628\u0647 \u06a9\u0633\u0627\u0646\u06cc \u06a9\u0647 \u0628\u0647 \u062f\u0646\u0628\u0627\u0644 \u0627\u0648 \u0647\u0633\u062a\u0646\u062f \u0628\u0631\u0646\u06af\u0631\u062f\u0627\u0646\u06cc\u062f.  \u0633\u067e\u0633\u060c \u0634\u0645\u0627 \u06cc\u06a9 \u062f\u0634\u0645\u0646 \u0642\u062f\u0631\u062a\u0645\u0646\u062f \u0628\u0631\u0627\u06cc \u0632\u0646\u062f\u06af\u06cc \u062f\u0631 \u062f\u0645 \u062e\u0648\u062f \u062e\u0648\u0627\u0647\u06cc\u062f \u062f\u0627\u0634\u062a.<\/p>\n<p><!-- Zone: every entry repeatable. --><\/p>\n<h2 id=\"joker-and-makoto---persona-5\"><span class=\"ez-toc-section\" id=\"6_Joker_And_Makoto_%E2%80%93_Persona_5\"><\/span> <span class=\"item-num\">6 <\/span> <span>Joker And Makoto &#8211; Persona 5<\/span> <span class=\"ez-toc-section-end\"><\/span><\/h2>\n<div class=\"body-img landscape\">\n<div class=\"responsive-img image-expandable img-article-item\" style=\"padding-bottom:50%\" data-img-url=\"https:\/\/nabfollower.com\/blog\/wp-content\/uploads\/2023\/02\/1676480009_291_8-\u0628\u0647\u062a\u0631\u06cc\u0646-\u062f\u0634\u0645\u0646\u0627\u0646-\u0639\u0627\u0634\u0642\u0627\u0646-\u0639\u0627\u0634\u0642\u0627\u0646\u0647-\u062f\u0631-\u0628\u0627\u0632\u06cc-\u0647\u0627.jpg\" data-modal-id=\"single-image-modal\" data-modal-container-id=\"single-image-modal-container\" data-img-caption=\"&quot;&quot;\">\n<figure> <picture> <!--[if IE 9]> <video style=\"display: none;\"><![endif]--><source media=\"(min-width: 1024px)\"  data-\/><source media=\"(min-width: 768px)\"  data-\/><source media=\"(min-width: 481px)\"  data-\/><source media=\"(min-width: 0px)\"  data-\/><!--[if IE 9]><\/video><![endif]--><img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"1000\" class=\"lazyload\" alt=\"\u062c\u0648\u06a9\u0631 \u067e\u0633 \u0627\u0632 \u06af\u0631\u0641\u062a\u0646 \u0645\u0627\u06a9\u0648\u062a\u0648 \u06af\u0647\u0648\u0627\u0631\u0647 \u0645\u06cc \u0634\u0648\u062f - Persona 5\" src=\"https:\/\/nabfollower.com\/blog\/wp-content\/uploads\/2023\/02\/1676480009_291_8-\u0628\u0647\u062a\u0631\u06cc\u0646-\u062f\u0634\u0645\u0646\u0627\u0646-\u0639\u0627\u0634\u0642\u0627\u0646-\u0639\u0627\u0634\u0642\u0627\u0646\u0647-\u062f\u0631-\u0628\u0627\u0632\u06cc-\u0647\u0627.jpg\" title=\"\"> <\/picture> <\/figure>\n<\/p><\/div>\n<\/p><\/div>\n<p>\u0645\u0627\u06a9\u0648\u062a\u0648 \u0646\u06cc\u062c\u06cc\u0645\u0627 \u0627\u0632 Persona 5 \u0628\u06cc\u0634\u062a\u0631 \u0627\u0632 \u0622\u0646 \u0686\u06cc\u0632\u06cc \u06a9\u0647 \u0628\u0647 \u06a9\u0633\u06cc \u0627\u0639\u062a\u0631\u0627\u0641 \u06a9\u0631\u062f\u0647 \u0628\u0627\u0634\u062f\u060c \u062e\u0648\u0627\u0647\u0631 \u062f\u0627\u062f\u0633\u062a\u0627\u0646\u0634 \u0631\u0627 \u062a\u062d\u062a \u062a\u0639\u0642\u06cc\u0628 \u0642\u0631\u0627\u0631 \u0645\u06cc \u062f\u0647\u062f.  \u0627\u0648 \u0628\u0647 \u0627\u0646\u062f\u0627\u0632\u0647 \u06a9\u0627\u0641\u06cc \u0641\u0647\u06cc\u0645 \u0627\u0633\u062a \u06a9\u0647 \u062c\u0648\u06a9\u0631 \u0631\u0627 \u0628\u06af\u06cc\u0631\u062f \u0648 \u0637\u0631\u0641 \u0645\u0642\u0627\u0628\u0644 \u06a9\u0633\u0627\u0646\u06cc \u0647\u0633\u062a\u0646\u062f \u06a9\u0647 \u0642\u0644\u0628 \u0647\u0627 \u0631\u0627 \u0645\u06cc \u062f\u0632\u062f\u0646\u062f \u0648 \u0628\u0644\u0627\u0641\u0627\u0635\u0644\u0647 \u0627\u0632 \u0622\u0646 \u0628\u0631\u0627\u06cc \u0628\u0627\u062c \u06af\u06cc\u0631\u06cc \u0634\u0645\u0627 \u0628\u0631\u0627\u06cc \u0627\u0646\u062c\u0627\u0645 \u0622\u0646\u0686\u0647 \u0645\u06cc \u062e\u0648\u0627\u0647\u062f \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc \u06a9\u0646\u062f.  \u0627\u06cc\u0646 \u062d\u062a\u06cc \u0628\u0627 \u062f\u0646\u0628\u0627\u0644 \u06a9\u0631\u062f\u0646 \u0627\u0648 \u062f\u0631 \u0633\u0631\u0627\u0633\u0631 \u0634\u0647\u0631\u060c \u062c\u0648\u06a9\u0631 \u0645\u0633\u062a\u0642\u06cc\u0645\u0627\u064b \u062a\u0639\u0642\u06cc\u0628 \u06a9\u0646\u0646\u062f\u0647 \u0631\u0627 \u0645\u0637\u0631\u062d \u0646\u0645\u06cc \u06a9\u0646\u062f.<\/p>\n<p><span class=\"related-single\">\u0645\u0637\u0627\u0644\u0628 \u0645\u0631\u062a\u0628\u0637: \u0628\u0647\u062a\u0631\u06cc\u0646 \u0628\u0647\u062a\u0631\u06cc\u0646 Shin Megami Tensei \u0648 Persona Enemies<\/span><\/p>\n<p>\u0627\u0644\u0628\u062a\u0647 \u0647\u0645\u0647 \u0627\u06cc\u0646\u0647\u0627 \u0645\u0648\u0642\u062a\u06cc \u0627\u0633\u062a\u060c \u0632\u06cc\u0631\u0627 \u0627\u0646\u06af\u06cc\u0632\u0647 \u0647\u0627\u06cc \u062c\u0648\u06a9\u0631 \u0648 \u0645\u0627\u06a9\u0648\u062a\u0648 \u0628\u0647 \u0648\u0636\u0648\u062d \u0645\u0634\u062e\u0635 \u0634\u062f\u0647 \u0627\u0633\u062a\u060c \u0622\u0646\u0647\u0627 \u0628\u0627 \u0627\u0647\u062f\u0627\u0641 \u0645\u0634\u0627\u0628\u0647\u06cc \u0628\u0647 \u0646\u06cc\u0631\u0648\u0647\u0627 \u0645\u06cc \u067e\u06cc\u0648\u0646\u062f\u0646\u062f\u060c \u0648 \u0627\u0648 \u062f\u0631 \u0646\u0647\u0627\u06cc\u062a \u0628\u0647 \u062e\u0627\u0637\u0631 \u0646\u062d\u0648\u0647 \u0645\u062f\u06cc\u0631\u06cc\u062a \u0647\u0645\u0647 \u0686\u06cc\u0632 \u0639\u0630\u0631\u062e\u0648\u0627\u0647\u06cc \u0645\u06cc \u06a9\u0646\u062f.  \u0627\u06af\u0631\u0686\u0647 \u0646\u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u0627\u0648 \u0631\u0627 \u0633\u0631\u0632\u0646\u0634 \u06a9\u0646\u06cc\u062f &#8211; \u0645\u0627\u06a9\u0648\u062a\u0648 \u0627\u062d\u0633\u0627\u0633 \u0645\u06cc\u200c\u06a9\u0631\u062f \u06a9\u0647 \u0628\u0627\u06cc\u062f \u0647\u0645\u0647 \u06a9\u0627\u0631\u0647\u0627 \u0631\u0627 \u0628\u0647 \u062a\u0646\u0647\u0627\u06cc\u06cc \u0627\u0646\u062c\u0627\u0645 \u062f\u0647\u062f\u060c \u062d\u062a\u06cc \u06a9\u0627\u0631\u0647\u0627\u06cc\u06cc \u06a9\u0647 \u0628\u0631\u0627\u06cc \u0628\u0632\u0631\u06af\u0633\u0627\u0644\u0627\u0646 \u0632\u0646\u062f\u06af\u06cc \u0627\u0648 \u0645\u0646\u0627\u0633\u0628\u200c\u062a\u0631 \u0628\u0648\u062f.<\/p>\n<p><!-- Zone: every entry repeatable. --><\/p>\n<h2 id=\"ada-wong-and-leon-kennedy---resident-evil-series\"><span class=\"ez-toc-section\" id=\"5_%D8%A2%D8%AF%D8%A7_%D9%88%D8%A7%D9%86%DA%AF_%D9%88_%D9%84%D8%A6%D9%88%D9%86_%DA%A9%D9%86%D8%AF%DB%8C_%E2%80%93_%D8%B3%D8%B1%DB%8C_Resident_Evil\"><\/span> <span class=\"item-num\">5 <\/span> <span>\u0622\u062f\u0627 \u0648\u0627\u0646\u06af \u0648 \u0644\u0626\u0648\u0646 \u06a9\u0646\u062f\u06cc &#8211; \u0633\u0631\u06cc Resident Evil<\/span> <span class=\"ez-toc-section-end\"><\/span><\/h2>\n<div class=\"body-img landscape\">\n<div class=\"responsive-img image-expandable img-article-item\" style=\"padding-bottom:50%\" data-img-url=\"https:\/\/nabfollower.com\/blog\/wp-content\/uploads\/2023\/02\/1676480010_414_8-\u0628\u0647\u062a\u0631\u06cc\u0646-\u062f\u0634\u0645\u0646\u0627\u0646-\u0639\u0627\u0634\u0642\u0627\u0646-\u0639\u0627\u0634\u0642\u0627\u0646\u0647-\u062f\u0631-\u0628\u0627\u0632\u06cc-\u0647\u0627.jpg\" data-modal-id=\"single-image-modal\" data-modal-container-id=\"single-image-modal-container\" data-img-caption=\"&quot;&quot;\">\n<figure> <picture> <!--[if IE 9]> <video style=\"display: none;\"><![endif]--><source media=\"(min-width: 1024px)\"  data-\/><source media=\"(min-width: 768px)\"  data-\/><source media=\"(min-width: 481px)\"  data-\/><source media=\"(min-width: 0px)\"  data-\/><!--[if IE 9]><\/video><![endif]--><img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"1000\" class=\"lazyload\" alt=\"\u0622\u062f\u0627 \u0648\u0627\u0646\u06af \u0648 \u0644\u0626\u0648\u0646 \u06a9\u0646\u062f\u06cc \u062f\u0631 \u0634\u0628 \u0628\u0627 \u0647\u0645 \u0633\u0648\u0627\u0631 \u0642\u0627\u06cc\u0642 \u0645\u06cc \u0634\u0648\u0646\u062f\" src=\"https:\/\/nabfollower.com\/blog\/wp-content\/uploads\/2023\/02\/1676480010_414_8-\u0628\u0647\u062a\u0631\u06cc\u0646-\u062f\u0634\u0645\u0646\u0627\u0646-\u0639\u0627\u0634\u0642\u0627\u0646-\u0639\u0627\u0634\u0642\u0627\u0646\u0647-\u062f\u0631-\u0628\u0627\u0632\u06cc-\u0647\u0627.jpg\" title=\"\"> <\/picture> <\/figure>\n<\/p><\/div>\n<\/p><\/div>\n<p>\u0631\u0627\u0628\u0637\u0647 \u0628\u06cc\u0646 \u0622\u062f\u0627 \u0648\u0627\u0646\u06af \u0648 \u0644\u0626\u0648\u0646 \u0627\u0632 \u0646\u0638\u0631 \u0641\u0646\u06cc \u0648\u062c\u0648\u062f \u0646\u062f\u0627\u0631\u062f.  \u0627\u0648 \u0628\u0647 \u062f\u0644\u0627\u06cc\u0644\u06cc \u06a9\u0647 \u0628\u0631\u0627\u06cc \u0634\u0645\u0627 \u0646\u0627\u0634\u0646\u0627\u062e\u062a\u0647 \u0627\u0633\u062a \u0628\u0631\u0627\u06cc \u0634\u0631\u06a9\u062a \u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641 \u0634\u0631\u0648\u0631 \u06a9\u0627\u0631 \u0645\u06cc \u06a9\u0646\u062f\u060c \u0648 \u0627\u0648 \u0645\u0631\u062f\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0628\u062f\u062a\u0631\u06cc\u0646 \u0631\u0648\u0632 \u0627\u0648\u0644 \u06a9\u0627\u0631 \u0631\u0627 \u062f\u0631 \u062a\u0627\u0631\u06cc\u062e \u0627\u0633\u062a\u062e\u062f\u0627\u0645 \u062f\u0627\u0634\u062a\u0647 \u0627\u0633\u062a \u0648 \u0628\u0647 \u062f\u0646\u0628\u0627\u0644 \u0622\u0646 \u0686\u0646\u062f\u06cc\u0646 \u062d\u0645\u0644\u0647 \u062f\u06cc\u06af\u0631 \u0634\u0627\u0645\u0644 \u0632\u0627\u0645\u0628\u06cc \u0647\u0627 \u0648 \u0633\u0644\u0627\u062d \u0647\u0627\u06cc \u0632\u06cc\u0633\u062a\u06cc \u062c\u0646\u06af\u06cc \u0627\u0646\u062c\u0627\u0645 \u0634\u062f\u0647 \u0627\u0633\u062a.  \u0632\u0645\u0627\u0646\u06cc \u0628\u0631\u0627\u06cc \u0634\u06a9\u0648\u0641\u0627\u06cc\u06cc \u0639\u0634\u0642 \u0648\u062c\u0648\u062f \u0646\u062f\u0627\u0631\u062f.<\/p>\n<p>\u062f\u0631 \u0628\u06cc\u0646 \u0645\u0648\u0627\u0642\u0639\u06cc \u06a9\u0647 \u0628\u0627\u06cc\u062f \u0627\u0633\u0644\u062d\u0647\u200c\u0647\u0627\u06cc \u062e\u0648\u062f \u0631\u0627 \u0628\u0647 \u0633\u0645\u062a \u06cc\u06a9\u062f\u06cc\u06af\u0631 \u0628\u06af\u06cc\u0631\u0646\u062f\u060c \u0644\u0626\u0648\u0646 \u0648 \u0622\u062f\u0627 \u062f\u0631 \u062d\u06cc\u0646 \u062a\u0628\u0627\u062f\u0644 \u0627\u0637\u0644\u0627\u0639\u0627\u062a \u06cc\u0627 \u06a9\u0645\u06a9 \u0628\u0647 \u0628\u0642\u0627\u06cc \u06cc\u06a9\u062f\u06cc\u06af\u0631\u060c \u06a9\u0646\u0627\u06cc\u0647\u200c\u0647\u0627\u06cc \u0639\u0634\u0648\u0647\u200c\u0622\u0645\u06cc\u0632 \u0648 \u0628\u0648\u0633\u0647\u200c\u0647\u0627\u06cc \u062f\u0632\u062f\u06cc\u062f\u0647 \u0634\u062f\u0647 \u0631\u0627 \u0628\u0647 \u0639\u0642\u0628 \u0648 \u062c\u0644\u0648 \u0631\u062f \u0648 \u0628\u062f\u0644 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f.  \u0647\u0631 \u062f\u0648 \u062c\u0627\u0646 \u062e\u0648\u062f \u0631\u0627 \u0628\u0631\u0627\u06cc \u06cc\u06a9\u062f\u06cc\u06af\u0631 \u0628\u0647 \u062e\u0637\u0631 \u0627\u0646\u062f\u0627\u062e\u062a\u0647 \u0627\u0646\u062f\u060c \u0627\u0645\u0627 \u0627\u06cc\u0646 \u0645\u0627\u0646\u0639 \u0627\u0632 \u0622\u0646 \u0646\u0645\u06cc \u0634\u0648\u062f \u06a9\u0647 \u0622\u062f\u0627 \u062f\u0631 \u0646\u0647\u0627\u06cc\u062a \u0645\u0631\u0627\u0642\u0628 \u062e\u0648\u062f\u0634 \u0628\u0627\u0634\u062f.  \u0622\u0646\u0647\u0627 \u0642\u0631\u0627\u0631 \u0646\u06cc\u0633\u062a \u0628\u0627\u0634\u0646\u062f\u060c \u0627\u0645\u0627 \u0647\u0646\u0648\u0632 \u0647\u0645 \u0645\u06cc \u062a\u0648\u0627\u0646\u0646\u062f \u0628\u0627 \u06cc\u06a9\u062f\u06cc\u06af\u0631 \u062e\u0648\u0634 \u0628\u06af\u0630\u0631\u0627\u0646\u0646\u062f.<\/p>\n<p><!-- Zone: every entry repeatable. --><\/p>\n<h2 id=\"lady-and-dante---devil-may-cry-3-dante-rsquo-s-awakening\"><span class=\"ez-toc-section\" id=\"4_Lady_And_Dante_%E2%80%93_Devil_May_Cry_3_Dantes_Awakening\"><\/span> <span class=\"item-num\">4 <\/span> <span>Lady And Dante &#8211; Devil May Cry 3: Dante&#8217;s Awakening<\/span> <span class=\"ez-toc-section-end\"><\/span><\/h2>\n<div class=\"body-img landscape\">\n<div class=\"responsive-img image-expandable img-article-item\" style=\"padding-bottom:50%\" data-img-url=\"https:\/\/nabfollower.com\/blog\/wp-content\/uploads\/2023\/02\/1676480010_311_8-\u0628\u0647\u062a\u0631\u06cc\u0646-\u062f\u0634\u0645\u0646\u0627\u0646-\u0639\u0627\u0634\u0642\u0627\u0646-\u0639\u0627\u0634\u0642\u0627\u0646\u0647-\u062f\u0631-\u0628\u0627\u0632\u06cc-\u0647\u0627.jpg\" data-modal-id=\"single-image-modal\" data-modal-container-id=\"single-image-modal-container\" data-img-caption=\"&quot;&quot;\">\n<figure> <picture> <!--[if IE 9]> <video style=\"display: none;\"><![endif]--><source media=\"(min-width: 1024px)\"  data-\/><source media=\"(min-width: 768px)\"  data-\/><source media=\"(min-width: 481px)\"  data-\/><source media=\"(min-width: 0px)\"  data-\/><!--[if IE 9]><\/video><![endif]--><img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"1000\" class=\"lazyload\" alt=\"\u062f\u0627\u0646\u062a\u0647 \u0644\u06cc\u062f\u06cc \u0631\u0627 \u0628\u0647 \u062f\u06cc\u0648\u0627\u0631 \u0633\u0645\u062a \u0686\u067e \u0641\u0634\u0627\u0631 \u0645\u06cc \u062f\u0647\u062f - Devil May Cry 3\" src=\"https:\/\/nabfollower.com\/blog\/wp-content\/uploads\/2023\/02\/1676480010_311_8-\u0628\u0647\u062a\u0631\u06cc\u0646-\u062f\u0634\u0645\u0646\u0627\u0646-\u0639\u0627\u0634\u0642\u0627\u0646-\u0639\u0627\u0634\u0642\u0627\u0646\u0647-\u062f\u0631-\u0628\u0627\u0632\u06cc-\u0647\u0627.jpg\" title=\"\"> <\/picture> <\/figure>\n<\/p><\/div>\n<\/p><\/div>\n<p>\u062f\u0631 \u062c\u0633\u062a\u062c\u0648\u06cc \u067e\u062f\u0631\u0634\u060c \u0644\u06cc\u062f\u06cc \u062d\u0648\u0635\u0644\u0647 \u06cc \u0644\u0627\u0641 \u0632\u062f\u0646 \u0642\u0647\u0631\u0645\u0627\u0646\u0627\u0646 \u062f\u0627\u0633\u062a\u0627\u0646 \u0631\u0627 \u0628\u0627 \u062a\u0631\u0627\u0634\u0647 \u0627\u06cc \u0631\u0648\u06cc \u0634\u0627\u0646\u0647 \u0627\u0634 \u0646\u062f\u0627\u0631\u062f\u060c \u062d\u062a\u06cc \u0627\u06af\u0631 \u0627\u062d\u0633\u0627\u0633 \u06a9\u0646\u062f \u06a9\u0647 \u062c\u0627\u0646 \u0627\u0648 \u0631\u0627 \u0646\u062c\u0627\u062a \u062f\u0627\u062f\u0647 \u0627\u0633\u062a.  \u062f\u0627\u0646\u062a\u0647 \u0647\u0646\u06af\u0627\u0645 \u0633\u0642\u0648\u0637 \u0627\u0632 \u0628\u0627\u0644\u0627\u06cc \u0628\u0631\u062c \u0634\u06cc\u0637\u0627\u0646\u060c \u0627\u0648 \u0631\u0627 \u0627\u0632 \u0647\u0648\u0627 \u0628\u06cc\u0631\u0648\u0646 \u0645\u06cc\u200c\u0622\u0648\u0631\u062f\u060c \u0648 \u0627\u0648 \u0628\u0631\u0627\u06cc \u062a\u0634\u06a9\u0631 \u0686\u0647 \u0645\u06cc\u200c\u06a9\u0646\u062f\u061f  \u0627\u0644\u0628\u062a\u0647 \u0628\u0647\u0634 \u0634\u0644\u06cc\u06a9 \u06a9\u0646  \u062f\u0648 \u0628\u0631\u0627\u0628\u0631.<\/p>\n<p>\u0627\u06cc\u0646 \u06a9\u0627\u0631 \u0647\u0631 \u0628\u0627\u0631 \u06a9\u0647 \u0645\u0633\u06cc\u0631\u0647\u0627\u06cc \u0622\u0646\u200c\u0647\u0627 \u0645\u062a\u0644\u0627\u0634\u06cc \u0645\u06cc\u200c\u0634\u0648\u062f\u060c \u0627\u062f\u0627\u0645\u0647 \u0645\u06cc\u200c\u06cc\u0627\u0628\u062f\u060c \u0648 \u0622\u062e\u0631\u06cc\u0646 \u0631\u0648\u06cc\u0627\u0631\u0648\u06cc\u06cc \u062c\u0646\u06af\u06cc \u0622\u0646\u200c\u0647\u0627 \u0628\u0647 \u06cc\u06a9 \u0628\u0627\u0633 \u0641\u0627\u06cc\u062a \u062a\u0628\u062f\u06cc\u0644 \u0645\u06cc\u200c\u0634\u0648\u062f \u06a9\u0647 \u062f\u0631 \u0622\u0646 \u062f\u0627\u0646\u062a\u0647 \u0628\u0627 \u0645\u0648\u0634\u06a9\u200c\u0627\u0646\u062f\u0627\u0632 \u0645\u0646\u062d\u0635\u0631\u0628\u0647\u200c\u0641\u0631\u062f \u062e\u0648\u062f \u0631\u0648\u0628\u0631\u0648 \u0645\u06cc\u200c\u0634\u0648\u062f.  \u0627\u0648 \u0634\u06a9\u0633\u062a \u0645\u06cc\u200c\u062e\u0648\u0631\u062f\u060c \u0627\u0645\u0627 \u062f\u0631 \u0646\u0647\u0627\u06cc\u062a \u0628\u0647 \u0634\u0645\u0627 \u0627\u0639\u062a\u0645\u0627\u062f \u0645\u06cc\u200c\u06a9\u0646\u062f\u060c \u06a9\u0647 \u0646\u0645\u0627\u062f \u0622\u0646 \u0627\u06cc\u0646 \u0627\u0633\u062a \u06a9\u0647 \u0627\u0648 \u0633\u0644\u0627\u062d \u0633\u0641\u0627\u0631\u0634\u06cc \u062e\u0648\u062f \u0631\u0627 \u0628\u0647 \u0634\u0645\u0627 \u0645\u06cc\u200c\u062f\u0647\u062f.  \u0647\u0646\u06af\u0627\u0645\u06cc \u06a9\u0647 \u06af\u0631\u062f \u0648 \u063a\u0628\u0627\u0631 \u0641\u0631\u0648 \u0645\u06cc \u0646\u0634\u06cc\u0646\u062f \u0648 \u0627\u0641\u0631\u0627\u062f \u0628\u062f \u0634\u06a9\u0633\u062a \u0645\u06cc \u062e\u0648\u0631\u0646\u062f\u060c \u062f\u0627\u0646\u062a\u0647 \u0648 \u0644\u06cc\u062f\u06cc \u0628\u0627\u0642\u06cc \u0645\u06cc \u0645\u0627\u0646\u0646\u062f.  \u0631\u0627\u0628\u0637\u0647 \u0622\u0646\u0647\u0627 \u0645\u0628\u0647\u0645 \u0627\u0633\u062a\u060c \u0627\u0645\u0627 \u0622\u0646\u0647\u0627 \u0686\u0646\u06cc\u0646 \u0627\u0633\u062a\u0646\u0628\u0627\u0637 \u0645\u06cc \u06a9\u0646\u0646\u062f \u06a9\u0647 \u0627\u0648 \u0628\u0631\u0627\u06cc \u0645\u062f\u062a\u06cc \u0628\u0647 \u0627\u0637\u0631\u0627\u0641 \u0645\u06cc \u0645\u0627\u0646\u062f.<\/p>\n<p><!-- Zone: every entry repeatable. --><\/p>\n<h2 id=\"dorian-and-iron-bull---dragonage-inquisition\"><span class=\"ez-toc-section\" id=\"3_Dorian_And_Iron_Bull_%E2%80%93_DragonAge_Inquisition\"><\/span> <span class=\"item-num\">3 <\/span> <span>Dorian And Iron Bull &#8211; DragonAge: Inquisition<\/span> <span class=\"ez-toc-section-end\"><\/span><\/h2>\n<div class=\"body-img landscape\">\n<div class=\"responsive-img image-expandable img-article-item\" style=\"padding-bottom:50%\" data-img-url=\"https:\/\/nabfollower.com\/blog\/wp-content\/uploads\/2023\/02\/1676480011_195_8-\u0628\u0647\u062a\u0631\u06cc\u0646-\u062f\u0634\u0645\u0646\u0627\u0646-\u0639\u0627\u0634\u0642\u0627\u0646-\u0639\u0627\u0634\u0642\u0627\u0646\u0647-\u062f\u0631-\u0628\u0627\u0632\u06cc-\u0647\u0627.jpg\" data-modal-id=\"single-image-modal\" data-modal-container-id=\"single-image-modal-container\" data-img-caption=\"&quot;&quot;\">\n<figure> <picture> <!--[if IE 9]> <video style=\"display: none;\"><![endif]--><source media=\"(min-width: 1024px)\"  data-\/><source media=\"(min-width: 768px)\"  data-\/><source media=\"(min-width: 481px)\"  data-\/><source media=\"(min-width: 0px)\"  data-\/><!--[if IE 9]><\/video><![endif]--><img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"1000\" class=\"lazyload\" alt=\"\u06af\u0627\u0648 \u0622\u0647\u0646\u06cc \u062f\u0631 \u0633\u0645\u062a \u0686\u067e \u0627\u06cc\u0633\u062a\u0627\u062f\u0647 \u0627\u0633\u062a\u060c \u062f\u0648\u0631\u06cc\u0627\u0646 \u0628\u0647 \u0633\u0645\u062a \u0631\u0627\u0633\u062a \u0646\u06af\u0627\u0647 \u0645\u06cc \u06a9\u0646\u062f\" src=\"https:\/\/nabfollower.com\/blog\/wp-content\/uploads\/2023\/02\/1676480011_195_8-\u0628\u0647\u062a\u0631\u06cc\u0646-\u062f\u0634\u0645\u0646\u0627\u0646-\u0639\u0627\u0634\u0642\u0627\u0646-\u0639\u0627\u0634\u0642\u0627\u0646\u0647-\u062f\u0631-\u0628\u0627\u0632\u06cc-\u0647\u0627.jpg\" title=\"\"> <\/picture> <\/figure>\n<\/p><\/div>\n<\/p><\/div>\n<p>\u06cc\u06a9\u06cc \u0627\u0632 \u0633\u0627\u0644\u0645\u200c\u062a\u0631\u06cc\u0646 \u0631\u0648\u0627\u0628\u0637 \u062f\u0631 \u0627\u06cc\u0646 \u0633\u0631\u06cc\u0627\u0644\u060c \u0627\u06af\u0631 \u0628\u0627 \u06cc\u06a9\u06cc \u0627\u0632 \u0622\u0646\u200c\u0647\u0627 \u0631\u0627\u0628\u0637\u0647\u200c\u0627\u06cc \u0639\u0627\u0634\u0642\u0627\u0646\u0647 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f\u060c \u0628\u0633\u06cc\u0627\u0631 \u063a\u06cc\u0631\u0645\u0645\u06a9\u0646 \u0627\u0633\u062a\u060c \u06a9\u0647 \u0645\u0627\u06cc\u0647 \u0634\u0631\u0645\u0633\u0627\u0631\u06cc \u0627\u0633\u062a.  \u06af\u0627\u0648 \u0622\u0647\u0646\u06cc \u0642\u0648\u0646\u0627\u0631\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0628\u0627 \u062c\u0627\u062f\u0648\u06af\u0631\u0627\u0646 \u062e\u0648\u062f \u062f\u0631 \u0632\u06cc\u0631 \u0632\u0646\u062c\u06cc\u0631\u0647\u0627\u06cc \u0633\u0646\u06af\u06cc\u0646 \u0627\u062d\u062a\u0631\u0627\u0645 \u0648 \u062a\u0631\u0633 \u0628\u0647 \u0646\u0633\u0628\u062a \u0645\u0633\u0627\u0648\u06cc \u0631\u0641\u062a\u0627\u0631 \u0645\u06cc \u06a9\u0646\u0646\u062f.  \u062f\u0648\u0631\u06cc\u0627\u0646 \u0627\u0647\u0644 \u062a\u0648\u06cc\u0646\u062a\u0631 \u0627\u0633\u062a\u060c \u0633\u0631\u0632\u0645\u06cc\u0646\u06cc \u06a9\u0647 \u062a\u0648\u0633\u0637 \u062c\u0627\u062f\u0648\u0647\u0627\u060c \u0628\u0631\u062f\u0647 \u062f\u0627\u0631\u06cc \u0648 \u062c\u0627\u062f\u0648\u06cc \u062e\u0648\u0646 \u063a\u06cc\u0631\u0631\u0633\u0645\u06cc \u0627\u062f\u0627\u0631\u0647 \u0645\u06cc \u0634\u0648\u062f.  \u062f\u0648 \u06a9\u0634\u0648\u0631 \u0622\u0646\u0647\u0627 \u0635\u062f\u0647\u0627 \u0633\u0627\u0644 \u0627\u0633\u062a \u06a9\u0647 \u062f\u0631\u06af\u06cc\u0631 \u062c\u0646\u06af \u0628\u0648\u062f\u0647 \u0627\u0646\u062f.<\/p>\n<p><span class=\"related-single\">\u0645\u0637\u0627\u0644\u0628 \u0645\u0631\u062a\u0628\u0637: \u0628\u0647\u062a\u0631\u06cc\u0646 \u0628\u0627\u0632\u06cc \u0647\u0627\u06cc RPG \u062f\u0631 \u062c\u0627\u06cc\u06cc \u06a9\u0647 \u062f\u0646\u06cc\u0627 \u0631\u0627 \u0646\u062c\u0627\u062a \u0646\u0645\u06cc \u062f\u0647\u06cc\u062f<\/span><\/p>\n<p>\u0628\u0647 \u0637\u0648\u0631 \u0645\u0639\u0645\u0648\u0644\u060c \u0627\u06cc\u0646 \u0628\u062f\u0627\u0646 \u0645\u0639\u0646\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0647\u0631 \u062f\u0648\u06cc \u0622\u0646\u0647\u0627 \u0628\u0647 \u0627\u062d\u062a\u0645\u0627\u0644 \u0632\u06cc\u0627\u062f \u0628\u0644\u0627\u0641\u0627\u0635\u0644\u0647 \u062f\u0631 \u0647\u0646\u06af\u0627\u0645 \u0645\u0634\u0627\u0647\u062f\u0647 \u0628\u0627 \u0647\u0645 \u062f\u0639\u0648\u0627 \u0645\u06cc \u06a9\u0646\u0646\u062f &#8211; \u062f\u0631 \u0639\u0648\u0636\u060c \u0622\u0646\u0647\u0627 \u062a\u0635\u0645\u06cc\u0645 \u0645\u06cc \u06af\u06cc\u0631\u0646\u062f \u06a9\u0647 \u06cc\u06a9\u062f\u06cc\u06af\u0631 \u0631\u0627 \u062f\u0631 \u0633\u0637\u062d \u0634\u062e\u0635\u06cc \u0628\u0634\u0646\u0627\u0633\u0646\u062f \u0648 \u0645\u062a\u0648\u062c\u0647 \u0645\u06cc \u0634\u0648\u0646\u062f \u06a9\u0647 \u0628\u06cc\u0634\u062a\u0631 \u0627\u0632 \u06a9\u0634\u0648\u0631\u0634\u0627\u0646 \u0647\u0633\u062a\u0646\u062f.  \u062f\u0648\u0631\u06cc\u0627\u0646 \u0627\u0645\u06cc\u062f \u062a\u063a\u06cc\u06cc\u0631 \u06a9\u0634\u0648\u0631\u0634 \u0631\u0627 \u062f\u0627\u0631\u062f \u0648 \u0622\u06cc\u0631\u0648\u0646 \u0628\u0648\u0644 \u0627\u0632 \u062f\u0648\u0631 \u0627\u0632 \u0627\u0648 \u062d\u0645\u0627\u06cc\u062a \u0645\u06cc \u06a9\u0646\u062f.<\/p>\n<p><!-- Zone: every entry repeatable. --><\/p>\n<h2 id=\"cody-and-may---it-takes-two\"><span class=\"ez-toc-section\" id=\"2_%DA%A9%D9%88%D8%AF%DB%8C_%D9%88_%D9%85%DB%8C_%E2%80%93_%D8%AF%D9%88_%D9%86%D9%81%D8%B1_%D8%B7%D9%88%D9%84_%D9%85%DB%8C_%DA%A9%D8%B4%D8%AF\"><\/span> <span class=\"item-num\">2 <\/span> <span>\u06a9\u0648\u062f\u06cc \u0648 \u0645\u06cc &#8211; \u062f\u0648 \u0646\u0641\u0631 \u0637\u0648\u0644 \u0645\u06cc \u06a9\u0634\u062f<\/span> <span class=\"ez-toc-section-end\"><\/span><\/h2>\n<div class=\"body-img landscape\">\n<div class=\"responsive-img image-expandable img-article-item\" style=\"padding-bottom:50%\" data-img-url=\"https:\/\/nabfollower.com\/blog\/wp-content\/uploads\/2023\/02\/1676480011_905_8-\u0628\u0647\u062a\u0631\u06cc\u0646-\u062f\u0634\u0645\u0646\u0627\u0646-\u0639\u0627\u0634\u0642\u0627\u0646-\u0639\u0627\u0634\u0642\u0627\u0646\u0647-\u062f\u0631-\u0628\u0627\u0632\u06cc-\u0647\u0627.jpg\" data-modal-id=\"single-image-modal\" data-modal-container-id=\"single-image-modal-container\" data-img-caption=\"&quot;&quot;\">\n<figure> <picture> <!--[if IE 9]> <video style=\"display: none;\"><![endif]--><source media=\"(min-width: 1024px)\"  data-\/><source media=\"(min-width: 768px)\"  data-\/><source media=\"(min-width: 481px)\"  data-\/><source media=\"(min-width: 0px)\"  data-\/><!--[if IE 9]><\/video><![endif]--><img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"1000\" class=\"lazyload\" alt=\"\u062f\u0633\u062a\u0627\u0646 \u06a9\u0648\u062f\u06cc \u0648 \u06a9\u0648\u062f\u06a9 \u0645\u06cc \u0639\u0631\u0648\u0633\u06a9 \u0647\u0627\u06cc\u06cc \u0631\u0627 \u06a9\u0647 \u0634\u0628\u06cc\u0647 \u0648\u0627\u0644\u062f\u06cc\u0646 \u0627\u0648 \u0647\u0633\u062a\u0646\u062f \u0646\u06af\u0647 \u0645\u06cc \u062f\u0627\u0631\u062f\" src=\"https:\/\/nabfollower.com\/blog\/wp-content\/uploads\/2023\/02\/1676480011_905_8-\u0628\u0647\u062a\u0631\u06cc\u0646-\u062f\u0634\u0645\u0646\u0627\u0646-\u0639\u0627\u0634\u0642\u0627\u0646-\u0639\u0627\u0634\u0642\u0627\u0646\u0647-\u062f\u0631-\u0628\u0627\u0632\u06cc-\u0647\u0627.jpg\" title=\"\"> <\/picture> <\/figure>\n<\/p><\/div>\n<\/p><\/div>\n<p>\u062f\u0631 It Takes Two\u060c \u0632\u0648\u062c \u062e\u0648\u0634\u0628\u062e\u062a \u0648 \u062f\u0648\u0633\u062a \u062f\u0627\u0634\u062a\u0646\u06cc \u06a9\u0648\u062f\u06cc \u0648 \u0645\u06cc \u062f\u0631 \u062d\u0627\u0644 \u06af\u0630\u0631\u0627\u0646\u062f\u0646 \u06cc\u06a9 \u0645\u0634\u06a9\u0644 \u0633\u062e\u062a \u0647\u0633\u062a\u0646\u062f.  \u0647\u0631 \u062f\u0648 \u0627\u062d\u0633\u0627\u0633 \u0645\u06cc \u06a9\u0646\u0646\u062f \u0647\u06cc\u0686 \u0639\u0634\u0642\u06cc \u0628\u06cc\u0646 \u0622\u0646\u0647\u0627 \u0648\u062c\u0648\u062f \u0646\u062f\u0627\u0631\u062f \u0648 \u0647\u0631 \u0686\u0647 \u0632\u0648\u062f\u062a\u0631 \u0631\u0627\u0647 \u062e\u0648\u062f \u0631\u0627 \u0628\u0631\u0648\u0646\u062f\u060c \u0628\u0647\u062a\u0631 \u0627\u0633\u062a.  \u06af\u0641\u062a\u0646 \u062f\u062e\u062a\u0631\u0634\u0627\u0646 \u06cc\u06a9 \u0648\u0627\u06a9\u0646\u0634 \u0632\u0646\u062c\u06cc\u0631\u0647 \u0627\u06cc \u0627\u0632 \u0648\u0642\u0627\u06cc\u0639 \u0631\u0627 \u0628\u0647 \u0647\u0645\u0631\u0627\u0647 \u062f\u0627\u0631\u062f.<\/p>\n<p>\u0628\u0631\u0627\u06cc \u0634\u0631\u0648\u0639\u060c \u0634\u0645\u0627 \u0645\u062c\u0628\u0648\u0631 \u0647\u0633\u062a\u06cc\u062f \u0628\u0627 \u0634\u0631\u06cc\u06a9 \u0633\u0627\u0628\u0642 \u062e\u0648\u062f \u06a9\u0647 \u0628\u0647 \u0632\u0648\u062f\u06cc \u0628\u0647 \u0622\u0646 \u062a\u0628\u062f\u06cc\u0644 \u0645\u06cc \u0634\u0648\u06cc\u062f \u06a9\u0627\u0631 \u06a9\u0646\u06cc\u062f \u062a\u0627 \u0628\u0641\u0647\u0645\u06cc\u062f \u0686\u06af\u0648\u0646\u0647 \u067e\u06cc\u0634\u0631\u0641\u062a \u06a9\u0646\u06cc\u062f \u062a\u0627 \u0628\u0647 \u0628\u062f\u0646 \u062e\u0648\u062f \u0628\u0627\u0632\u06af\u0631\u062f\u06cc\u062f.  \u062f\u0631 \u0637\u0648\u0644 \u0631\u0627\u0647\u060c \u0645\u0648\u0627\u0646\u0639\u06cc \u0628\u0631 \u0633\u0631 \u0631\u0627\u0647 \u0634\u0645\u0627 \u0642\u0631\u0627\u0631 \u0645\u06cc \u06af\u06cc\u0631\u0646\u062f \u062a\u0627 \u0628\u0647 \u0634\u0645\u0627 \u06a9\u0645\u06a9 \u06a9\u0646\u0646\u062f \u0639\u0634\u0642 \u062e\u0648\u062f \u0631\u0627 \u0628\u0647 \u062e\u0627\u0637\u0631 \u0628\u0633\u067e\u0627\u0631\u06cc\u062f\u060c \u0628\u0647 \u062c\u0627\u06cc \u0627\u06cc\u0646\u06a9\u0647 \u062f\u0634\u0645\u0646\u0627\u0646 \u0628\u06cc\u0634\u062a\u0631\u06cc \u0634\u0648\u06cc\u062f.<\/p>\n<p><!-- Zone: every entry repeatable. --><\/p>\n<h2 id=\"darth-revan-and-bastila---star-wars-knights-of-the-old-republic\"><span class=\"ez-toc-section\" id=\"1_%D8%AF%D8%A7%D8%B1%D8%AB_%D8%B1%D9%88%D8%A7%D9%86_%D9%88_%D8%A8%D8%A7%D8%B3%D8%AA%DB%8C%D9%84%D8%A7_%E2%80%93_%D8%AC%D9%86%DA%AF_%D8%B3%D8%AA%D8%A7%D8%B1%DA%AF%D8%A7%D9%86_%D8%B4%D9%88%D8%A7%D9%84%DB%8C%D9%87_%D9%87%D8%A7%DB%8C_%D8%AC%D9%85%D9%87%D9%88%D8%B1%DB%8C_%D9%82%D8%AF%DB%8C%D9%85%DB%8C\"><\/span> <span class=\"item-num\">1 <\/span> <span>\u062f\u0627\u0631\u062b \u0631\u0648\u0627\u0646 \u0648 \u0628\u0627\u0633\u062a\u06cc\u0644\u0627 &#8211; \u062c\u0646\u06af \u0633\u062a\u0627\u0631\u06af\u0627\u0646: \u0634\u0648\u0627\u0644\u06cc\u0647 \u0647\u0627\u06cc \u062c\u0645\u0647\u0648\u0631\u06cc \u0642\u062f\u06cc\u0645\u06cc<\/span> <span class=\"ez-toc-section-end\"><\/span><\/h2>\n<div class=\"body-img landscape\">\n<div class=\"responsive-img image-expandable img-article-item\" style=\"padding-bottom:50%\" data-img-url=\"https:\/\/nabfollower.com\/blog\/wp-content\/uploads\/2023\/02\/1676480011_291_8-\u0628\u0647\u062a\u0631\u06cc\u0646-\u062f\u0634\u0645\u0646\u0627\u0646-\u0639\u0627\u0634\u0642\u0627\u0646-\u0639\u0627\u0634\u0642\u0627\u0646\u0647-\u062f\u0631-\u0628\u0627\u0632\u06cc-\u0647\u0627.jpg\" data-modal-id=\"single-image-modal\" data-modal-container-id=\"single-image-modal-container\" data-img-caption=\"&quot;&quot;\">\n<figure> <picture> <!--[if IE 9]> <video style=\"display: none;\"><![endif]--><source media=\"(min-width: 1024px)\"  data-\/><source media=\"(min-width: 768px)\"  data-\/><source media=\"(min-width: 481px)\"  data-\/><source media=\"(min-width: 0px)\"  data-\/><!--[if IE 9]><\/video><![endif]--><img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"1000\" class=\"lazyload\" alt=\"\u0628\u0627\u0633\u062a\u06cc\u0644\u0627 \u0628\u0647 \u0639\u0634\u0642 \u062e\u0648\u062f \u0628\u0647 Revan \u062e\u0627\u0631\u062c \u0627\u0632 \u0635\u0641\u062d\u0647 \u0646\u0645\u0627\u06cc\u0634 KOTOR \u0627\u0639\u062a\u0631\u0627\u0641 \u0645\u06cc \u06a9\u0646\u062f\" src=\"https:\/\/nabfollower.com\/blog\/wp-content\/uploads\/2023\/02\/1676480011_291_8-\u0628\u0647\u062a\u0631\u06cc\u0646-\u062f\u0634\u0645\u0646\u0627\u0646-\u0639\u0627\u0634\u0642\u0627\u0646-\u0639\u0627\u0634\u0642\u0627\u0646\u0647-\u062f\u0631-\u0628\u0627\u0632\u06cc-\u0647\u0627.jpg\" title=\"\"> <\/picture> <\/figure>\n<\/p><\/div>\n<\/p><\/div>\n<p>\u0639\u0627\u0634\u0642\u0627\u0646\u0647 \u0627\u06cc \u06a9\u0647 \u0628\u0631 \u0627\u0633\u0627\u0633 \u062f\u0631\u0648\u063a \u0633\u0627\u062e\u062a\u0647 \u0634\u062f\u0647 \u0627\u0633\u062a\u060c \u062d\u062a\u06cc \u0628\u0627 \u0628\u0647\u062a\u0631\u06cc\u0646 \u0639\u0644\u0627\u06cc\u0642 \u062f\u0631 \u0642\u0644\u0628\u060c \u0642\u0637\u0639\u0627\u064b \u0628\u0647 \u062a\u0631\u0627\u0698\u062f\u06cc \u062e\u062a\u0645 \u0645\u06cc \u0634\u0648\u062f.  \u062d\u062a\u06cc \u0628\u06cc\u0634\u062a\u0631 \u0627\u0632 \u0622\u0646 \u0632\u0645\u0627\u0646\u06cc \u06a9\u0647 \u0634\u0645\u0627 \u0628\u0647 \u0637\u0648\u0631 \u0627\u062a\u0641\u0627\u0642\u06cc \u067e\u0631\u0648\u0631\u062f\u06af\u0627\u0631 \u0633\u0627\u0628\u0642 \u0633\u06cc\u062b \u0628\u0627 \u062d\u0627\u0641\u0638\u0647 \u0627\u06cc \u0646\u0627\u0645\u0648\u062c\u0648\u062f \u0647\u0633\u062a\u06cc\u062f.  \u062f\u0627\u0631\u062b \u0631\u06cc\u0648\u0646 \u0648 \u0628\u0627\u0633\u062a\u06cc\u0644\u0627 \u0627\u0632 \u062f\u0648 \u0637\u0631\u0641 \u0646\u06cc\u0631\u0648 \u0645\u06cc\u200c\u0622\u06cc\u0646\u062f \u0648 \u0628\u06cc\u0634 \u0627\u0632 \u06cc\u06a9 \u0628\u0627\u0631 \u0642\u0628\u0644 \u0627\u0632 \u0631\u0648\u06cc\u062f\u0627\u062f\u0647\u0627\u06cc \u0641\u0639\u0644\u06cc \u0628\u0627\u0632\u06cc\u200c\u0647\u0627 \u0628\u0627 \u0647\u0645 \u0628\u0631\u062e\u0648\u0631\u062f \u06a9\u0631\u062f\u0647\u200c\u0627\u0646\u062f.<\/p>\n<p>\u0622\u0646\u0647\u0627 \u062d\u062a\u06cc \u062f\u0631 \u06cc\u06a9 \u0646\u0642\u0637\u0647 \u0637\u0631\u0641 \u062e\u0648\u062f \u0631\u0627 \u0639\u0648\u0636 \u06a9\u0631\u062f\u0647 \u0627\u0646\u062f.  \u0627\u06cc\u0645\u0627\u0646 \u0645\u062a\u0632\u0644\u0632\u0644 \u0627\u0648 \u0628\u0647 \u062c\u062f\u06cc \u0627\u0648 \u0631\u0627 \u0628\u0647 \u0633\u0645\u062a \u062a\u0627\u0631\u06cc\u06a9\u06cc \u0633\u0648\u0642 \u062f\u0627\u062f\u060c \u062f\u0631\u0633\u062a \u0647\u0645\u0627\u0646\u0637\u0648\u0631 \u06a9\u0647 \u0631\u06cc\u0648\u0646 \u062a\u0635\u0645\u06cc\u0645 \u06af\u0631\u0641\u062a \u062f\u0631 \u0632\u0645\u0627\u0646\u06cc \u06a9\u0647 \u0628\u0631\u0627\u06cc \u0627\u0648\u0644\u06cc\u0646 \u0628\u0627\u0631 \u062e\u0627\u0637\u0631\u0627\u062a\u0634 \u0631\u0627 \u0627\u0632 \u062f\u0633\u062a \u062f\u0627\u062f\u060c \u0631\u0627\u0647 \u062e\u0648\u062f \u0631\u0627 \u0628\u0647 \u0633\u0645\u062a \u0646\u0648\u0631 \u067e\u06cc\u062f\u0627 \u06a9\u0646\u062f.  \u0627\u0632 \u0637\u0631\u06cc\u0642 \u0647\u0645\u0647 \u0627\u06cc\u0646\u0647\u0627\u060c \u0648 \u0628\u0647 \u0634\u0631\u0637\u06cc \u06a9\u0647 \u062a\u0635\u0645\u06cc\u0645\u0627\u062a \u062f\u0631\u0633\u062a\u06cc \u0631\u0627 \u062f\u0631 \u0645\u0648\u0631\u062f \u062f\u06cc\u0627\u0644\u0648\u06af \u0628\u06af\u06cc\u0631\u06cc\u062f\u060c \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u0628\u0627\u0633\u062a\u06cc\u0644\u0627 \u0631\u0627 \u0642\u0628\u0644 \u0627\u0632 \u0627\u06cc\u0646\u06a9\u0647 \u062e\u06cc\u0644\u06cc \u062f\u06cc\u0631 \u0634\u0648\u062f \u0628\u0647 \u0633\u0645\u062a \u0633\u0628\u06a9 \u0628\u06a9\u0634\u06cc\u062f \u0648 \u0639\u0634\u0642\u062a\u0627\u0646 \u0631\u0627 \u0646\u062c\u0627\u062a \u062f\u0647\u06cc\u062f \u0647\u0645\u0627\u0646\u0637\u0648\u0631 \u06a9\u0647 \u0627\u0648 \u0634\u0645\u0627 \u0631\u0627 \u0646\u062c\u0627\u062a \u062f\u0627\u062f.<\/p>\n<p><span class=\"next-single\">\u0628\u0639\u062f\u06cc: \u0628\u0627\u0632\u06cc\u200c\u0647\u0627\u06cc \u0639\u0627\u0634\u0642\u0627\u0646\u0647 LGBTQ+<\/span><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u0639\u0627\u0634\u0642\u0627\u0646\u0647 \u062f\u0631 \u0628\u0627\u0632\u06cc \u0647\u0627 \u0686\u06cc\u0632 \u062c\u062f\u06cc\u062f\u06cc \u0646\u06cc\u0633\u062a \u0648 \u0628\u0647 \u062f\u0627\u0633\u062a\u0627\u0646 \u06a9\u0644\u0627\u0633\u06cc\u06a9 \u0645\u0627\u0631\u06cc\u0648 \u06a9\u0647 \u0634\u0627\u0647\u0632\u0627\u062f\u0647 \u062e\u0627\u0646\u0645 \u0631\u0627 \u0646\u062c\u0627\u062a \u0645\u06cc \u062f\u0647\u062f\u060c \u0645\u06cc \u0631\u0633\u062f. \u0634\u0645\u0627 \u0647\u0645\u0647 \u0646\u0648\u0639 \u0639\u0634\u0642 \u0631\u0627 \u0645\u06cc \u0628\u06cc\u0646\u06cc\u062f\u060c \u0686\u0647 \u062f\u0631 \u0639\u062c\u06cc\u0628 \u062a\u0631\u06cc\u0646 \u0634\u0631\u0627\u06cc\u0637 \u06af\u0631\u062f \u0647\u0645 \u0628\u06cc\u0627\u06cc\u06cc\u062f \u0648 \u0627\u062d\u0633\u0627\u0633 \u062e\u0648\u062f \u0631\u0627 \u062f\u0631 \u0645\u06cc\u0627\u0646 \u062e\u0637\u0631 \u067e\u06cc\u062f\u0627 \u06a9\u0646\u06cc\u062f\u060c \u0686\u0647 \u06a9\u0633\u06cc \u06a9\u0647 \u0628\u0627\u06cc\u062f \u0646\u062c\u0627\u062a\u0634 \u062f\u0647\u06cc\u062f \u0648 \u062f\u0631 \u0646\u0647\u0627\u06cc\u062a \u0628\u0647 &hellip;<\/p>\n","protected":false},"author":2,"featured_media":6281,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[352],"tags":[],"class_list":["post-6280","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-game"],"_links":{"self":[{"href":"https:\/\/nabfollower.com\/blog\/wp-json\/wp\/v2\/posts\/6280","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nabfollower.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nabfollower.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nabfollower.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/nabfollower.com\/blog\/wp-json\/wp\/v2\/comments?post=6280"}],"version-history":[{"count":0,"href":"https:\/\/nabfollower.com\/blog\/wp-json\/wp\/v2\/posts\/6280\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nabfollower.com\/blog\/wp-json\/wp\/v2\/media\/6281"}],"wp:attachment":[{"href":"https:\/\/nabfollower.com\/blog\/wp-json\/wp\/v2\/media?parent=6280"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nabfollower.com\/blog\/wp-json\/wp\/v2\/categories?post=6280"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nabfollower.com\/blog\/wp-json\/wp\/v2\/tags?post=6280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}