{"id":63735,"date":"2024-05-26T08:47:45","date_gmt":"2024-05-26T05:17:45","guid":{"rendered":"https:\/\/nabfollower.com\/blog\/enhanced-container-isolationeci-vs-rootless-docker-securing-your-docker-desktop-workflows-16cb\/"},"modified":"2024-05-26T08:47:45","modified_gmt":"2024-05-26T05:17:45","slug":"enhanced-container-isolationeci-vs-rootless-docker-securing-your-docker-desktop-workflows-16cb","status":"publish","type":"post","link":"https:\/\/nabfollower.com\/blog\/enhanced-container-isolationeci-vs-rootless-docker-securing-your-docker-desktop-workflows-16cb\/","title":{"rendered":"\u062c\u062f\u0627\u0633\u0627\u0632\u06cc \u06a9\u0627\u0646\u062a\u06cc\u0646\u0631 \u067e\u06cc\u0634\u0631\u0641\u062a\u0647 (ECI) \u062f\u0631 \u0645\u0642\u0627\u0628\u0644 Docker \u0628\u062f\u0648\u0646 \u0631\u06cc\u0634\u0647: \u0627\u06cc\u0645\u0646 \u06a9\u0631\u062f\u0646 \u06af\u0631\u062f\u0634 \u06a9\u0627\u0631 \u062f\u0633\u06a9\u062a\u0627\u067e Docker \u0634\u0645\u0627"},"content":{"rendered":"<div data-article-id=\"1865356\" id=\"article-body\">\n<p>Docker Desktop \u06cc\u06a9 \u0627\u0628\u0632\u0627\u0631 \u0645\u062d\u0628\u0648\u0628 \u0628\u0631\u0627\u06cc \u062a\u0648\u0633\u0639\u0647 \u062f\u0647\u0646\u062f\u06af\u0627\u0646\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0628\u0627 \u06a9\u0627\u0646\u062a\u06cc\u0646\u0631\u0647\u0627 \u062f\u0631 \u0648\u06cc\u0646\u062f\u0648\u0632\u060c \u0644\u06cc\u0646\u0648\u06a9\u0633 \u0648 macOS \u06a9\u0627\u0631 \u0645\u06cc \u06a9\u0646\u0646\u062f.  \u0627\u0645\u0627 \u0628\u0627 \u0631\u0627\u06cc\u062c \u0634\u062f\u0646 \u0628\u0631\u0646\u0627\u0645\u0647 \u0647\u0627\u06cc \u06a9\u0627\u0631\u0628\u0631\u062f\u06cc \u06a9\u0627\u0646\u062a\u06cc\u0646\u0631\u06cc\u060c \u0646\u06cc\u0627\u0632 \u0628\u0647 \u0627\u0645\u0646\u06cc\u062a \u0642\u0648\u06cc \u0646\u06cc\u0632 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0645\u06cc \u06cc\u0627\u0628\u062f.  \u0627\u06cc\u0646\u062c\u0627\u0633\u062a \u06a9\u0647 Enhanced Container Isolation (ECI) \u0648 Rootless Docker \u0648\u0627\u0631\u062f \u0639\u0645\u0644 \u0645\u06cc \u0634\u0648\u0646\u062f.  \u0647\u0631 \u062f\u0648 \u0645\u0632\u0627\u06cc\u0627\u06cc \u0627\u0645\u0646\u06cc\u062a\u06cc \u0631\u0627 \u0627\u0631\u0627\u0626\u0647 \u0645\u06cc \u062f\u0647\u0646\u062f\u060c \u0627\u0645\u0627 \u0628\u0647 \u0631\u0648\u0634 \u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641\u06cc \u06a9\u0627\u0631 \u0645\u06cc \u06a9\u0646\u0646\u062f.  \u0628\u06cc\u0627\u06cc\u06cc\u062f \u062a\u0641\u0627\u0648\u062a \u0647\u0627\u06cc \u0627\u0635\u0644\u06cc \u0631\u0627 \u0628\u0634\u06a9\u0646\u06cc\u0645:<\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter-rtl ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u0641\u0647\u0631\u0633\u062a \u0645\u0637\u0627\u0644\u0628<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"\u062a\u063a\u06cc\u06cc\u0631 \u0648\u0636\u0639\u06cc\u062a \u0641\u0647\u0631\u0633\u062a \u0645\u0637\u0627\u0644\u0628\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/nabfollower.com\/blog\/enhanced-container-isolationeci-vs-rootless-docker-securing-your-docker-desktop-workflows-16cb\/#Rootless_Docker_Running_Lean_%D8%B1%D9%88%DB%8C_%D9%84%DB%8C%D9%86%D9%88%DA%A9%D8%B3\" >Rootless Docker: Running Lean \u0631\u0648\u06cc \u0644\u06cc\u0646\u0648\u06a9\u0633<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/nabfollower.com\/blog\/enhanced-container-isolationeci-vs-rootless-docker-securing-your-docker-desktop-workflows-16cb\/#%D8%AC%D8%AF%D8%A7%D8%B3%D8%A7%D8%B2%DB%8C_%DA%A9%D8%A7%D9%86%D8%AA%DB%8C%D9%86%D8%B1_%D9%BE%DB%8C%D8%B4%D8%B1%D9%81%D8%AA%D9%87_%D8%AA%D9%82%D9%88%DB%8C%D8%AA_%D8%AF%D8%B3%DA%A9%D8%AA%D8%A7%D9%BE_Docker\" >\u062c\u062f\u0627\u0633\u0627\u0632\u06cc \u06a9\u0627\u0646\u062a\u06cc\u0646\u0631 \u067e\u06cc\u0634\u0631\u0641\u062a\u0647: \u062a\u0642\u0648\u06cc\u062a \u062f\u0633\u06a9\u062a\u0627\u067e Docker<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/nabfollower.com\/blog\/enhanced-container-isolationeci-vs-rootless-docker-securing-your-docker-desktop-workflows-16cb\/#Sysbox_%DB%8C%DA%A9_%D8%B2%D9%85%D8%A7%D9%86_%D8%A7%D8%AC%D8%B1%D8%A7_%D9%85%D9%86%D8%A7%D8%B3%D8%A8_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%AC%D8%AF%D8%A7%D8%B3%D8%A7%D8%B2%DB%8C_%D9%BE%DB%8C%D8%B4%D8%B1%D9%81%D8%AA%D9%87\" >Sysbox: \u06cc\u06a9 \u0632\u0645\u0627\u0646 \u0627\u062c\u0631\u0627 \u0645\u0646\u0627\u0633\u0628 \u0628\u0631\u0627\u06cc \u062c\u062f\u0627\u0633\u0627\u0632\u06cc \u067e\u06cc\u0634\u0631\u0641\u062a\u0647<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/nabfollower.com\/blog\/enhanced-container-isolationeci-vs-rootless-docker-securing-your-docker-desktop-workflows-16cb\/#%D8%A7%D9%86%D8%AA%D9%82%D8%A7%D9%84_%D8%A8%D8%AF%D9%88%D9%86_%D8%AF%D8%B1%D8%B2_%D8%A8%D8%B1%D8%A7%DB%8C_%DA%A9%D8%A7%D8%B1%D8%A8%D8%B1%D8%A7%D9%86_Sysbox_%D8%B2%DB%8C%D8%B1_%D8%B3%D8%B1%D9%BE%D9%88%D8%B4_%D8%A7%D8%AC%D8%B1%D8%A7_%D9%85%DB%8C_%D8%B4%D9%88%D8%AF\" >\u0627\u0646\u062a\u0642\u0627\u0644 \u0628\u062f\u0648\u0646 \u062f\u0631\u0632 \u0628\u0631\u0627\u06cc \u06a9\u0627\u0631\u0628\u0631\u0627\u0646: Sysbox \u0632\u06cc\u0631 \u0633\u0631\u067e\u0648\u0634 \u0627\u062c\u0631\u0627 \u0645\u06cc \u0634\u0648\u062f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/nabfollower.com\/blog\/enhanced-container-isolationeci-vs-rootless-docker-securing-your-docker-desktop-workflows-16cb\/#%D8%B1%D8%A7%D9%85_%DA%A9%D8%B1%D8%AF%D9%86_%D8%AC%D8%A7%D9%86%D9%88%D8%B1_%D9%85%D9%85%D8%AA%D8%A7%D8%B2_%D8%A7%D8%B9%D8%AF%D8%A7%D9%85_%D8%A7%DB%8C%D9%85%D9%86_%D8%AD%D8%AA%DB%8C_%D8%A8%D8%A7_%E2%80%9C%E2%80%93%D9%85%D9%85%D8%AA%D8%A7%D8%B2%E2%80%9D\" >\u0631\u0627\u0645 \u06a9\u0631\u062f\u0646 \u062c\u0627\u0646\u0648\u0631 \u0645\u0645\u062a\u0627\u0632: \u0627\u0639\u062f\u0627\u0645 \u0627\u06cc\u0645\u0646 \u062d\u062a\u06cc \u0628\u0627 &#8220;&#8211;\u0645\u0645\u062a\u0627\u0632&#8221;<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/nabfollower.com\/blog\/enhanced-container-isolationeci-vs-rootless-docker-securing-your-docker-desktop-workflows-16cb\/#%D9%86%DA%A9%D8%AA%D9%87_%D8%A7%DB%8C_%D8%AF%D8%B1_%D9%85%D9%88%D8%B1%D8%AF_%D8%B3%D8%A7%D8%B2%DA%AF%D8%A7%D8%B1%DB%8C_%D9%88_%D8%AA%D9%85%D8%A7%DB%8C%D8%B2\" >\u0646\u06a9\u062a\u0647 \u0627\u06cc \u062f\u0631 \u0645\u0648\u0631\u062f \u0633\u0627\u0632\u06af\u0627\u0631\u06cc \u0648 \u062a\u0645\u0627\u06cc\u0632<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/nabfollower.com\/blog\/enhanced-container-isolationeci-vs-rootless-docker-securing-your-docker-desktop-workflows-16cb\/#%D9%86%DA%A9%D8%A7%D8%AA_%DA%A9%D9%84%DB%8C%D8%AF%DB%8C\" >\u0646\u06a9\u0627\u062a \u06a9\u0644\u06cc\u062f\u06cc:<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/nabfollower.com\/blog\/enhanced-container-isolationeci-vs-rootless-docker-securing-your-docker-desktop-workflows-16cb\/#%D8%A7%D9%86%D8%AA%D8%AE%D8%A7%D8%A8_%D8%B1%D9%88%DB%8C%DA%A9%D8%B1%D8%AF_%D9%85%D9%86%D8%A7%D8%B3%D8%A8\" >\u0627\u0646\u062a\u062e\u0627\u0628 \u0631\u0648\u06cc\u06a9\u0631\u062f \u0645\u0646\u0627\u0633\u0628<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Rootless_Docker_Running_Lean_%D8%B1%D9%88%DB%8C_%D9%84%DB%8C%D9%86%D9%88%DA%A9%D8%B3\"><\/span>\n<p>  Rootless Docker: Running Lean \u0631\u0648\u06cc \u0644\u06cc\u0646\u0648\u06a9\u0633<br \/>\n<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0633\u0646\u0627\u0631\u06cc\u0648\u06cc\u06cc \u0631\u0627 \u062a\u0635\u0648\u0631 \u06a9\u0646\u06cc\u062f \u06a9\u0647 \u062f\u0631 \u0622\u0646 \u0645\u06cc\u200c\u062e\u0648\u0627\u0647\u06cc\u062f \u0627\u0632 Docker \u0628\u0631 \u0631\u0648\u06cc \u06cc\u06a9 \u0645\u0627\u0634\u06cc\u0646 \u0644\u06cc\u0646\u0648\u06a9\u0633 \u0628\u062f\u0648\u0646 \u0641\u0644\u0632 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f.  Rootless Docker \u0628\u0647 \u0634\u0645\u0627 \u0627\u06cc\u0646 \u0627\u0645\u06a9\u0627\u0646 \u0631\u0627 \u0645\u06cc \u062f\u0647\u062f \u06a9\u0647 \u0627\u06cc\u0646 \u06a9\u0627\u0631 \u0631\u0627 \u0627\u0646\u062c\u0627\u0645 \u062f\u0647\u06cc\u062f.  \u0627\u0633\u0627\u0633\u0627\u064b Docker Engine \u0631\u0627 \u0627\u0632 \u0627\u0645\u062a\u06cc\u0627\u0632\u0627\u062a \u0631\u06cc\u0634\u0647 \u062e\u0648\u062f \u0645\u062d\u0631\u0648\u0645 \u0645\u06cc \u06a9\u0646\u062f \u0648 \u0628\u0647 \u06a9\u0627\u0631\u0628\u0631\u0627\u0646 \u0639\u0627\u062f\u06cc \u0627\u0645\u06a9\u0627\u0646 \u0645\u06cc \u062f\u0647\u062f \u0628\u062f\u0648\u0646 \u0646\u06cc\u0627\u0632 \u0628\u0647 \u062f\u0633\u062a\u0631\u0633\u06cc \u0645\u062f\u06cc\u0631\u06cc\u062a\u06cc \u06a9\u0627\u0646\u062a\u06cc\u0646\u0631\u0647\u0627 \u0631\u0627 \u0646\u0635\u0628 \u0648 \u0645\u062f\u06cc\u0631\u06cc\u062a \u06a9\u0646\u0646\u062f.  \u0627\u06cc\u0646 \u0627\u0645\u0631 \u0628\u0627 \u0628\u0647 \u062d\u062f\u0627\u0642\u0644 \u0631\u0633\u0627\u0646\u062f\u0646 \u0633\u0637\u062d \u062d\u0645\u0644\u0647\u060c \u0627\u0645\u0646\u06cc\u062a \u0631\u0627 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0645\u06cc \u062f\u0647\u062f.<\/p>\n<p>\u0628\u0627 \u0627\u06cc\u0646 \u062d\u0627\u0644\u060c Rootless Docker \u0645\u062d\u062f\u0648\u062f\u06cc\u062a \u0647\u0627\u06cc\u06cc \u062f\u0627\u0631\u062f.  \u062f\u0631 \u062d\u0627\u0644 \u062d\u0627\u0636\u0631 \u062f\u0631 Docker Desktop \u067e\u0634\u062a\u06cc\u0628\u0627\u0646\u06cc \u0646\u0645\u06cc\u200c\u0634\u0648\u062f\u060c \u0632\u06cc\u0631\u0627 Docker Desktop \u0642\u0628\u0644\u0627\u064b \u0645\u0648\u062a\u0648\u0631 Docker \u0631\u0627 \u0645\u062c\u0627\u0632\u06cc \u0645\u06cc\u200c\u06a9\u0646\u062f \u0648 \u0644\u0627\u06cc\u0647\u200c\u0627\u06cc \u0627\u0632 \u0627\u0646\u0632\u0648\u0627 \u0631\u0627 \u0641\u0631\u0627\u0647\u0645 \u0645\u06cc\u200c\u06a9\u0646\u062f.  \u0639\u0644\u0627\u0648\u0647 \u0628\u0631 \u0627\u06cc\u0646\u060c Rootless Docker \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0628\u0627 \u0645\u062d\u062f\u0648\u062f\u06cc\u062a\u200c\u0647\u0627\u06cc\u06cc \u0628\u0631 \u0631\u0648\u06cc \u0639\u0645\u0644\u06a9\u0631\u062f\u0647\u0627\u06cc \u062e\u0627\u0635\u06cc \u06a9\u0647 \u0628\u0647 \u0627\u0645\u062a\u06cc\u0627\u0632\u0627\u062a \u0628\u0627\u0644\u0627\u062a\u0631\u06cc \u0646\u06cc\u0627\u0632 \u062f\u0627\u0631\u0646\u062f\u060c \u0645\u0648\u0627\u062c\u0647 \u0634\u0648\u062f.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D8%AC%D8%AF%D8%A7%D8%B3%D8%A7%D8%B2%DB%8C_%DA%A9%D8%A7%D9%86%D8%AA%DB%8C%D9%86%D8%B1_%D9%BE%DB%8C%D8%B4%D8%B1%D9%81%D8%AA%D9%87_%D8%AA%D9%82%D9%88%DB%8C%D8%AA_%D8%AF%D8%B3%DA%A9%D8%AA%D8%A7%D9%BE_Docker\"><\/span>\n<p>  \u062c\u062f\u0627\u0633\u0627\u0632\u06cc \u06a9\u0627\u0646\u062a\u06cc\u0646\u0631 \u067e\u06cc\u0634\u0631\u0641\u062a\u0647: \u062a\u0642\u0648\u06cc\u062a \u062f\u0633\u06a9\u062a\u0627\u067e Docker<br \/>\n<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>ECI \u0631\u0648\u06cc\u06a9\u0631\u062f \u0645\u062a\u0641\u0627\u0648\u062a\u06cc \u062f\u0627\u0631\u062f.  \u062a\u0645\u0631\u06a9\u0632 \u0622\u0646 \u0628\u0631 \u062c\u062f\u0627\u0633\u0627\u0632\u06cc \u062e\u0648\u062f \u06a9\u0627\u0646\u062a\u06cc\u0646\u0631\u0647\u0627 \u0627\u0633\u062a\u060c \u0646\u0647 Docker Engine.  \u0647\u0646\u06af\u0627\u0645\u06cc \u06a9\u0647 \u062f\u0631 Docker Desktop \u0641\u0639\u0627\u0644 \u0645\u06cc \u0634\u0648\u062f\u060c ECI \u062a\u0636\u0645\u06cc\u0646 \u0645\u06cc \u06a9\u0646\u062f \u06a9\u0647 \u06a9\u0627\u0646\u062a\u06cc\u0646\u0631\u0647\u0627 \u062f\u0631 \u0641\u0636\u0627\u06cc \u0646\u0627\u0645 \u06a9\u0627\u0631\u0628\u0631\u06cc \u0644\u06cc\u0646\u0648\u06a9\u0633 \u0627\u062c\u0631\u0627 \u0645\u06cc \u0634\u0648\u0646\u062f.  \u0627\u06cc\u0646 \u06cc\u06a9 \u0645\u0627\u0646\u0639 \u0642\u0648\u06cc\u200c\u062a\u0631 \u0628\u06cc\u0646 \u06a9\u0627\u0646\u062a\u06cc\u0646\u0631\u0647\u0627 \u0648 Docker Desktop Linux VM \u0627\u06cc\u062c\u0627\u062f \u0645\u06cc\u200c\u06a9\u0646\u062f.<\/p>\n<p>\u0627\u06cc\u0646\u0637\u0648\u0631 \u0641\u06a9\u0631 \u06a9\u0646\u06cc\u062f: ECI \u0627\u0632 \u062f\u0633\u062a\u0631\u0633\u06cc \u06cc\u06a9 \u0628\u0631\u0646\u0627\u0645\u0647 \u06a9\u0627\u0646\u062a\u06cc\u0646\u0631\u06cc \u0628\u0647 \u062e\u0627\u0631\u062c \u0627\u0632 \u0641\u0636\u0627\u06cc \u062a\u0639\u06cc\u06cc\u0646 \u0634\u062f\u0647 \u0648 \u0628\u0647 \u0637\u0648\u0631 \u0628\u0627\u0644\u0642\u0648\u0647 \u062f\u0633\u062a\u06a9\u0627\u0631\u06cc \u062a\u0646\u0638\u06cc\u0645\u0627\u062a \u0627\u0645\u0646\u06cc\u062a\u06cc \u0645\u0627\u0634\u06cc\u0646 \u0645\u062c\u0627\u0632\u06cc \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0645\u06cc \u06a9\u0646\u062f.  \u0627\u06cc\u0646 \u0628\u0647 \u0648\u06cc\u0698\u0647 \u0628\u0631\u0627\u06cc \u062a\u0648\u0633\u0639\u0647 \u062f\u0647\u0646\u062f\u06af\u0627\u0646\u06cc \u06a9\u0647 \u0628\u0631\u0627\u06cc \u06af\u0631\u062f\u0634 \u06a9\u0627\u0631 \u062a\u0648\u0633\u0639\u0647 \u0628\u0647 Docker Desktop \u0645\u062a\u06a9\u06cc \u0647\u0633\u062a\u0646\u062f \u0648 \u062e\u0648\u0627\u0647\u0627\u0646 \u06cc\u06a9 \u0644\u0627\u06cc\u0647 \u062d\u0641\u0627\u0638\u062a\u06cc \u0627\u0636\u0627\u0641\u06cc \u0647\u0633\u062a\u0646\u062f \u0628\u0633\u06cc\u0627\u0631 \u0627\u0631\u0632\u0634\u0645\u0646\u062f \u0627\u0633\u062a.<\/p>\n<p>\u0627\u06a9\u0646\u0648\u0646\u060c \u0628\u06cc\u0627\u06cc\u06cc\u062f \u0639\u0645\u06cc\u0642\u200c\u062a\u0631 \u0628\u0647 \u0639\u0645\u0644\u06a9\u0631\u062f \u062f\u0631\u0648\u0646\u06cc ECI \u0628\u067e\u0631\u062f\u0627\u0632\u06cc\u0645 \u0648 \u0641\u0646\u0627\u0648\u0631\u06cc \u0631\u0627 \u06a9\u0634\u0641 \u06a9\u0646\u06cc\u0645 \u06a9\u0647 \u0627\u0646\u0631\u0698\u06cc \u0622\u0646 \u0631\u0627 \u062a\u0627\u0645\u06cc\u0646 \u0645\u06cc\u200c\u06a9\u0646\u062f: Sysbox.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Sysbox_%DB%8C%DA%A9_%D8%B2%D9%85%D8%A7%D9%86_%D8%A7%D8%AC%D8%B1%D8%A7_%D9%85%D9%86%D8%A7%D8%B3%D8%A8_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%AC%D8%AF%D8%A7%D8%B3%D8%A7%D8%B2%DB%8C_%D9%BE%DB%8C%D8%B4%D8%B1%D9%81%D8%AA%D9%87\"><\/span>\n<p>  Sysbox: \u06cc\u06a9 \u0632\u0645\u0627\u0646 \u0627\u062c\u0631\u0627 \u0645\u0646\u0627\u0633\u0628 \u0628\u0631\u0627\u06cc \u062c\u062f\u0627\u0633\u0627\u0632\u06cc \u067e\u06cc\u0634\u0631\u0641\u062a\u0647<br \/>\n<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u062f\u0631 \u062d\u0627\u0644\u06cc \u06a9\u0647 Docker \u0628\u0647 \u0637\u0648\u0631 \u0633\u0646\u062a\u06cc \u0628\u0647 \u0632\u0645\u0627\u0646 \u0627\u062c\u0631\u0627\u06cc OCI \u0628\u0631\u0627\u06cc \u0645\u062f\u06cc\u0631\u06cc\u062a \u06a9\u0627\u0646\u062a\u06cc\u0646\u0631\u0647\u0627 \u0645\u062a\u06a9\u06cc \u0627\u0633\u062a\u060c ECI \u0627\u0632 \u0646\u0633\u062e\u0647 \u0633\u0641\u0627\u0631\u0634\u06cc Sysbox \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc \u06a9\u0646\u062f.  Sysbox \u062e\u0648\u062f \u0645\u0634\u062a\u0642\u06cc \u0627\u0632 runc \u0627\u0633\u062a\u060c \u0627\u0645\u0627 \u0628\u0627 \u062a\u063a\u06cc\u06cc\u0631\u0627\u062a \u06a9\u0644\u06cc\u062f\u06cc \u0637\u0631\u0627\u062d\u06cc \u0634\u062f\u0647 \u0628\u0631\u0627\u06cc \u0627\u0631\u062a\u0642\u0627\u06cc \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f\u0647\u0627\u06cc \u062c\u062f\u0627\u0633\u0627\u0632\u06cc \u06a9\u0627\u0646\u062a\u06cc\u0646\u0631 \u0648 \u0628\u0647\u06cc\u0646\u0647 \u0633\u0627\u0632\u06cc \u0627\u062c\u0631\u0627\u06cc \u062d\u062c\u0645 \u06a9\u0627\u0631.  \u0627\u06cc\u0646 \u0646\u0633\u062e\u0647 \u0633\u0641\u0627\u0631\u0634\u06cc \u06a9\u0647 \u0627\u0632 \u0646\u0633\u062e\u0647 4.13 \u062f\u0631 Docker Desktop \u06af\u0646\u062c\u0627\u0646\u062f\u0647 \u0634\u062f\u0647 \u0627\u0633\u062a\u060c \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u0633\u062a\u0648\u0646 \u0641\u0642\u0631\u0627\u062a \u067e\u06cc\u0634\u0631\u0641\u062a \u0647\u0627\u06cc \u0627\u0645\u0646\u06cc\u062a\u06cc ECI \u0639\u0645\u0644 \u0645\u06cc \u06a9\u0646\u062f.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D8%A7%D9%86%D8%AA%D9%82%D8%A7%D9%84_%D8%A8%D8%AF%D9%88%D9%86_%D8%AF%D8%B1%D8%B2_%D8%A8%D8%B1%D8%A7%DB%8C_%DA%A9%D8%A7%D8%B1%D8%A8%D8%B1%D8%A7%D9%86_Sysbox_%D8%B2%DB%8C%D8%B1_%D8%B3%D8%B1%D9%BE%D9%88%D8%B4_%D8%A7%D8%AC%D8%B1%D8%A7_%D9%85%DB%8C_%D8%B4%D9%88%D8%AF\"><\/span>\n<p>  \u0627\u0646\u062a\u0642\u0627\u0644 \u0628\u062f\u0648\u0646 \u062f\u0631\u0632 \u0628\u0631\u0627\u06cc \u06a9\u0627\u0631\u0628\u0631\u0627\u0646: Sysbox \u0632\u06cc\u0631 \u0633\u0631\u067e\u0648\u0634 \u0627\u062c\u0631\u0627 \u0645\u06cc \u0634\u0648\u062f<br \/>\n<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0632\u06cc\u0628\u0627\u06cc\u06cc ECI \u062f\u0631 \u06a9\u0627\u0631\u0628\u0631\u067e\u0633\u0646\u062f \u0628\u0648\u062f\u0646 \u0622\u0646 \u0646\u0647\u0641\u062a\u0647 \u0627\u0633\u062a.  \u0648\u0642\u062a\u06cc \u0641\u0639\u0627\u0644 \u0628\u0627\u0634\u062f\u060c \u06a9\u0627\u0646\u062a\u06cc\u0646\u0631\u0647\u0627\u06cc\u06cc \u06a9\u0647 \u0627\u0632 \u0637\u0631\u06cc\u0642 \u062f\u0633\u062a\u0648\u0631\u0627\u062a \u0622\u0634\u0646\u0627 \u0645\u0627\u0646\u0646\u062f docker run \u06cc\u0627 docker create \u0631\u0627\u0647 \u0627\u0646\u062f\u0627\u0632\u06cc \u0645\u06cc \u0634\u0648\u0646\u062f\u060c \u0628\u0647 \u0637\u0648\u0631 \u062e\u0648\u062f\u06a9\u0627\u0631 \u0627\u0632 Sysbox \u0628\u0647 \u062c\u0627\u06cc runc \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc \u06a9\u0646\u0646\u062f.  \u0627\u06cc\u0646 \u062f\u0631 \u067e\u0634\u062a \u0635\u062d\u0646\u0647 \u0627\u062a\u0641\u0627\u0642 \u0645\u06cc \u0627\u0641\u062a\u062f \u0648 \u0646\u06cc\u0627\u0632\u06cc \u0628\u0647 \u067e\u06cc\u06a9\u0631\u0628\u0646\u062f\u06cc \u0627\u0636\u0627\u0641\u06cc \u0627\u0632 \u062c\u0627\u0646\u0628 \u06a9\u0627\u0631\u0628\u0631 \u0646\u062f\u0627\u0631\u062f.  \u062a\u0648\u0633\u0639\u0647\u200c\u062f\u0647\u0646\u062f\u06af\u0627\u0646 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0637\u0628\u0642 \u0645\u0639\u0645\u0648\u0644 \u0628\u0647 \u06a9\u0627\u0631 \u0628\u0627 \u06a9\u0627\u0646\u062a\u06cc\u0646\u0631\u0647\u0627 \u0627\u062f\u0627\u0645\u0647 \u062f\u0647\u0646\u062f\u060c \u062f\u0631 \u062d\u0627\u0644\u06cc \u06a9\u0647 ECI \u0628\u06cc\u200c\u0635\u062f\u0627 \u0648\u0636\u0639\u06cc\u062a \u0627\u0645\u0646\u06cc\u062a\u06cc \u0631\u0627 \u062a\u0642\u0648\u06cc\u062a \u0645\u06cc\u200c\u06a9\u0646\u062f.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D8%B1%D8%A7%D9%85_%DA%A9%D8%B1%D8%AF%D9%86_%D8%AC%D8%A7%D9%86%D9%88%D8%B1_%D9%85%D9%85%D8%AA%D8%A7%D8%B2_%D8%A7%D8%B9%D8%AF%D8%A7%D9%85_%D8%A7%DB%8C%D9%85%D9%86_%D8%AD%D8%AA%DB%8C_%D8%A8%D8%A7_%E2%80%9C%E2%80%93%D9%85%D9%85%D8%AA%D8%A7%D8%B2%E2%80%9D\"><\/span>\n<p>  \u0631\u0627\u0645 \u06a9\u0631\u062f\u0646 \u062c\u0627\u0646\u0648\u0631 \u0645\u0645\u062a\u0627\u0632: \u0627\u0639\u062f\u0627\u0645 \u0627\u06cc\u0645\u0646 \u062d\u062a\u06cc \u0628\u0627 &#8220;&#8211;\u0645\u0645\u062a\u0627\u0632&#8221;<br \/>\n<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0638\u0631\u0648\u0641 \u0628\u0627 \u0645\u062e\u0627\u0637\u0631\u0627\u062a \u0642\u0628\u0644\u06cc \u0631\u0627\u0647 \u0627\u0646\u062f\u0627\u0632\u06cc \u0634\u062f <code>--privileged<\/code> \u0627\u06a9\u0646\u0648\u0646 \u0645\u06cc \u062a\u0648\u0627\u0646 \u067e\u0631\u0686\u0645 \u0631\u0627 \u0628\u0647 \u0637\u0648\u0631 \u0627\u06cc\u0645\u0646 \u0628\u0627 ECI \u0645\u0647\u0627\u0631 \u06a9\u0631\u062f.  \u0627\u06cc\u0646 \u067e\u0631\u0686\u0645 \u0645\u0639\u0645\u0648\u0644\u0627\u064b \u0627\u0645\u062a\u06cc\u0627\u0632\u0627\u062a \u0628\u0627\u0644\u0627\u06cc\u06cc \u0631\u0627 \u0627\u0639\u0637\u0627 \u0645\u06cc \u06a9\u0646\u062f \u06a9\u0647 \u06cc\u06a9 \u062a\u0647\u062f\u06cc\u062f \u0627\u0645\u0646\u06cc\u062a\u06cc \u0628\u0627\u0644\u0642\u0648\u0647 \u0627\u0633\u062a.  \u0628\u0627 \u0627\u06cc\u0646 \u062d\u0627\u0644\u060c ECI \u0628\u0627 \u0627\u0637\u0645\u06cc\u0646\u0627\u0646 \u0627\u0632 \u0627\u06cc\u0646\u06a9\u0647 \u0686\u0646\u06cc\u0646 \u06a9\u0627\u0646\u062a\u06cc\u0646\u0631\u0647\u0627\u06cc\u06cc \u0646\u0645\u06cc \u062a\u0648\u0627\u0646\u0646\u062f \u0645\u0627\u0634\u06cc\u0646 \u0645\u062c\u0627\u0632\u06cc Docker Desktop (VM) \u0631\u0627 \u0646\u0642\u0636 \u06a9\u0646\u0646\u062f \u06cc\u0627 \u0633\u0627\u06cc\u0631 \u06a9\u0627\u0646\u062a\u06cc\u0646\u0631\u0647\u0627 \u0631\u0627 \u062f\u0631 \u0645\u0639\u0631\u0636 \u062e\u0637\u0631 \u0642\u0631\u0627\u0631 \u062f\u0647\u0646\u062f\u060c \u0628\u0647 \u0637\u0648\u0631 \u0645\u0648\u062b\u0631 \u0627\u06cc\u0646 \u062e\u0637\u0631 \u0631\u0627 \u06a9\u0627\u0647\u0634 \u0645\u06cc \u062f\u0647\u062f.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D9%86%DA%A9%D8%AA%D9%87_%D8%A7%DB%8C_%D8%AF%D8%B1_%D9%85%D9%88%D8%B1%D8%AF_%D8%B3%D8%A7%D8%B2%DA%AF%D8%A7%D8%B1%DB%8C_%D9%88_%D8%AA%D9%85%D8%A7%DB%8C%D8%B2\"><\/span>\n<p>  \u0646\u06a9\u062a\u0647 \u0627\u06cc \u062f\u0631 \u0645\u0648\u0631\u062f \u0633\u0627\u0632\u06af\u0627\u0631\u06cc \u0648 \u062a\u0645\u0627\u06cc\u0632<br \/>\n<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0645\u0647\u0645 \u0627\u0633\u062a \u06a9\u0647 \u0628\u0647 \u06cc\u0627\u062f \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f \u06a9\u0647 ECI \u0627\u0632 \u062d\u0627\u0644\u062a userns-remap \u0645\u0648\u062a\u0648\u0631 Docker \u0648 Docker \u0628\u062f\u0648\u0646 \u0631\u06cc\u0634\u0647 \u0645\u062a\u0645\u0627\u06cc\u0632 \u0627\u0633\u062a.  \u062f\u0631 \u062d\u0627\u0644\u06cc \u06a9\u0647 \u0622\u0646\u0647\u0627 \u062f\u0631 \u0647\u062f\u0641 \u0628\u0647\u0628\u0648\u062f \u0627\u0645\u0646\u06cc\u062a \u0645\u0634\u062a\u0631\u06a9 \u0647\u0633\u062a\u0646\u062f\u060c \u0627\u0645\u0627 \u0639\u0645\u0644\u06a9\u0631\u062f \u0645\u062a\u0641\u0627\u0648\u062a\u06cc \u062f\u0627\u0631\u0646\u062f.  \u062f\u0631 \u067e\u0633\u062a \u0622\u06cc\u0646\u062f\u0647 \u0627\u06cc\u0646 \u062a\u0645\u0627\u06cc\u0632\u0627\u062a \u0631\u0627 \u0628\u0627 \u062c\u0632\u0626\u06cc\u0627\u062a \u0628\u06cc\u0634\u062a\u0631\u06cc \u0628\u0631\u0631\u0633\u06cc \u062e\u0648\u0627\u0647\u06cc\u0645 \u06a9\u0631\u062f.<\/p>\n<p>Sysbox \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u0646\u06cc\u0631\u0648\u06cc \u0646\u0627\u0645\u0631\u0626\u06cc \u067e\u0634\u062a \u062c\u062f\u0627\u0633\u0627\u0632\u06cc \u06a9\u0627\u0646\u062a\u06cc\u0646\u0631 \u067e\u06cc\u0634\u0631\u0641\u062a\u0647 ECI \u0639\u0645\u0644 \u0645\u06cc \u06a9\u0646\u062f.  \u0627\u06cc\u0646 \u06cc\u06a9\u067e\u0627\u0631\u0686\u0647 \u0628\u0627 Docker Desktop \u0627\u062f\u063a\u0627\u0645 \u0645\u06cc \u0634\u0648\u062f \u0648 \u0627\u0645\u0646\u06cc\u062a \u0642\u0648\u06cc \u0631\u0627 \u0628\u062f\u0648\u0646 \u0628\u0647 \u062e\u0637\u0631 \u0627\u0646\u062f\u0627\u062e\u062a\u0646 \u062a\u062c\u0631\u0628\u0647 \u06a9\u0627\u0631\u0628\u0631 \u0627\u0631\u0627\u0626\u0647 \u0645\u06cc \u062f\u0647\u062f.  \u0645\u0646\u062a\u0638\u0631 \u0628\u0631\u0631\u0633\u06cc \u0628\u06cc\u0634\u062a\u0631 \u0631\u0648\u06cc\u06a9\u0631\u062f \u0645\u0646\u062d\u0635\u0631 \u0628\u0647 \u0641\u0631\u062f ECI \u062f\u0631 \u0645\u0642\u0627\u06cc\u0633\u0647 \u0628\u0627 \u0633\u0627\u06cc\u0631 \u0645\u06a9\u0627\u0646\u06cc\u0633\u0645 \u0647\u0627\u06cc \u0627\u0645\u0646\u06cc\u062a\u06cc \u0628\u0627\u0634\u06cc\u062f.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D9%86%DA%A9%D8%A7%D8%AA_%DA%A9%D9%84%DB%8C%D8%AF%DB%8C\"><\/span>\n<p>  \u0646\u06a9\u0627\u062a \u06a9\u0644\u06cc\u062f\u06cc:<br \/>\n<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<ul>\n<li>Rootless Docker: \u0627\u06cc\u062f\u0647\u200c\u0622\u0644 \u0628\u0631\u0627\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 Docker \u0628\u0648\u0645\u06cc \u062f\u0631 \u0644\u06cc\u0646\u0648\u06a9\u0633\u060c \u0628\u0627 \u0627\u062c\u0631\u0627\u06cc \u06a9\u0627\u0646\u062a\u06cc\u0646\u0631\u0647\u0627\u06cc \u0628\u062f\u0648\u0646 \u062d\u0642\u0648\u0642 \u0631\u06cc\u0634\u0647\u060c \u0627\u0645\u0646\u06cc\u062a \u0628\u0647\u062a\u0631\u06cc \u0631\u0627 \u0627\u0631\u0627\u0626\u0647 \u0645\u06cc\u200c\u062f\u0647\u062f.<\/li>\n<li>\u062c\u062f\u0627\u0633\u0627\u0632\u06cc \u06a9\u0627\u0646\u062a\u06cc\u0646\u0631 \u067e\u06cc\u0634\u0631\u0641\u062a\u0647: \u0628\u0647 \u0637\u0648\u0631 \u062e\u0627\u0635 \u0628\u0631\u0627\u06cc Docker Desktop \u0637\u0631\u0627\u062d\u06cc \u0634\u062f\u0647 \u0627\u0633\u062a \u0648 \u062c\u062f\u0627\u0633\u0627\u0632\u06cc \u0628\u06cc\u0646 \u06a9\u0627\u0646\u062a\u06cc\u0646\u0631\u0647\u0627 \u0648 Docker Desktop Linux VM \u0631\u0627 \u062a\u0642\u0648\u06cc\u062a \u0645\u06cc \u06a9\u0646\u062f.<\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"%D8%A7%D9%86%D8%AA%D8%AE%D8%A7%D8%A8_%D8%B1%D9%88%DB%8C%DA%A9%D8%B1%D8%AF_%D9%85%D9%86%D8%A7%D8%B3%D8%A8\"><\/span>\n<p>  \u0627\u0646\u062a\u062e\u0627\u0628 \u0631\u0648\u06cc\u06a9\u0631\u062f \u0645\u0646\u0627\u0633\u0628<br \/>\n<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0628\u0647\u062a\u0631\u06cc\u0646 \u06af\u0632\u06cc\u0646\u0647 \u0628\u0647 \u0645\u062d\u06cc\u0637 \u0634\u0645\u0627 \u0628\u0633\u062a\u06af\u06cc \u062f\u0627\u0631\u062f.  \u0627\u06af\u0631 \u0627\u0632 Docker \u0628\u0647 \u0635\u0648\u0631\u062a \u0628\u0648\u0645\u06cc \u062f\u0631 \u0644\u06cc\u0646\u0648\u06a9\u0633 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u06a9\u0646\u06cc\u062f \u0648 \u0645\u06cc\u200c\u062e\u0648\u0627\u0647\u06cc\u062f \u06cc\u06a9 \u0631\u0627\u0647\u200c\u062d\u0644 \u0633\u0628\u06a9 \u0648\u0632\u0646 \u0628\u0627 \u0627\u0645\u0646\u06cc\u062a \u0628\u0647\u0628\u0648\u062f \u06cc\u0627\u0641\u062a\u0647 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f\u060c Rootless Docker \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0631\u0627\u0647 \u062d\u0644\u06cc \u0628\u0627\u0634\u062f.  \u0627\u0645\u0627 \u0628\u0631\u0627\u06cc \u062a\u0648\u0633\u0639\u0647\u200c\u062f\u0647\u0646\u062f\u06af\u0627\u0646\u06cc \u06a9\u0647 \u0627\u0632 Docker Desktop \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f \u0648 \u0628\u0647 \u062f\u0646\u0628\u0627\u0644 \u062c\u062f\u0627\u0633\u0627\u0632\u06cc \u06a9\u0627\u0646\u062a\u06cc\u0646\u0631 \u067e\u06cc\u0634\u0631\u0641\u062a\u0647 \u062f\u0631 \u0645\u062d\u06cc\u0637 \u0645\u062c\u0627\u0632\u06cc \u0647\u0633\u062a\u0646\u062f\u060c ECI \u0628\u0631\u0646\u062f\u0647 \u0648\u0627\u0636\u062d \u0627\u0633\u062a.<\/p>\n<p>\u0628\u0647 \u06cc\u0627\u062f \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f\u060c \u0627\u0645\u0646\u06cc\u062a \u06cc\u06a9 \u0641\u0631\u0622\u06cc\u0646\u062f \u0645\u062f\u0627\u0648\u0645 \u0627\u0633\u062a.  \u0647\u0631 \u062f\u0648 ECI \u0648 Rootless Docker \u0648\u06cc\u0698\u06af\u06cc\u200c\u0647\u0627\u06cc \u0627\u0645\u0646\u06cc\u062a\u06cc \u0627\u0631\u0632\u0634\u0645\u0646\u062f\u06cc \u0631\u0627 \u0627\u0631\u0627\u0626\u0647 \u0645\u06cc\u200c\u062f\u0647\u0646\u062f\u060c \u0627\u0645\u0627 \u0628\u0627\u06cc\u062f \u062f\u0631 \u06a9\u0646\u0627\u0631 \u0633\u0627\u06cc\u0631 \u0628\u0647\u062a\u0631\u06cc\u0646 \u0631\u0648\u0634\u200c\u0647\u0627\u06cc \u0627\u0645\u0646\u06cc\u062a\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0634\u0648\u0646\u062f \u062a\u0627 \u0627\u0637\u0645\u06cc\u0646\u0627\u0646 \u062d\u0627\u0635\u0644 \u0634\u0648\u062f \u06a9\u0647 \u06af\u0631\u062f\u0634\u200c\u0647\u0627\u06cc \u06a9\u0627\u0631\u06cc \u06a9\u0627\u0646\u062a\u06cc\u0646\u0631\u06cc \u0634\u0645\u0627 \u0633\u0627\u0644\u0645 \u0648 \u0633\u0627\u0644\u0645 \u0628\u0627\u0642\u06cc \u0645\u06cc\u200c\u0645\u0627\u0646\u0646\u062f.<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Docker Desktop \u06cc\u06a9 \u0627\u0628\u0632\u0627\u0631 \u0645\u062d\u0628\u0648\u0628 \u0628\u0631\u0627\u06cc \u062a\u0648\u0633\u0639\u0647 \u062f\u0647\u0646\u062f\u06af\u0627\u0646\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0628\u0627 \u06a9\u0627\u0646\u062a\u06cc\u0646\u0631\u0647\u0627 \u062f\u0631 \u0648\u06cc\u0646\u062f\u0648\u0632\u060c \u0644\u06cc\u0646\u0648\u06a9\u0633 \u0648 macOS \u06a9\u0627\u0631 \u0645\u06cc \u06a9\u0646\u0646\u062f. \u0627\u0645\u0627 \u0628\u0627 \u0631\u0627\u06cc\u062c \u0634\u062f\u0646 \u0628\u0631\u0646\u0627\u0645\u0647 \u0647\u0627\u06cc \u06a9\u0627\u0631\u0628\u0631\u062f\u06cc \u06a9\u0627\u0646\u062a\u06cc\u0646\u0631\u06cc\u060c \u0646\u06cc\u0627\u0632 \u0628\u0647 \u0627\u0645\u0646\u06cc\u062a \u0642\u0648\u06cc \u0646\u06cc\u0632 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0645\u06cc \u06cc\u0627\u0628\u062f. \u0627\u06cc\u0646\u062c\u0627\u0633\u062a \u06a9\u0647 Enhanced Container Isolation (ECI) \u0648 Rootless Docker \u0648\u0627\u0631\u062f \u0639\u0645\u0644 \u0645\u06cc \u0634\u0648\u0646\u062f. \u0647\u0631 \u062f\u0648 \u0645\u0632\u0627\u06cc\u0627\u06cc \u0627\u0645\u0646\u06cc\u062a\u06cc \u0631\u0627 \u0627\u0631\u0627\u0626\u0647 &hellip;<\/p>\n","protected":false},"author":2,"featured_media":63736,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[339],"tags":[],"class_list":["post-63735","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dev"],"_links":{"self":[{"href":"https:\/\/nabfollower.com\/blog\/wp-json\/wp\/v2\/posts\/63735","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nabfollower.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nabfollower.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nabfollower.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/nabfollower.com\/blog\/wp-json\/wp\/v2\/comments?post=63735"}],"version-history":[{"count":0,"href":"https:\/\/nabfollower.com\/blog\/wp-json\/wp\/v2\/posts\/63735\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nabfollower.com\/blog\/wp-json\/wp\/v2\/media\/63736"}],"wp:attachment":[{"href":"https:\/\/nabfollower.com\/blog\/wp-json\/wp\/v2\/media?parent=63735"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nabfollower.com\/blog\/wp-json\/wp\/v2\/categories?post=63735"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nabfollower.com\/blog\/wp-json\/wp\/v2\/tags?post=63735"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}